{"id":185,"count":6,"description":"","link":"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/","name":"Arte Contemporanea","slug":"arte-contemporanea","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arte Contemporanea Archivi - Eventi - LazioInnova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arte Contemporanea Archivi - Eventi - LazioInnova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventi - LazioInnova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/tag\\\/arte-contemporanea\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/tag\\\/arte-contemporanea\\\/\",\"name\":\"Arte Contemporanea Archivi - Eventi - LazioInnova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/tag\\\/arte-contemporanea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/tag\\\/arte-contemporanea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte Contemporanea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/\",\"name\":\"Eventi - LazioInnova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arte Contemporanea Archivi - Eventi - LazioInnova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/","og_locale":"it_IT","og_type":"article","og_title":"Arte Contemporanea Archivi - Eventi - LazioInnova","og_url":"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/","og_site_name":"Eventi - LazioInnova","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/","url":"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/","name":"Arte Contemporanea Archivi - Eventi - LazioInnova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/#website"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/eventi\/tag\/arte-contemporanea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home"},{"@type":"ListItem","position":2,"name":"Arte Contemporanea"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/eventi\/#website","url":"https:\/\/www.lazioinnova.it\/eventi\/","name":"Eventi - LazioInnova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/eventi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tags\/185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/posts?tags=185"},{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events?tags=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}