{"id":22145,"date":"2022-09-27T10:53:47","date_gmt":"2022-09-27T08:53:47","guid":{"rendered":"https:\/\/www.lazioinnova.it\/eventi\/?post_type=tribe_events&#038;p=22145"},"modified":"2022-11-24T17:02:22","modified_gmt":"2022-11-24T16:02:22","slug":"romasposa-salone-internazionale-della-sposa","status":"publish","type":"tribe_events","link":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/","title":{"rendered":"ROMASPOSA \u2013 Salone Internazionale della Sposa"},"content":{"rendered":"<p>La <strong>Regione Lazio<\/strong>, per il tramite del soggetto attuatore <strong>Lazio Innova<\/strong>, e la<strong> Camera di Commercio di Roma<\/strong> promuovono la partecipazione a <strong>ROMASPOSA \u2013 Salone Internazionale della Sposa<\/strong><strong>,<\/strong> che si svolger\u00e0 dal <strong>6 al 9 ottobre 2022 <\/strong>presso il Palazzo dei Congressi di Roma.<\/p>\n<p>Nell\u2019ambito della manifestazione gli Enti promotori hanno intenzione di organizzare uni spazio espositivo per ospitare <strong>30 aziende<\/strong> rappresentative delle migliori produzioni del Lazio.\u00a0 La partecipazione di <strong>15 di queste \u00e8 sostenuta con il contributo del POR FESR Lazio 2014-2020.<\/strong><\/p>\n<p><strong>Maggiori informazioni <a href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/09\/22\/manifestazione-di-interesse-per-la-partecipazione-a-romasposa-salone-internazionale-della-sposa-roma-palazzo-dei-congressi-6-9-ottobre-2022\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/strong><\/p>\n<p><strong>Iscrizioni online <a href=\"https:\/\/www.lazioinnova.it\/laziointernational\/partecipazione-a-roma-sposa-autunno-2022\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/strong>\u00a0entro e non oltre le<strong> ore 12 di gioved\u00ec 29 settembre 2022<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Lazio, per il tramite del soggetto attuatore Lazio Innova, e la Camera di Commercio di Roma promuovono la partecipazione a ROMASPOSA \u2013 Salone Internazionale della Sposa, che si [&hellip;]<\/p>\n","protected":false},"author":6849,"featured_media":22146,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[175,173,30,174,78,100,172,125],"tribe_events_cat":[132,206],"class_list":["post-22145","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-accessori","tag-banqueting","tag-camera-di-commercio-di-roma","tag-floricoltura","tag-lazio-innova","tag-regione-lazio","tag-sartoria","tag-wedding","tribe_events_cat-internazionalizzazione","tribe_events_cat-pr-fesr-lazio-2021-2027","cat_internazionalizzazione","cat_pr-fesr-lazio-2021-2027"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ROMASPOSA \u2013 Salone Internazionale della Sposa - Eventi - LazioInnova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ROMASPOSA \u2013 Salone Internazionale della Sposa - Eventi - LazioInnova\" \/>\n<meta property=\"og:description\" content=\"La Regione Lazio, per il tramite del soggetto attuatore Lazio Innova, e la Camera di Commercio di Roma promuovono la partecipazione a ROMASPOSA \u2013 Salone Internazionale della Sposa, che si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventi - LazioInnova\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-24T16:02:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2022\/09\/roma-768x462-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/\",\"name\":\"ROMASPOSA \u2013 Salone Internazionale della Sposa - Eventi - LazioInnova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/app\\\/uploads\\\/2022\\\/09\\\/roma-768x462-1.png\",\"datePublished\":\"2022-09-27T08:53:47+00:00\",\"dateModified\":\"2022-11-24T16:02:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/app\\\/uploads\\\/2022\\\/09\\\/roma-768x462-1.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/app\\\/uploads\\\/2022\\\/09\\\/roma-768x462-1.png\",\"width\":768,\"height\":462},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/romasposa-salone-internazionale-della-sposa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ROMASPOSA \u2013 Salone Internazionale della Sposa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/\",\"name\":\"Eventi - LazioInnova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ROMASPOSA \u2013 Salone Internazionale della Sposa - Eventi - LazioInnova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/","og_locale":"it_IT","og_type":"article","og_title":"ROMASPOSA \u2013 Salone Internazionale della Sposa - Eventi - LazioInnova","og_description":"La Regione Lazio, per il tramite del soggetto attuatore Lazio Innova, e la Camera di Commercio di Roma promuovono la partecipazione a ROMASPOSA \u2013 Salone Internazionale della Sposa, che si [&hellip;]","og_url":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/","og_site_name":"Eventi - LazioInnova","article_modified_time":"2022-11-24T16:02:22+00:00","og_image":[{"width":768,"height":462,"url":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2022\/09\/roma-768x462-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/","url":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/","name":"ROMASPOSA \u2013 Salone Internazionale della Sposa - Eventi - LazioInnova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2022\/09\/roma-768x462-1.png","datePublished":"2022-09-27T08:53:47+00:00","dateModified":"2022-11-24T16:02:22+00:00","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2022\/09\/roma-768x462-1.png","contentUrl":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2022\/09\/roma-768x462-1.png","width":768,"height":462},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/romasposa-salone-internazionale-della-sposa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.lazioinnova.it\/eventi\/"},{"@type":"ListItem","position":3,"name":"ROMASPOSA \u2013 Salone Internazionale della Sposa"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/eventi\/#website","url":"https:\/\/www.lazioinnova.it\/eventi\/","name":"Eventi - LazioInnova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/eventi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events\/22145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/users\/6849"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/comments?post=22145"}],"version-history":[{"count":3,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events\/22145\/revisions"}],"predecessor-version":[{"id":22149,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events\/22145\/revisions\/22149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/media\/22146"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/media?parent=22145"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tags?post=22145"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events_cat?post=22145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}