{"id":27036,"date":"2024-01-04T10:47:55","date_gmt":"2024-01-04T09:47:55","guid":{"rendered":"https:\/\/www.lazioinnova.it\/eventi\/?post_type=tribe_events&#038;p=27036"},"modified":"2025-07-29T14:58:32","modified_gmt":"2025-07-29T12:58:32","slug":"webinar-strumenti-fare-lazio-spazio-attivo-bracciano","status":"publish","type":"tribe_events","link":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/","title":{"rendered":"Webinar strumenti Fare Lazio &#8211; Spazio Attivo Bracciano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36192 aligncenter\" src=\"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2025\/07\/COESIONE-Versione-positiva-fondo-trasparente-300x44.png\" alt=\"\" width=\"423\" height=\"62\" srcset=\"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2025\/07\/COESIONE-Versione-positiva-fondo-trasparente-300x44.png 300w, https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2025\/07\/COESIONE-Versione-positiva-fondo-trasparente-1024x150.png 1024w, https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2025\/07\/COESIONE-Versione-positiva-fondo-trasparente-768x112.png 768w, https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2025\/07\/COESIONE-Versione-positiva-fondo-trasparente-1536x225.png 1536w, https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2025\/07\/COESIONE-Versione-positiva-fondo-trasparente-2048x300.png 2048w\" sizes=\"auto, (max-width: 423px) 100vw, 423px\" \/><\/p>\n<p>Mercoled\u00ec 10 gennaio\u00a0 ore 16.00 Spazio Attivo Bracciano<\/p>\n<p>Lazio Innova organizza in collaborazione con Artigiancassa un ciclo di webinar di approfondimento sui seguenti strumenti finanziari:<\/p>\n<ul>\n<li>Nuovo Fondo Piccolo Credito (NFPC) &#8211; Si rivolge alle imprese che hanno fabbisogni finanziari contenuti e non generano sufficiente marginalit\u00e0 per il sistema bancario. Eroga finanziamenti a tasso zero della durata di 5 anni, da 10 a 50mila euro;<\/li>\n<li>Nuovo Fondo Futuro (NFF) &#8211; L\u2019avviso si rivolge a imprese nuove o in fase di avvio. Eroga finanziamenti a tasso zero per la durata di 6 anni, da 5 a 25mila euro con abbuono ultime 12 rate mensili per le imprese in regola con il piano di ammortamento;<\/li>\n<li>Fondo Patrimonializzazione PMI &#8211; Il bando si rivolge a Piccole e Medie Imprese (PMI) costituite in forma di societ\u00e0 di capitali. Ha l\u2019obiettivo di incentivare un intervento di patrimonializzazione da parte di soci nuovi o esistenti. Il prestito pu\u00f2 coprire fino al 50% del progetto in quanto la parte restante deve essere coperta dall\u2019aumento di capitale. Eroga finanziamenti a tasso zero della durata di 7 anni, da 50 a 500 mila euro, in misura pari all\u2019aumento di capitale sottoscritto e versato;<\/li>\n<\/ul>\n<p>L\u2019iniziativa \u00e8 realizzata con il cofinanziamento dell&#8217;Unione europea attraverso i fondi del PR FESR Lazio 2021-2027<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 10 gennaio\u00a0 ore 16.00 Spazio Attivo Bracciano Lazio Innova organizza in collaborazione con Artigiancassa un ciclo di webinar di approfondimento sui seguenti strumenti finanziari: Nuovo Fondo Piccolo Credito (NFPC) [&hellip;]<\/p>\n","protected":false},"author":4597,"featured_media":27019,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[281,282,65,92,94,100,124],"tribe_events_cat":[206,290,138],"class_list":["post-27036","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-accesso-al-credito","tag-fare-lazio","tag-fondi-europei","tag-pmi","tag-pr-fesr-2021-2027","tag-regione-lazio","tag-webinar","tribe_events_cat-pr-fesr-lazio-2021-2027","tribe_events_cat-seminario","tribe_events_cat-webinar-2","cat_pr-fesr-lazio-2021-2027","cat_seminario","cat_webinar-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webinar strumenti Fare Lazio - Spazio Attivo Bracciano - Eventi - LazioInnova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webinar strumenti Fare Lazio - Spazio Attivo Bracciano - Eventi - LazioInnova\" \/>\n<meta property=\"og:description\" content=\"Mercoled\u00ec 10 gennaio\u00a0 ore 16.00 Spazio Attivo Bracciano Lazio Innova organizza in collaborazione con Artigiancassa un ciclo di webinar di approfondimento sui seguenti strumenti finanziari: Nuovo Fondo Piccolo Credito (NFPC) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventi - LazioInnova\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T12:58:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2024\/01\/credito-pmi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/\",\"name\":\"Webinar strumenti Fare Lazio - Spazio Attivo Bracciano - Eventi - LazioInnova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/app\\\/uploads\\\/2024\\\/01\\\/credito-pmi.png\",\"datePublished\":\"2024-01-04T09:47:55+00:00\",\"dateModified\":\"2025-07-29T12:58:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/app\\\/uploads\\\/2024\\\/01\\\/credito-pmi.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/app\\\/uploads\\\/2024\\\/01\\\/credito-pmi.png\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/e\\\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Webinar strumenti Fare Lazio &#8211; Spazio Attivo Bracciano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/\",\"name\":\"Eventi - LazioInnova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/eventi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webinar strumenti Fare Lazio - Spazio Attivo Bracciano - Eventi - LazioInnova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/","og_locale":"it_IT","og_type":"article","og_title":"Webinar strumenti Fare Lazio - Spazio Attivo Bracciano - Eventi - LazioInnova","og_description":"Mercoled\u00ec 10 gennaio\u00a0 ore 16.00 Spazio Attivo Bracciano Lazio Innova organizza in collaborazione con Artigiancassa un ciclo di webinar di approfondimento sui seguenti strumenti finanziari: Nuovo Fondo Piccolo Credito (NFPC) [&hellip;]","og_url":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/","og_site_name":"Eventi - LazioInnova","article_modified_time":"2025-07-29T12:58:32+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2024\/01\/credito-pmi.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/","url":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/","name":"Webinar strumenti Fare Lazio - Spazio Attivo Bracciano - Eventi - LazioInnova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2024\/01\/credito-pmi.png","datePublished":"2024-01-04T09:47:55+00:00","dateModified":"2025-07-29T12:58:32+00:00","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2024\/01\/credito-pmi.png","contentUrl":"https:\/\/www.lazioinnova.it\/eventi\/app\/uploads\/2024\/01\/credito-pmi.png","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/eventi\/e\/webinar-strumenti-fare-lazio-spazio-attivo-bracciano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.lazioinnova.it\/eventi\/"},{"@type":"ListItem","position":3,"name":"Webinar strumenti Fare Lazio &#8211; Spazio Attivo Bracciano"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/eventi\/#website","url":"https:\/\/www.lazioinnova.it\/eventi\/","name":"Eventi - LazioInnova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/eventi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"ticketed":["rsvp"],"_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events\/27036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/users\/4597"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/comments?post=27036"}],"version-history":[{"count":6,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events\/27036\/revisions"}],"predecessor-version":[{"id":36330,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events\/27036\/revisions\/36330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/media\/27019"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/media?parent=27036"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tags?post=27036"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/eventi\/wp-json\/wp\/v2\/tribe_events_cat?post=27036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}