{"id":6009,"date":"2025-10-31T17:21:08","date_gmt":"2025-10-31T16:21:08","guid":{"rendered":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/?post_type=innovatore&#038;p=6009"},"modified":"2025-11-05T11:30:26","modified_gmt":"2025-11-05T10:30:26","slug":"nib-biotec","status":"publish","type":"innovatore","link":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/","title":{"rendered":"NIB biotec"},"content":{"rendered":"\n<p>NIB biotec \u00e8 un\u2019azienda innovativa che sviluppa test diagnostici in vitro per il tumore alla<br>prostata, integrando competenze in ricerca oncologica, chimica analitica, sviluppo prodotto,<br>aspetti regolatori, clinical trial e business development. <br>La vision \u00e8 rendere la diagnosi precoce pi\u00f9 accessibile, precisa e sostenibile attraverso la medicina di precisione.<\/p>\n\n\n\n<p>Sede legale: Torino<br>Sede operativa: Milano<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"soluzione-innovativa\">Soluzione Innovativa<\/h3>\n\n\n\n<p>NIB biotec ha brevettato biomarcatori urinari per il tumore alla prostata e ha sviluppato un<br>test rapido, non invasivo e clinicamente validato. <br>La soluzione migliora l\u2019accuratezza diagnostica, riduce esami inutili e ottimizza i percorsi diagnostico-terapeutici grazie alla sua agevole integrazione nella normale pratica clinica, dallo studio medico ai flussi ospedalieri.<\/p>\n\n\n\n<p>Il basso costo e la semplicit\u00e0 di utilizzo del test consente un accesso equo e la decentralizzazione degli esami di primo livello, anche in contesti non urbani e con risorse limitate, facilitandone la diffusione e l\u2019utilizzo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NIB biotec \u00e8 un\u2019azienda innovativa che sviluppa test diagnostici in vitro per il tumore allaprostata, integrando competenze in ricerca oncologica, chimica analitica, sviluppo prodotto,aspetti regolatori, clinical trial e business development. La vision \u00e8 rendere la diagnosi precoce pi\u00f9 accessibile, precisa e sostenibile attraverso la medicina di precisione. Sede legale: TorinoSede operativa: Milano Soluzione Innovativa NIB [&hellip;]<\/p>\n","protected":false},"featured_media":6013,"template":"","meta":{"_acf_changed":true,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"class_list":["post-6009","innovatore","type-innovatore","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NIB biotec - Innovazione Aperta - LazioInnova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NIB biotec - Innovazione Aperta - LazioInnova\" \/>\n<meta property=\"og:description\" content=\"NIB biotec \u00e8 un\u2019azienda innovativa che sviluppa test diagnostici in vitro per il tumore allaprostata, integrando competenze in ricerca oncologica, chimica analitica, sviluppo prodotto,aspetti regolatori, clinical trial e business development. La vision \u00e8 rendere la diagnosi precoce pi\u00f9 accessibile, precisa e sostenibile attraverso la medicina di precisione. Sede legale: TorinoSede operativa: Milano Soluzione Innovativa NIB [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovazione Aperta - LazioInnova\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T10:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2025\/10\/Logo-NIB-biotech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/\",\"name\":\"NIB biotec - Innovazione Aperta - LazioInnova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/app\\\/uploads\\\/2025\\\/10\\\/Logo-NIB-biotech.jpg\",\"datePublished\":\"2025-10-31T16:21:08+00:00\",\"dateModified\":\"2025-11-05T10:30:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/app\\\/uploads\\\/2025\\\/10\\\/Logo-NIB-biotech.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/app\\\/uploads\\\/2025\\\/10\\\/Logo-NIB-biotech.jpg\",\"width\":400,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/nib-biotec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovatori\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/innovatore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NIB biotec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/\",\"name\":\"Innovazione Aperta - LazioInnova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NIB biotec - Innovazione Aperta - LazioInnova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/","og_locale":"it_IT","og_type":"article","og_title":"NIB biotec - Innovazione Aperta - LazioInnova","og_description":"NIB biotec \u00e8 un\u2019azienda innovativa che sviluppa test diagnostici in vitro per il tumore allaprostata, integrando competenze in ricerca oncologica, chimica analitica, sviluppo prodotto,aspetti regolatori, clinical trial e business development. La vision \u00e8 rendere la diagnosi precoce pi\u00f9 accessibile, precisa e sostenibile attraverso la medicina di precisione. Sede legale: TorinoSede operativa: Milano Soluzione Innovativa NIB [&hellip;]","og_url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/","og_site_name":"Innovazione Aperta - LazioInnova","article_modified_time":"2025-11-05T10:30:26+00:00","og_image":[{"width":400,"height":360,"url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2025\/10\/Logo-NIB-biotech.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/","url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/","name":"NIB biotec - Innovazione Aperta - LazioInnova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2025\/10\/Logo-NIB-biotech.jpg","datePublished":"2025-10-31T16:21:08+00:00","dateModified":"2025-11-05T10:30:26+00:00","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2025\/10\/Logo-NIB-biotech.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2025\/10\/Logo-NIB-biotech.jpg","width":400,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/nib-biotec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/"},{"@type":"ListItem","position":2,"name":"Innovatori","item":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/innovatore\/"},{"@type":"ListItem","position":3,"name":"NIB biotec"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/#website","url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/","name":"Innovazione Aperta - LazioInnova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/innovatore\/6009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/innovatore"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/types\/innovatore"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/media\/6013"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/media?parent=6009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}