{"id":3331,"date":"2024-11-08T17:03:52","date_gmt":"2024-11-08T16:03:52","guid":{"rendered":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/?post_type=partner&#038;p=3331"},"modified":"2024-11-14T15:10:28","modified_gmt":"2024-11-14T14:10:28","slug":"gruppo-rea-italia","status":"publish","type":"partner","link":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/","title":{"rendered":"Gruppo REA Italia"},"content":{"rendered":"\n<p>Gruppo REA Italia \u00e8 il secondo consorzio nazionale di imprese, con oltre 140 aziende associate, che si concentra principalmente sul settore dell\u2019edilizia e sulla distribuzione di materiali da costruzione. <br>Nato nel 2015, fin dalla sua costituzione ha sempre sostenuto:<br>&#8211; la Sostenibilit\u00e0<br>&#8211; l\u2019Edilizia Circolare<br>&#8211; l\u2019Edilizia digitale<br>&#8211; la Formazione Specializzata<br>promuovendo sempre prodotti della bioedilizia, innovativi, a km 0, nel rispetto dell\u2019ambiente, delle normative e della sicurezza in cantiere e nei luoghi di lavoro.<\/p>\n\n\n\n<p>Tra le principali partnership si citano quelle con DAIKIN, ECOBEL, KERAKOLL, VAGA MAPEI, LINEA VITA CO.MED, UNIVERSITA\u2019 SANTA RITA Roma, INBAR ISTITUTO NAZIONALE BIOARCHITETTURA.<\/p>\n\n\n\n<p>Crediamo molto nell\u2019energia pulita, per questo investiamo per portare sul mercato le migliori soluzioni per l\u2019utilizzo delle energie rinnovabili all\u2019interno degli edifici. Dagli impianti fotovoltaici alle pompe di calore, dalle caldaie a biomassa ai sistemi radianti: il continuo sviluppo di prodotti e sistemi all\u2019avanguardia, ci permette di offrire la combinazione migliore per soddisfare ogni esigenza in termini di efficienza energetica e sostenibilit\u00e0, fornendo l\u2019energia giusta ad ogni ambiente dell\u2019edificio. Per limitare al massimo la dispersione e lo spreco energetico, massimizzando il risparmio e l\u2019efficienza dei sistemi proposti, offriamo le soluzioni per l\u2019isolamento e la coibentazione pi\u00f9 efficaci e naturali: dai pannelli sottovuoto alle fibre vegetali, passando per le facciate ventilate.<\/p>\n\n\n\n<p>In collaborazione con l\u2019Universit\u00e0 di Roma Santa Rita, nostro partner per la formazione specializzata nel settore dell\u2019edilizia, ci impegniamo nel rilascio di certificazioni obbligatorie e patentini per operare in cantiere (installazione pannelli fotovoltaici, pompe di calore, posa di cappotti termici, linea vita per la sicurezza sui terrazzi, decoratori).<br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/308798286_3324295507855560_645470117700754343_n-1024x768.jpg\" alt=\"\" class=\"wp-image-3351\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/308798286_3324295507855560_645470117700754343_n-1024x768.jpg 1024w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/308798286_3324295507855560_645470117700754343_n-300x225.jpg 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/308798286_3324295507855560_645470117700754343_n-768x576.jpg 768w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/308798286_3324295507855560_645470117700754343_n-1536x1152.jpg 1536w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/308798286_3324295507855560_645470117700754343_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>Gallery Prodotti<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/cappottocapo-squadra-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"282\" data-id=\"3333\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/cappottocapo-squadra-.png\" alt=\"\" class=\"wp-image-3333\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/cappottocapo-squadra-.png 337w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/cappottocapo-squadra--300x251.png 300w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-2-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"342\" height=\"302\" data-id=\"3336\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-2-.png\" alt=\"\" class=\"wp-image-3336\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-2-.png 342w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-2--300x265.png 300w\" sizes=\"auto, (max-width: 342px) 100vw, 342px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"331\" data-id=\"3337\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-3.png\" alt=\"\" class=\"wp-image-3337\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-3.png 340w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-3-300x292.png 300w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-4-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"257\" data-id=\"3338\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-4-.png\" alt=\"\" class=\"wp-image-3338\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-4-.png 338w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-4--300x228.png 300w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-5.png\"><img loading=\"lazy\" decoding=\"async\" width=\"351\" height=\"286\" data-id=\"3341\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-5.png\" alt=\"\" class=\"wp-image-3341\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-5.png 351w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-5-300x244.png 300w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-6.png\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"277\" data-id=\"3332\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-6.png\" alt=\"\" class=\"wp-image-3332\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-6.png 350w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-6-300x237.png 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-7.png\"><img loading=\"lazy\" decoding=\"async\" width=\"356\" height=\"281\" data-id=\"3334\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-7.png\" alt=\"\" class=\"wp-image-3334\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-7.png 356w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-7-300x237.png 300w\" sizes=\"auto, (max-width: 356px) 100vw, 356px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-8.png\"><img loading=\"lazy\" decoding=\"async\" width=\"347\" height=\"297\" data-id=\"3335\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-8.png\" alt=\"\" class=\"wp-image-3335\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-8.png 347w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-8-300x257.png 300w\" sizes=\"auto, (max-width: 347px) 100vw, 347px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-10.png\"><img loading=\"lazy\" decoding=\"async\" width=\"341\" height=\"287\" data-id=\"3339\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-10.png\" alt=\"\" class=\"wp-image-3339\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-10.png 341w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/corso-10-300x252.png 300w\" sizes=\"auto, (max-width: 341px) 100vw, 341px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-erba-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"922\" height=\"736\" data-id=\"3344\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-erba-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3344\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-erba-bio-edilizia-.png 922w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-erba-bio-edilizia--300x239.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-erba-bio-edilizia--768x613.png 768w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-cannicciato-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"937\" height=\"647\" data-id=\"3349\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-cannicciato-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3349\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-cannicciato-bio-edilizia-.png 937w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-cannicciato-bio-edilizia--300x207.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-cannicciato-bio-edilizia--768x530.png 768w\" sizes=\"auto, (max-width: 937px) 100vw, 937px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-legno-e-cemento-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"906\" height=\"661\" data-id=\"3347\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-legno-e-cemento-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3347\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-legno-e-cemento-bio-edilizia-.png 906w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-legno-e-cemento-bio-edilizia--300x219.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-in-legno-e-cemento-bio-edilizia--768x560.png 768w\" sizes=\"auto, (max-width: 906px) 100vw, 906px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-inalga-marina-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"922\" height=\"692\" data-id=\"3346\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-inalga-marina-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3346\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-inalga-marina-bio-edilizia-.png 922w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-inalga-marina-bio-edilizia--300x225.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-inalga-marina-bio-edilizia--768x576.png 768w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"913\" height=\"876\" data-id=\"3340\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3340\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-bio-edilizia-.png 913w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-bio-edilizia--300x288.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-bio-edilizia--768x737.png 768w\" sizes=\"auto, (max-width: 913px) 100vw, 913px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-piu-fibra-di-legno-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"947\" height=\"740\" data-id=\"3342\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-piu-fibra-di-legno-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3342\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-piu-fibra-di-legno-bio-edilizia-.png 947w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-piu-fibra-di-legno-bio-edilizia--300x234.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolante-sotto-vuoto-piu-fibra-di-legno-bio-edilizia--768x600.png 768w\" sizes=\"auto, (max-width: 947px) 100vw, 947px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolantefibra-di-paglia-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"932\" height=\"670\" data-id=\"3348\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolantefibra-di-paglia-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3348\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolantefibra-di-paglia-bio-edilizia-.png 932w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolantefibra-di-paglia-bio-edilizia--300x216.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolantefibra-di-paglia-bio-edilizia--768x552.png 768w\" sizes=\"auto, (max-width: 932px) 100vw, 932px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolanti-in-fibra-di-legno-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"926\" height=\"725\" data-id=\"3343\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolanti-in-fibra-di-legno-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3343\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolanti-in-fibra-di-legno-bio-edilizia-.png 926w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolanti-in-fibra-di-legno-bio-edilizia--300x235.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/isolanti-in-fibra-di-legno-bio-edilizia--768x601.png 768w\" sizes=\"auto, (max-width: 926px) 100vw, 926px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/livellante-isolante-in-canapa-bio-edilizia-.png\"><img loading=\"lazy\" decoding=\"async\" width=\"912\" height=\"687\" data-id=\"3345\" src=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/livellante-isolante-in-canapa-bio-edilizia-.png\" alt=\"\" class=\"wp-image-3345\" srcset=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/livellante-isolante-in-canapa-bio-edilizia-.png 912w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/livellante-isolante-in-canapa-bio-edilizia--300x226.png 300w, https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/livellante-isolante-in-canapa-bio-edilizia--768x579.png 768w\" sizes=\"auto, (max-width: 912px) 100vw, 912px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"featured_media":3368,"template":"","meta":{"_acf_changed":true,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"class_list":["post-3331","partner","type-partner","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gruppo REA Italia - Innovazione Aperta - LazioInnova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gruppo REA Italia - Innovazione Aperta - LazioInnova\" \/>\n<meta property=\"og:description\" content=\"Gruppo REA Italia \u00e8 il secondo consorzio nazionale di imprese, con oltre 140 aziende associate, che si concentra principalmente sul settore dell\u2019edilizia e sulla distribuzione di materiali da costruzione. Nato nel 2015, fin dalla sua costituzione ha sempre sostenuto:&#8211; la Sostenibilit\u00e0&#8211; l\u2019Edilizia Circolare&#8211; l\u2019Edilizia digitale&#8211; la Formazione Specializzatapromuovendo sempre prodotti della bioedilizia, innovativi, a km [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovazione Aperta - LazioInnova\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T14:10:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/nuovo-logo-gruppo-rea.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"361\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/\",\"name\":\"Gruppo REA Italia - Innovazione Aperta - LazioInnova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/app\\\/uploads\\\/2024\\\/11\\\/nuovo-logo-gruppo-rea.png\",\"datePublished\":\"2024-11-08T16:03:52+00:00\",\"dateModified\":\"2024-11-14T14:10:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/app\\\/uploads\\\/2024\\\/11\\\/nuovo-logo-gruppo-rea.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/app\\\/uploads\\\/2024\\\/11\\\/nuovo-logo-gruppo-rea.png\",\"width\":400,\"height\":361},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/gruppo-rea-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partner\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/partner\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gruppo REA Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/\",\"name\":\"Innovazione Aperta - LazioInnova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/innovazione-aperta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gruppo REA Italia - Innovazione Aperta - LazioInnova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/","og_locale":"it_IT","og_type":"article","og_title":"Gruppo REA Italia - Innovazione Aperta - LazioInnova","og_description":"Gruppo REA Italia \u00e8 il secondo consorzio nazionale di imprese, con oltre 140 aziende associate, che si concentra principalmente sul settore dell\u2019edilizia e sulla distribuzione di materiali da costruzione. Nato nel 2015, fin dalla sua costituzione ha sempre sostenuto:&#8211; la Sostenibilit\u00e0&#8211; l\u2019Edilizia Circolare&#8211; l\u2019Edilizia digitale&#8211; la Formazione Specializzatapromuovendo sempre prodotti della bioedilizia, innovativi, a km [&hellip;]","og_url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/","og_site_name":"Innovazione Aperta - LazioInnova","article_modified_time":"2024-11-14T14:10:28+00:00","og_image":[{"width":400,"height":361,"url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/nuovo-logo-gruppo-rea.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/","url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/","name":"Gruppo REA Italia - Innovazione Aperta - LazioInnova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/nuovo-logo-gruppo-rea.png","datePublished":"2024-11-08T16:03:52+00:00","dateModified":"2024-11-14T14:10:28+00:00","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/nuovo-logo-gruppo-rea.png","contentUrl":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/app\/uploads\/2024\/11\/nuovo-logo-gruppo-rea.png","width":400,"height":361},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/gruppo-rea-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/"},{"@type":"ListItem","position":2,"name":"Partner","item":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/partner\/"},{"@type":"ListItem","position":3,"name":"Gruppo REA Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/#website","url":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/","name":"Innovazione Aperta - LazioInnova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/partner\/3331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/partner"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/types\/partner"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/media\/3368"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/innovazione-aperta\/wp-json\/wp\/v2\/media?parent=3331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}