{"id":10051,"date":"2023-05-30T08:34:06","date_gmt":"2023-05-30T06:34:06","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=10051"},"modified":"2023-06-06T16:30:08","modified_gmt":"2023-06-06T14:30:08","slug":"digital-export-academy-di-ice-agenzia-focus-editoria","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/","title":{"rendered":"Digital Export Academy\u00ae- Focus Editoria"},"content":{"rendered":"\n<p><strong>Agenzia ICE <\/strong>per la promozione all&#8217;estero e l&#8217;internazionalizzazione delle imprese italiane in <strong>collaborazione con AIE &#8211; Associazione Italiana Editori<\/strong> organizza il <strong>percorso formativo <a href=\"https:\/\/exportraining.ice.it\/offerta-formativa\/formazione-imprese\/digital-export-academy-editoria-percorso-avanzato-in-collaborazione-con-aie-associazione-italiana-editori\/\" target=\"_blank\" rel=\"noreferrer noopener\">Digital Export Academy\u00ae<\/a><\/strong> &#8211;  dedicato ad un massimo di <strong>100 aziende del settore dell\u2019editoria interessate allo sviluppo della propria strategia di internazionalizzazione mediante gli strumenti digitali. &nbsp;<\/strong><\/p>\n\n\n\n<p>La Digital Export Academy\u00ae giunta ormai alla V annualit\u00e0 \u00e8 un percorso con marchio registrato Agenzia ICE, <strong>completamente gratuito<\/strong>, erogato in modalit\u00e0 online non registrata e dedicato alle principali materie del marketing digitale.<\/p>\n\n\n\n<p><strong>OBIETTIVI e CONTENUTI<\/strong><\/p>\n\n\n\n<p>La Digital Export Academy\u00ae si rivolge a PMI che intendono sviluppare competenze sugli strumenti di marketing, comunicazione, vendita e promozione digitale a supporto della propria strategia di internazionalizzazione. I moduli previsti in questa edizione dedicata al settore dell\u2019editoria approfondiranno i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri, con esempi pratici e focus di mercato per paesi dell\u2019America Latina ed Europa dell\u2019Est.<\/p>\n\n\n\n<p><strong>MODALITA\u2019 DI SVOLGIMENTO<\/strong><\/p>\n\n\n\n<p>Le lezioni si svolgeranno in modalit\u00e0 virtuale, attraverso la piattaforma per videoconferenze LifeSize accessibile da browser. Alle aziende ammesse saranno fornite le indicazioni per accedere all\u2019aula virtuale.<\/p>\n\n\n\n<p><strong>CALENDARIO<\/strong><\/p>\n\n\n\n<p>Le lezioni si svolgeranno secondo il seguente calendario ogni mattina ad eccezione del 28 giugno che sar\u00e0 una sessione pomeridiana:<\/p>\n\n\n\n<p>\u00a7 <strong>22 e 26 giugno<\/strong>: Saluti istituzionali di apertura e E-commerce (Digital Business Promotion per l\u2019editoria)<\/p>\n\n\n\n<p>\u00a7 <strong>28 giugno<\/strong>: Focus Mercato- America Latina (Brasile, Colombia, Messico)<\/p>\n\n\n\n<p>\u00a7 <strong>3 luglio<\/strong>: Gestione dell&#8217;E-meeting e Public Speaking Internazionale<\/p>\n\n\n\n<p>\u00a7 <strong>5 luglio<\/strong>: Focus Mercato- Europa dell\u2019Est (Romania, Albania, Croazia)<\/p>\n\n\n\n<p>\u00a7 <strong>6 luglio<\/strong>: La tutela on line del diritto d\u2019autore<\/p>\n\n\n\n<p><strong>ADESIONI <\/strong><\/p>\n\n\n\n<p>Per iscriversi, occorre compilare in ogni sua parte il form di adesione al seguente link:<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfPiwrQS1S8DaCYunjPfU1zjTp9yOQ5JPuOL3AlblzpArLLuQ\/viewform\">Scheda di adesione &#8211; <\/a><\/strong><\/p>\n\n\n\n<p><strong>L\u2019adesione dovr\u00e0 essere perfezionata entro il 16 giugno 2023.<\/strong><\/p>\n\n\n\n<p>Non verranno accettate domande pervenute oltre i termini indicati. Le aziende saranno ammesse in ordine cronologico, fino ad esaurimento dei posti disponibili compatibilmente con il possesso dei requisiti richiesti per la partecipazione. Il corso \u00e8 riservato alle figure aziendali che curano l\u2019export o attivit\u00e0 di marketing e comunicazione. Ogni azienda potr\u00e0 inviare domanda di adesione per un solo partecipante. L\u2019ammissione di un eventuale secondo partecipante sar\u00e0 valutata in seguito alla chiusura adesioni in base al numero di posti vacanti.<\/p>\n\n\n\n<p><strong>CRITERI DI AMMISSIBILIT\u00c0 <\/strong><\/p>\n\n\n\n<p>Il percorso formativo \u00e8 rivolto ad aziende del settore dell\u2019EDITORIA registrate presso le CCIAA, con particolare riguardo a PMI e\/o Consorzi all&#8217;export.<\/p>\n\n\n\n<p><strong>Saranno ammesse fino ad un massimo di 100 aziende<\/strong> che: <\/p>\n\n\n\n<p>\u25aa appartengano al settore dell\u2019editoria<\/p>\n\n\n\n<p>\u25aa non si trovino in situazioni di morosit\u00e0 nei confronti di ICE-Agenzia <\/p>\n\n\n\n<p>\u25aa siano dotate di un sito internet aziendale <\/p>\n\n\n\n<p>\u25aa siano dotate di una risorsa dedicata all\u2019export con buona conoscenza della lingua inglese.<\/p>\n\n\n\n<p><strong>\u00c8 in ogni caso esclusa la partecipazione di societ\u00e0 di consulenza e servizi.<\/strong><\/p>\n\n\n\n<p>Per maggiori informazioni contattare:<\/p>\n\n\n\n<p><strong>CONTATTI<\/strong><br><strong>AGENZIA ICE<\/strong><br>Ufficio Servizi Formativi<br>Dott.ssa Claudia Tola<br>Dott.ssa Federica Orlando<br>Tel. +39 06 5992<br>6106\/6061<br>digitalexportacademy@ice.it<br><\/p>\n\n\n\n<p><strong>AIE &#8211; EDISER<\/strong><br>Societ\u00e0 di Servizi<br>dell&#8217;Associazione Italiana<br>Editori<br>Dott. Manuel Recchia<br>Tel. +39 02 8928 0801<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sei appuntamenti di alta formazione, organizzati da Agenzia ICE ed AIE, dal 22 giugno al 6 luglio, per approfondire i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri. Adesioni entro il 16 giugno.<\/p>\n","protected":false},"author":11,"featured_media":10137,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[27,269],"tags":[95,71,170,161],"class_list":["post-10051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formazione-ed-empowerment","category-network","tag-agenzia-ice","tag-editoria","tag-formazione","tag-ice-agenzia"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital Export Academy\u00ae- Focus Editoria - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"Sei appuntamenti di alta formazione, organizzati da Agenzia ICE ed AIE, dal 22 giugno al 6 luglio, per approfondire i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri. Adesioni entro il 16 giugno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital Export Academy\u00ae- Focus Editoria - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Sei appuntamenti di alta formazione, organizzati da Agenzia ICE ed AIE, dal 22 giugno al 6 luglio, per approfondire i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri. Adesioni entro il 16 giugno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-30T06:34:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T14:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto.png\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Patrizia De Vincenzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrizia De Vincenzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/\"},\"author\":{\"name\":\"Patrizia De Vincenzi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"headline\":\"Digital Export Academy\u00ae- Focus Editoria\",\"datePublished\":\"2023-05-30T06:34:06+00:00\",\"dateModified\":\"2023-06-06T14:30:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/\"},\"wordCount\":488,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/05\\\/BANNER-EDITORIA-giusto.png\",\"keywords\":[\"Agenzia ICE\",\"Editoria\",\"formazione\",\"ICE-Agenzia\"],\"articleSection\":[\"Formazione ed Empowerment\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/\",\"name\":\"Digital Export Academy\u00ae- Focus Editoria - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/05\\\/BANNER-EDITORIA-giusto.png\",\"datePublished\":\"2023-05-30T06:34:06+00:00\",\"dateModified\":\"2023-06-06T14:30:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"description\":\"Sei appuntamenti di alta formazione, organizzati da Agenzia ICE ed AIE, dal 22 giugno al 6 luglio, per approfondire i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri. Adesioni entro il 16 giugno\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/05\\\/BANNER-EDITORIA-giusto.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/05\\\/BANNER-EDITORIA-giusto.png\",\"width\":777,\"height\":437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/05\\\/30\\\/digital-export-academy-di-ice-agenzia-focus-editoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digital Export Academy\u00ae- Focus Editoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\",\"name\":\"Patrizia De Vincenzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"caption\":\"Patrizia De Vincenzi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/p-devincenzi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital Export Academy\u00ae- Focus Editoria - Lazio International - Lazio Innova","description":"Sei appuntamenti di alta formazione, organizzati da Agenzia ICE ed AIE, dal 22 giugno al 6 luglio, per approfondire i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri. Adesioni entro il 16 giugno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/","og_locale":"it_IT","og_type":"article","og_title":"Digital Export Academy\u00ae- Focus Editoria - Lazio International - Lazio Innova","og_description":"Sei appuntamenti di alta formazione, organizzati da Agenzia ICE ed AIE, dal 22 giugno al 6 luglio, per approfondire i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri. Adesioni entro il 16 giugno","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2023-05-30T06:34:06+00:00","article_modified_time":"2023-06-06T14:30:08+00:00","og_image":[{"width":777,"height":437,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto.png","type":"image\/png"}],"author":"Patrizia De Vincenzi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Patrizia De Vincenzi","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/"},"author":{"name":"Patrizia De Vincenzi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"headline":"Digital Export Academy\u00ae- Focus Editoria","datePublished":"2023-05-30T06:34:06+00:00","dateModified":"2023-06-06T14:30:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/"},"wordCount":488,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto.png","keywords":["Agenzia ICE","Editoria","formazione","ICE-Agenzia"],"articleSection":["Formazione ed Empowerment","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/","name":"Digital Export Academy\u00ae- Focus Editoria - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto.png","datePublished":"2023-05-30T06:34:06+00:00","dateModified":"2023-06-06T14:30:08+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"description":"Sei appuntamenti di alta formazione, organizzati da Agenzia ICE ed AIE, dal 22 giugno al 6 luglio, per approfondire i pi\u00f9 importanti temi di marketing digitale a supporto della vendita dei diritti d\u2019autore sui mercati esteri. Adesioni entro il 16 giugno","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto.png","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto.png","width":777,"height":437},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/05\/30\/digital-export-academy-di-ice-agenzia-focus-editoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Digital Export Academy\u00ae- Focus Editoria"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758","name":"Patrizia De Vincenzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","caption":"Patrizia De Vincenzi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto-600x400.png","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/05\/BANNER-EDITORIA-giusto-600x437.png","author_info":{"display_name":"Patrizia De Vincenzi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/10051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=10051"}],"version-history":[{"count":11,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/10051\/revisions"}],"predecessor-version":[{"id":10139,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/10051\/revisions\/10139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/10137"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=10051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=10051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=10051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}