{"id":10995,"date":"2023-09-26T09:29:30","date_gmt":"2023-09-26T07:29:30","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=10995"},"modified":"2023-09-28T16:02:52","modified_gmt":"2023-09-28T14:02:52","slug":"manifestazione-di-interesse-per-romics-edizione-autunno","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/","title":{"rendered":"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"89\" src=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/09\/Loghi-PR-FESR-Fiere-1024x89.jpg\" alt=\"\" class=\"wp-image-11499\" srcset=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/09\/Loghi-PR-FESR-Fiere-1024x89.jpg 1024w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/09\/Loghi-PR-FESR-Fiere-300x26.jpg 300w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/09\/Loghi-PR-FESR-Fiere-768x67.jpg 768w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/09\/Loghi-PR-FESR-Fiere-1536x134.jpg 1536w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/09\/Loghi-PR-FESR-Fiere-2048x179.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>La Regione Lazio<\/strong>, attraverso il soggetto attuatore Lazio Innova, e la <strong>Camera di Commercio di Roma<\/strong>, con il con il supporto dell\u2019<strong>Azienda Speciale Sviluppo e Territorio<\/strong>, nell\u2019ambito della Convenzione per la partecipazione congiunta a iniziative e manifestazioni fieristiche, e allo scopo di sostenere l\u2019internazionalizzazione dell\u2019ecosistema della filiera del fumetto regionale, selezionano <strong>n. 32 imprese del Lazio<\/strong> interessate a prendere parte a Romics \u2013 Edizione Autunno, che si svolger\u00e0 in presenza, <strong>dal 5 all\u20198 ottobre 2023<\/strong> presso la Fiera di Roma.<\/p>\n\n\n\n<p>La partecipazione di <strong>12 imprese<\/strong> delle 32 selezionate <strong>\u00e8 sostenuta con il contributo del PR FESR Lazio 2021-2027.<\/strong><\/p>\n\n\n\n<p>Gli Enti promotori, Lazio Innova e Sviluppo e Territorio daranno opportuna diffusione sui rispettivi siti istituzionali e su tutti i canali di comunicazione utilizzati per promuovere le iniziative.<\/p>\n\n\n\n<p>Quattro giorni di kermesse ininterrotta con eventi, incontri e spettacoli: un programma ricco con presentazioni, incontri ed eventi in contemporanea per immergersi in tutti i mondi della creativit\u00e0, dal fumetto all\u2019illustrazione, dalla narrativa al cinema. Tutte le novit\u00e0 con le grandi case editrici, le fumetterie, i collezionisti, i videogiochi, i gadget e gli imperdibili incontri con autori e editori.<\/p>\n\n\n\n<p><strong>Ogni impresa avr\u00e0 a disposizione uno spazio espositivo di mq. 12 allestito come segue<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pareti perimetrali<\/li>\n\n\n\n<li>Moquette<\/li>\n\n\n\n<li>Allaccio elettrico da 2 kw<\/li>\n\n\n\n<li>Impianto elettrico con faretto circa per ogni metro lineare di fronte espositivo<\/li>\n\n\n\n<li>N. 1 tavolo e N. 2 sedie<\/li>\n\n\n\n<li>Fascione con denominazione dell\u2019azienda<\/li>\n\n\n\n<li>N. 1 pass auto<\/li>\n\n\n\n<li>Assicurazione.<\/li>\n<\/ul>\n\n\n\n<p><strong>Categorie di riferimento<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fumetterie<\/li>\n\n\n\n<li>Editoria e libri illustrati<\/li>\n\n\n\n<li>Giochi per bambini<\/li>\n\n\n\n<li>Educational games<\/li>\n\n\n\n<li>Cinema<\/li>\n\n\n\n<li>Cinema e studi di animazione<\/li>\n\n\n\n<li>Scuole di settore.<\/li>\n<\/ul>\n\n\n\n<p><br><strong>REQUISITI DI AMMISSIBILIT\u00c0 PER LE IMPRESE INVITATE A PARTECIPARE<\/strong><\/p>\n\n\n\n<p>L\u2019opportunit\u00e0 di prendere parte a ROMICS Autunno 2023 \u00e8 riservata ad imprese in possesso dei seguenti requisiti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sede legale e\/o operativa nella Regione Lazio;<\/li>\n\n\n\n<li>coerenza dell\u2019attivit\u00e0 dell\u2019azienda con il settore o i settori economici cui la manifestazione \u00e8 rivolta;<\/li>\n\n\n\n<li>essere MPMI, come classificate nell&#8217;Allegato I del Regolamento (UE) n. 651\/2014, in forma singola o associata in Consorzi, Societ\u00e0 Consortili o Reti di imprese con personalit\u00e0 giuridica (Reti-soggetto), definite ai sensi dei commi 4-ter e 4-quater dell&#8217;art. 3 del Decreto-legge n. 5 del 10 febbraio 2009, convertito, con modificazioni, nella Legge n. 33 del 09 Aprile 2009 e ss.mm.ii., al momento della presentazione della manifestazione di interesse;<\/li>\n\n\n\n<li>essere regolarmente iscritte nel Registro delle Imprese della C.C.I.A.A. competente per territorio e in regola, al momento della presentazione della manifestazione di interesse o comunque entro i termini di chiusura di presentazione della stessa, con il pagamento del diritto annuale e con la dichiarazione dell\u2019attivit\u00e0 esercitata;<\/li>\n\n\n\n<li>esercitare, in relazione alla sede laziale, un\u2019attivit\u00e0 economica coerente con il settore;<\/li>\n\n\n\n<li>non essere beneficiarie di agevolazioni pubbliche relative alla partecipazione alla manifestazione fieristica in questione n\u00e9 aver presentato domande di agevolazione per partecipare alla medesima manifestazione;<\/li>\n\n\n\n<li> essere nel pieno e libero esercizio dei propri diritti, attive e non essere sottoposte n\u00e9 essere state sottoposte, nei cinque anni precedenti, a procedure di liquidazione volontaria, liquidazione coatta, fallimento, concordato preventivo (ad eccezione del concordato preventivo con continuit\u00e0 aziendale) ed ogni altra procedura concorsuale n\u00e9 abbiano in corso un procedimento per la dichiarazione di una delle suddette situazioni;<\/li>\n\n\n\n<li>possedere capacit\u00e0 di contrarre ovvero non essere state oggetto di sanzione interdittiva o altra sanzione che comporti il divieto di contrarre con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>non avere Amministratori e\/o Legali Rappresentanti che siano stati condannati con sentenza passata in giudicato ovvero nei cui confronti sia stato emesso decreto penale di condanna divenuto irrevocabile o sentenza di applicazione della pena su richiesta, ai sensi dell\u2019art. 444 c.p.p., per reati gravi in danno dello Stato o della Comunit\u00e0 che incidono sulla moralit\u00e0 professionale (\u00e8 comunque causa di esclusione la condanna, con sentenza passata in giudicato, per reati di partecipazione ad un&#8217;organizzazione criminale, corruzione, frode, riciclaggio);<\/li>\n\n\n\n<li>non avere Amministratori e\/o Legali Rappresentanti che si siano resi colpevoli di false dichiarazioni nei rapporti con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>essere in regola con il versamento dei contributi previdenziali e assistenziali, accertabile mediante acquisizione del DURC, <br><br>ovvero<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>non essere soggetti agli obblighi in materia di regolarit\u00e0 contributiva e, quindi, non essere tenuti all\u2019iscrizione presso alcun Ente previdenziale o assistenziale.<\/li>\n<\/ul>\n\n\n\n<p>Il possesso dei requisiti \u00e8 attestato mediante dichiarazioni rese al momento della partecipazione attraverso il modulo di manifestazione di interesse.<\/p>\n\n\n\n<p>Tali dichiarazioni potranno essere verificate, cos\u00ec come stabilito dall\u2019art. 71 comma 1 del D.P.R. 445 del 28.12.2000, come modificato dall\u2019art. 264 del D.L. 19 maggio 2020 n. 34, con applicazione, nel caso di dichiarazioni mendaci, della decadenza dai benefici e delle sanzioni penali, rispettivamente previste dagli artt. 75 e 76 del medesimo D.P.R., come da ultimo rese pi\u00f9 severe per effetto del citato articolo 264.<\/p>\n\n\n\n<p><br><strong>MODALIT\u00c0 DI PRESENTAZIONE DELLA DOMANDA DI PARTECIPAZIONE<\/strong><\/p>\n\n\n\n<p>Le aziende interessate a partecipare alla collettiva regionale dovranno effettuare i seguenti adempimenti, entro e non oltre <strong>le ore 15:00 del 28 settembre<\/strong> <strong>2023<\/strong>, pena la non ammissibilit\u00e0 della domanda:<\/p>\n\n\n\n<p style=\"font-size:22px\"><strong>ISCRIZIONI CHIUSE<\/strong><\/p>\n\n\n\n<p><br><strong>CRITERI DI AMMISSIBILIT\u00c0 GENERALI<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Correttezza dell&#8217;iter amministrativo di presentazione della manifestazione di interesse (rispetto delle modalit\u00e0 e dei tempi);<\/li>\n\n\n\n<li>Completezza della domanda di partecipazione.<\/li>\n<\/ul>\n\n\n\n<p><br><strong>SELEZIONE<\/strong><\/p>\n\n\n\n<p>La selezione avverr\u00e0 a cura di un Nucleo di Valutazione composto da:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>un rappresentante di Regione Lazio;<\/li>\n\n\n\n<li>un rappresentante di Lazio Innova;<\/li>\n\n\n\n<li>un rappresentante del Sistema Camerale di Roma;<\/li>\n<\/ol>\n\n\n\n<p><br><strong>CRITERI DI SELEZIONE E COMUNICAZIONE DI AMMISSIONE<\/strong><\/p>\n\n\n\n<p>Le Manifestazioni di interesse saranno accolte secondo l\u2019ordine cronologico di arrivo trattandosi di \u201cprocedura a Sportello\u201d.<\/p>\n\n\n\n<p>A seguito dello svolgimento del processo di selezione, tutti i soggetti che hanno sottoposto la candidatura:<\/p>\n\n\n\n<ul class=\"wp-block-list\" type=\"1\" start=\"1\">\n<li>riceveranno una comunicazione via PEC \u2013 all\u2019indirizzo e-mail indicato in sede di presentazione della manifestazione di interesse \u2013 circa di ammissione o meno all\u2019iniziativa in oggetto;<\/li>\n\n\n\n<li>i soggetti ammessi dovranno, entro 2 giorni lavorativi dal ricevimento della predetta e-mail, provvedere a comunicare via PEC la loro adesione&nbsp;definitiva ovvero la loro rinuncia; Il mancato rispetto dei termini per l\u2019accettazione della proposta di partecipazione comporter\u00e0 l\u2019esclusione dell\u2019azienda. A seguito dell\u2019accettazione, l\u2019azienda sar\u00e0 tenuta a partecipare alla manifestazione in oggetto.<\/li>\n\n\n\n<li>in caso di rinuncia di uno o pi\u00f9 dei soggetti ammessi, si proceder\u00e0 a selezionare gli ulteriori soggetti risultati idonei, nel rispetto della graduatoria redatta dal Nucleo di Valutazione.<\/li>\n<\/ul>\n\n\n\n<p>Si segnala, infine, che la suddetta manifestazione di interesse dell\u2019impresa non vincola gli Enti promotori che si riservano, in qualsiasi momento, di poter annullare, qualora le circostanze lo richiedessero, l\u2019organizzazione della collettiva regionale alla Fiera in oggetto.<\/p>\n\n\n\n<p><br><strong>CONDIZIONI DI ESCLUSIONE<\/strong><\/p>\n\n\n\n<p>Sono&nbsp;escluse&nbsp;dalla partecipazione le imprese gi\u00e0 presenti alla manifestazione con un proprio stand e le imprese morose nei confronti degli organizzatori per somme relative a precedenti manifestazioni, ovvero morose nei confronti di altri organismi in collaborazione con i quali gli organizzatori promuovono le iniziative.<\/p>\n\n\n\n<p>La&nbsp;<strong>mancata partecipazione<\/strong>,&nbsp;o mancato presidio dello stand, potr\u00e0&nbsp;essere <strong>causa di esclusione<\/strong>,&nbsp;ad insindacabile giudizio del Nucleo di Valutazione, alle future&nbsp;iniziative organizzate da Regione Lazio e Camera di Commercio di Roma nell\u2019ambito della Convenzione.<\/p>\n\n\n\n<p><br><strong>REGIME DI AIUTO<\/strong><\/p>\n\n\n\n<p>Considerata la volont\u00e0 dell\u2019Ente promotore di venire incontro alle esigenze delle imprese selezionate, la partecipazione alla manifestazione \u00e8 gratuita, nel rispetto dei limiti del regime \u201cde minimis\u201d, fermo restando che rimangono a carico delle stesse le spese relative ad ogni ulteriore servizio extra di personalizzazione richiesto dalle imprese medesime.<\/p>\n\n\n\n<p>Il sostegno alle imprese si configura quale aiuto indiretto, per la partecipazione alle iniziative e manifestazioni promosse dalla Regione Lazio e sar\u00e0 concesso nel rispetto delle disposizioni di cui al Regolamento (UE) n.1407\/2013 del 18 dicembre 2013 relativo all\u2019applicazione degli articoli 107 e 108 del trattato sul funzionamento dell\u2019Unione Europea agli aiuti \u201cde minimis\u201d.<\/p>\n\n\n\n<p>A seguito dell\u2019obbligo di consultazione preventiva e di implementazione del Registro Nazionale degli Aiuti di Stato, di cui al Regolamento MISE n. 115 del 31 maggio 2017, gli importi relativi alle agevolazioni concesse verranno conseguentemente inseriti nel suddetto Registro, fino ad un importo di massimo <strong>\u20ac2.500,00 iva inclusa<\/strong>, per impresa. Come previsto dall\u2019art. 3 par. 7 dello stesso Regolamento, qualora la concessione di nuovi aiuti \u201cde minimis\u201d comporti il superamento dei massimali previsti, nessuna delle nuove misure di aiuto pu\u00f2 beneficiare del Regolamento. L\u2019importo massimo delle agevolazioni in regime \u201cde minimis\u201d che possono essere concesse ad una medesima impresa in un triennio (l\u2019esercizio finanziario in corso e i due precedenti), senza la preventiva notifica ed autorizzazione da parte della Commissione Europea e senza che ci\u00f2 possa pregiudicare le condizioni di concorrenza tra le imprese, \u00e8 pari a \u20ac 200.000,00.<\/p>\n\n\n\n<p>In caso di superamento delle soglie predette, l\u2019agevolazione suindicata non potr\u00e0 essere concessa, neppure per la parte che non superi detti massimali.<\/p>\n\n\n\n<p>Si fa presente che ciascuna impresa pu\u00f2 monitorare l\u2019importo delle agevolazioni in regime \u201cde minimis\u201d di cui ha beneficiato a far data dal 12 agosto 2017, sul sito del Registro Nazionale degli Aiuti di Stato nella sezione Trasparenza al seguente link:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.rna.gov.it\/RegistroNazionaleTrasparenza\/faces\/pages\/TrasparenzaAiuto.jspx\">https:\/\/www.rna.gov.it\/RegistroNazionaleTrasparenza\/faces\/pages\/TrasparenzaAiuto.jspx<\/a><\/p>\n\n\n\n<p><br><strong>PRIVACY<\/strong><\/p>\n\n\n\n<p>I dati forniti saranno trattati dagli organizzatori in osservanza di quanto disposto dal Regolamento UE 679\/2016 sulla protezione dei dati personali.<\/p>\n\n\n\n<p>Per informazioni rivolgersi a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Regione Lazio &#8211; Lazio Innova S.p.A. \u2013 Area Internazionalizzazione &amp; Cluster<br>e-mail: <a href=\"mailto:internazionalizzazione@lazioinnova.it\" target=\"_blank\" rel=\"noreferrer noopener\">internazionalizzazione@lazioinnova.it<\/a> &#8211; Tel. 06.60.51.60<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Camera di Commercio di Roma:<br>Area III Promozione e Sviluppo \u2013 Servizio Filiere produttive e Fiere <br>e- mail:<a href=\"mailto:attivita.promozionali@rm.camcom.it\">&nbsp;attivita.promozionali@rm.camcom.it<\/a>&nbsp;\u2013 Tel. 06.52082571 \u2013 2065<\/li>\n\n\n\n<li>Sviluppo e Territorio&nbsp;&nbsp; Azienda Speciale della Camera di Commercio di Roma per lo sviluppo e la crescita di Roma e del Lazio: <br>e-mail <a href=\"mailto:Sviluppo@sviluppoeterritorio.camcom.it\">Sviluppo@sviluppoeterritorio.camcom.it<\/a> Tel. 066787758 &#8211; 06 69797165.<\/li>\n<\/ul>\n\n\n\n<p><br>Tutta la modulistica \u00e8 consultabile e scaricabile sui seguenti siti Istituzionali:<\/p>\n\n\n\n<p><a href=\"http:\/\/www.lazioinnova.it\/laziointernational\">www.lazioinnova.it\/laziointernational<\/a>&nbsp;<br><a href=\"http:\/\/www.rm.camcom.it\/\">www.rm.camcom.it<\/a><br><a href=\"file:\/\/\/C:\/Users\/piccioned\/AppData\/Local\/Microsoft\/Windows\/INetCache\/Content.Outlook\/3R2Z0L7M\/www.sviluppoeterritorio.camcom.it\">www.sviluppoeterritorio.camcom.it<\/a><br><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partecipazione collettiva al Festival Internazionale del Fumetto, Animazione, Cinema e Games. Fiera di Roma, 5-8 ottobre 2023. Scadenza candidature 28 settembre 2023 ore 15.00<\/p>\n","protected":false},"author":15,"featured_media":10545,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[45,2,269],"tags":[434,71,450,448,209,77,72],"class_list":["post-10995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-finanziamenti","category-fiere-e-iniziative-internazionali","category-network","tag-cciaa-roma","tag-editoria","tag-educational-games","tag-fiera","tag-fumetto","tag-lazio-innova","tag-regione-lazio"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"Partecipazione collettiva al Festival Internazionale del Fumetto, Animazione, Cinema e Games. Fiera di Roma, 5-8 ottobre 2023. Scadenza candidature 28 settembre 2023 ore 15.00\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Partecipazione collettiva al Festival Internazionale del Fumetto, Animazione, Cinema e Games. Fiera di Roma, 5-8 ottobre 2023. Scadenza candidature 28 settembre 2023 ore 15.00\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-26T07:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T14:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simona Saldi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simona Saldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/\"},\"author\":{\"name\":\"Simona Saldi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/7cbe2b01abf9e66e3c12dd6c1af34b4a\"},\"headline\":\"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno\",\"datePublished\":\"2023-09-26T07:29:30+00:00\",\"dateModified\":\"2023-09-28T14:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/\"},\"wordCount\":1571,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/08\\\/Slider-romics.jpg\",\"keywords\":[\"CCIAA Roma\",\"Editoria\",\"Educational games\",\"fiera\",\"Fumetto\",\"Lazio Innova\",\"Regione Lazio\"],\"articleSection\":[\"Bandi e Finanziamenti\",\"Fiere e Iniziative Internazionali\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/\",\"name\":\"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/08\\\/Slider-romics.jpg\",\"datePublished\":\"2023-09-26T07:29:30+00:00\",\"dateModified\":\"2023-09-28T14:02:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/7cbe2b01abf9e66e3c12dd6c1af34b4a\"},\"description\":\"Partecipazione collettiva al Festival Internazionale del Fumetto, Animazione, Cinema e Games. Fiera di Roma, 5-8 ottobre 2023. Scadenza candidature 28 settembre 2023 ore 15.00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/08\\\/Slider-romics.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/08\\\/Slider-romics.jpg\",\"width\":1145,\"height\":630,\"caption\":\"Locandina Romics Autunno\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2023\\\/09\\\/26\\\/manifestazione-di-interesse-per-romics-edizione-autunno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/7cbe2b01abf9e66e3c12dd6c1af34b4a\",\"name\":\"Simona Saldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g\",\"caption\":\"Simona Saldi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/s-saldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno - Lazio International - Lazio Innova","description":"Partecipazione collettiva al Festival Internazionale del Fumetto, Animazione, Cinema e Games. Fiera di Roma, 5-8 ottobre 2023. Scadenza candidature 28 settembre 2023 ore 15.00","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/","og_locale":"it_IT","og_type":"article","og_title":"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno - Lazio International - Lazio Innova","og_description":"Partecipazione collettiva al Festival Internazionale del Fumetto, Animazione, Cinema e Games. Fiera di Roma, 5-8 ottobre 2023. Scadenza candidature 28 settembre 2023 ore 15.00","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2023-09-26T07:29:30+00:00","article_modified_time":"2023-09-28T14:02:52+00:00","og_image":[{"width":1145,"height":630,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics.jpg","type":"image\/jpeg"}],"author":"Simona Saldi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Simona Saldi","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/"},"author":{"name":"Simona Saldi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/7cbe2b01abf9e66e3c12dd6c1af34b4a"},"headline":"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno","datePublished":"2023-09-26T07:29:30+00:00","dateModified":"2023-09-28T14:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/"},"wordCount":1571,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics.jpg","keywords":["CCIAA Roma","Editoria","Educational games","fiera","Fumetto","Lazio Innova","Regione Lazio"],"articleSection":["Bandi e Finanziamenti","Fiere e Iniziative Internazionali","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/","name":"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics.jpg","datePublished":"2023-09-26T07:29:30+00:00","dateModified":"2023-09-28T14:02:52+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/7cbe2b01abf9e66e3c12dd6c1af34b4a"},"description":"Partecipazione collettiva al Festival Internazionale del Fumetto, Animazione, Cinema e Games. Fiera di Roma, 5-8 ottobre 2023. Scadenza candidature 28 settembre 2023 ore 15.00","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics.jpg","width":1145,"height":630,"caption":"Locandina Romics Autunno"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2023\/09\/26\/manifestazione-di-interesse-per-romics-edizione-autunno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Manifestazione di interesse per \u201cRomics\u201d Edizione Autunno"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/7cbe2b01abf9e66e3c12dd6c1af34b4a","name":"Simona Saldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g","caption":"Simona Saldi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/s-saldi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics-600x400.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/08\/Slider-romics-600x600.jpg","author_info":{"display_name":"Simona Saldi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/s-saldi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/10995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=10995"}],"version-history":[{"count":20,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/10995\/revisions"}],"predecessor-version":[{"id":11527,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/10995\/revisions\/11527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/10545"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=10995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=10995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=10995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}