{"id":12903,"date":"2024-01-22T11:19:32","date_gmt":"2024-01-22T10:19:32","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=12903"},"modified":"2024-01-30T14:27:40","modified_gmt":"2024-01-30T13:27:40","slug":"ice-agenzia-partecipazione-collettiva-a-satellite-2024","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/","title":{"rendered":"ICE Agenzia: partecipazione collettiva a &#8220;Satellite 2024&#8221;"},"content":{"rendered":"\n<p>ICE Agenzia per la promozione e l\u2019internazionalizzazione delle imprese italiane organizza una <strong>Partecipazione Collettiva<\/strong> di aziende italiane dell\u2019<strong>Aerospazio<\/strong> a \u201c<strong>Satellite 2024<\/strong>\u201d in programma a <strong>Washington, DC <\/strong>dal <strong>19 al 21 marzo 2024.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"perche-partecipare\"><br>Perch\u00e9 partecipare<\/h2>\n\n\n\n<p>Satellite 2024 rappresenta un\u2019ottima <strong>occasione per l\u2019industria aerospaziale italiana<\/strong> per proporsi nell\u2019interessante <strong>mercato statunitense <\/strong>e in particolare per prendere contatti con l\u2019ecosistema della <strong>East Coast.<\/strong> <br>L\u2019organizzazione della collettiva mira ad accrescere le occasioni di business per le aziende italiane partecipanti e nello stesso momento rafforzare l\u2019immagine della nostra tecnologia caratterizzata da elevati standard qualitativi e alto contenuto tecnologico e capace di soddisfare le esigenze di un comparto molto vivace ed in continua crescita. <br>L\u2019evento sar\u00e0 un\u2019ottima opportunit\u00e0 soprattutto per gli attori italiani nel <strong>sottosettore dei satelliti.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"offerta-ice-agenzia\"><br>Offerta ICE-Agenzia<\/h2>\n\n\n\n<p>ICE-Agenzia intende organizzare un padiglione ITALIA in open space. <br>La collettiva italiana sar\u00e0 allestita all\u2019interno uno <strong>Spazio Italia di circa 75 mq <\/strong>collocato all\u2019<strong>interno dell\u2019unica Hall espositiva <\/strong>presso il <strong>Walter E. Washington Convention Center <\/strong>a<strong> Washington.<\/strong><br>Per un <strong>importo di 1.000 EUR<\/strong>, sar\u00e0 offerta alle aziende una postazione, con tavolino e grafica aziendale.<br>Le <strong>postazioni disponibili, max 10<\/strong>, saranno assegnate seguendo l\u2019ordine di arrivo dei moduli di adesione.<br>Una volta completate le adesioni per lo spazio messo a disposizione della collettiva, le aziende intenzionate a partecipare saranno poste in lista di attesa e prese in considerazione qualora si registrassero rinunce.<br><br><strong>La postazione aziendale ad un costo di 1.000 EUR include:<\/strong><br>&#8211; affitto dell\u2019area espositiva;<br>&#8211; Postazione con tavolo, 2 sedie e grafica aziendale;<br>&#8211; allestimento di una rete wi-fi esclusiva per le aziende della collettiva;<br>&#8211; iscrizione al catalogo ufficiale della fiera, se disponibile e\/o catalogo digitale<br>&#8211; realizzazione della brochure delle aziende partecipanti alla collettiva;<br>&#8211; kit informativo sul mercato\/settore;<br>&#8211; promozione digitale e tradizionale della collettiva<br>Sar\u00e0 inoltre prevista lo Stand Istituzionale\/Centro Servizi ICE- Agenzia-ASI con un\u2019area comune attrezzata con collegamento internet, fax, telefono e stampante ed un Coffee Point.<br>Per promuovere la presenza italiana alla manifestazione, sono inoltre previste specifiche azioni di comunicazione nonch\u00e9 la realizzazione e distribuzione di un catalogo delle aziende partecipanti alla collettiva.<br><br><strong>Il piano di comunicazione prevede:<\/strong><br>\u2022 una landing page interattiva;<br>\u2022 una campagna promozionale via e-mail;<br>\u2022 una campagna social;<br>\u2022 una presenza pubblicitaria organica all\u2019interno dei canali istituzionali della Fiera;<br>\u2022 la pubblicazione di un catalogo informativo da distribuire ai visitatori.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"modalita-di-adesione\"><br>Modalit\u00e0 di adesione<\/h2>\n\n\n\n<p>Le domande di adesione saranno accolte dalle ore 10:00 del 22 gennaio alle 17.00 del 31 gennaio 2024.<\/p>\n\n\n\n<p>Istruzioni per l&#8217;adesione <strong><a href=\"https:\/\/www.ice.it\/it\/area-clienti\/eventi\/dettaglio-evento\/2023\/O1\/036\/modalita-adesione\" target=\"_blank\" rel=\"noreferrer noopener\">QUI<\/a><\/strong><\/p>\n\n\n\n<p><strong>Scarica la circolare ICE completa<\/strong>: <a href=\"https:\/\/www.ice.it\/it\/area-clienti\/eventi\/dettaglio-evento\/2023\/O1\/036\/allegati-generati\/pdf-completo\" target=\"_blank\" rel=\"noreferrer noopener\">pdf-completo (ice.it)<\/a><br><br><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adesioni dal 22 gennaio per partecipare con ICE Agenzia alla Fiera SATELLITE 2024. <\/p>\n","protected":false},"author":14,"featured_media":12904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[2,269],"tags":[32,161,519,404],"class_list":["post-12903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiere-e-iniziative-internazionali","category-network","tag-aerospazio","tag-ice-agenzia","tag-satelliti","tag-usa-2"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ICE Agenzia: partecipazione collettiva a &quot;Satellite 2024&quot; - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ICE Agenzia: partecipazione collettiva a &quot;Satellite 2024&quot; - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Adesioni dal 22 gennaio per partecipare con ICE Agenzia alla Fiera SATELLITE 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T10:19:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T13:27:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federica San\u00f2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federica San\u00f2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/\"},\"author\":{\"name\":\"Federica San\u00f2\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/5d1178a88b916d4e208c2f7f7880adb7\"},\"headline\":\"ICE Agenzia: partecipazione collettiva a &#8220;Satellite 2024&#8221;\",\"datePublished\":\"2024-01-22T10:19:32+00:00\",\"dateModified\":\"2024-01-30T13:27:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/\"},\"wordCount\":421,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/01\\\/pexels-spacex-23789-scaled.jpg\",\"keywords\":[\"Aerospazio\",\"ICE-Agenzia\",\"satelliti\",\"USA\"],\"articleSection\":[\"Fiere e Iniziative Internazionali\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/\",\"name\":\"ICE Agenzia: partecipazione collettiva a \\\"Satellite 2024\\\" - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/01\\\/pexels-spacex-23789-scaled.jpg\",\"datePublished\":\"2024-01-22T10:19:32+00:00\",\"dateModified\":\"2024-01-30T13:27:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/5d1178a88b916d4e208c2f7f7880adb7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/01\\\/pexels-spacex-23789-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/01\\\/pexels-spacex-23789-scaled.jpg\",\"width\":2560,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/01\\\/22\\\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ICE Agenzia: partecipazione collettiva a &#8220;Satellite 2024&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/5d1178a88b916d4e208c2f7f7880adb7\",\"name\":\"Federica San\u00f2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g\",\"caption\":\"Federica San\u00f2\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/f-sano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ICE Agenzia: partecipazione collettiva a \"Satellite 2024\" - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/","og_locale":"it_IT","og_type":"article","og_title":"ICE Agenzia: partecipazione collettiva a \"Satellite 2024\" - Lazio International - Lazio Innova","og_description":"Adesioni dal 22 gennaio per partecipare con ICE Agenzia alla Fiera SATELLITE 2024.","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2024-01-22T10:19:32+00:00","article_modified_time":"2024-01-30T13:27:40+00:00","og_image":[{"width":2560,"height":1700,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-scaled.jpg","type":"image\/jpeg"}],"author":"Federica San\u00f2","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Federica San\u00f2","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/"},"author":{"name":"Federica San\u00f2","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/5d1178a88b916d4e208c2f7f7880adb7"},"headline":"ICE Agenzia: partecipazione collettiva a &#8220;Satellite 2024&#8221;","datePublished":"2024-01-22T10:19:32+00:00","dateModified":"2024-01-30T13:27:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/"},"wordCount":421,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-scaled.jpg","keywords":["Aerospazio","ICE-Agenzia","satelliti","USA"],"articleSection":["Fiere e Iniziative Internazionali","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/","name":"ICE Agenzia: partecipazione collettiva a \"Satellite 2024\" - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-scaled.jpg","datePublished":"2024-01-22T10:19:32+00:00","dateModified":"2024-01-30T13:27:40+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/5d1178a88b916d4e208c2f7f7880adb7"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-scaled.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-scaled.jpg","width":2560,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/01\/22\/ice-agenzia-partecipazione-collettiva-a-satellite-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"ICE Agenzia: partecipazione collettiva a &#8220;Satellite 2024&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/5d1178a88b916d4e208c2f7f7880adb7","name":"Federica San\u00f2","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g","caption":"Federica San\u00f2"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/f-sano\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-600x400.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/01\/pexels-spacex-23789-600x600.jpg","author_info":{"display_name":"Federica San\u00f2","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/f-sano\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/12903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=12903"}],"version-history":[{"count":5,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/12903\/revisions"}],"predecessor-version":[{"id":13042,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/12903\/revisions\/13042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/12904"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=12903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=12903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=12903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}