{"id":15294,"date":"2024-09-03T11:19:27","date_gmt":"2024-09-03T09:19:27","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=15294"},"modified":"2024-09-03T11:19:27","modified_gmt":"2024-09-03T09:19:27","slug":"partecipazione-collettiva-aeromart-toulose-2024","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/","title":{"rendered":"Partecipazione Collettiva &#8211; Aeromart Toulose 2024"},"content":{"rendered":"\n<p>L\u2019ICE-Agenzia per la promozione all\u2019estero e l\u2019internazionalizzazione delle imprese italiane organizza una partecipazione collettiva italiana alla fiera <strong>Aeromart Toulouse, che si terr\u00e0 dal 3 al 5 dicembre 2024 presso il nuovo centro Congressi MEET di Tolos<\/strong>a, capitale dell\u2019industria aerospaziale europea.<\/p>\n\n\n\n<p><br><strong>Perch\u00e9 partecipare<\/strong><\/p>\n\n\n\n<p>Aeromart Toulouse riunisce, ogni due anni, i responsabili degli acquisti dei grandi costruttori mondiali di velivoli (Boeing, Bombardier, Dassault, ecc.) e di attrezzature e sistemi (Leonardo, Eaton, GE, ecc.), insieme ai fornitori pi\u00f9 qualificati e innovativi dell\u2019industria aerospaziale. <br>Grazie a una piattaforma interattiva per l\u2019organizzazione di incontri B2B, Aeromart Toulouse permette di incontrare i grandi buyers del settore, con un\u2019agenda personalizzata secondo gli interessi delle parti. <br><strong>Gli incontri B2B si terranno il 4 e 5 dicembre 2024.<\/strong><\/p>\n\n\n\n<p>Adesioni a partire dal 4 settembre.<br>Per maggiori informazioni <strong><a href=\"https:\/\/www.ice.it\/it\/area-clienti\/eventi\/dettaglio-evento\/2023\/C1\/049?elqTrackId=24e4dd0e3d98448781b42f60171fb13c&amp;elq=07e8882340b44a60b2e76e4dd8aad54a&amp;elqaid=13765&amp;elqat=1&amp;elqCampaignId=10001&amp;elqak=8AF5B36163BB5C59EE79066B6C8FFD2E15B96A807B3733A245EE0A5C8241E473CC4E\">clicca qui<\/a><\/strong><br><br><br><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adesioni dal prossimo 4 settembre.<\/p>\n","protected":false},"author":11,"featured_media":15307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[2,269],"tags":[657,32,516],"class_list":["post-15294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiere-e-iniziative-internazionali","category-network","tag-aeromart","tag-aerospazio","tag-ice-agenzia-2"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Partecipazione Collettiva - Aeromart Toulose 2024 - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partecipazione Collettiva - Aeromart Toulose 2024 - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Adesioni dal prossimo 4 settembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-03T09:19:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24.png\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Patrizia De Vincenzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrizia De Vincenzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/\"},\"author\":{\"name\":\"Patrizia De Vincenzi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"headline\":\"Partecipazione Collettiva &#8211; Aeromart Toulose 2024\",\"datePublished\":\"2024-09-03T09:19:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/\"},\"wordCount\":137,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/09\\\/AeromartT24.png\",\"keywords\":[\"Aeromart\",\"Aerospazio\",\"ICE Agenzia\"],\"articleSection\":[\"Fiere e Iniziative Internazionali\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/\",\"name\":\"Partecipazione Collettiva - Aeromart Toulose 2024 - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/09\\\/AeromartT24.png\",\"datePublished\":\"2024-09-03T09:19:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/09\\\/AeromartT24.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/09\\\/AeromartT24.png\",\"width\":777,\"height\":437,\"caption\":\"Logo aeromart Toulouse 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/09\\\/03\\\/partecipazione-collettiva-aeromart-toulose-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partecipazione Collettiva &#8211; Aeromart Toulose 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\",\"name\":\"Patrizia De Vincenzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"caption\":\"Patrizia De Vincenzi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/p-devincenzi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partecipazione Collettiva - Aeromart Toulose 2024 - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Partecipazione Collettiva - Aeromart Toulose 2024 - Lazio International - Lazio Innova","og_description":"Adesioni dal prossimo 4 settembre.","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2024-09-03T09:19:27+00:00","og_image":[{"width":777,"height":437,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24.png","type":"image\/png"}],"author":"Patrizia De Vincenzi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Patrizia De Vincenzi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/"},"author":{"name":"Patrizia De Vincenzi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"headline":"Partecipazione Collettiva &#8211; Aeromart Toulose 2024","datePublished":"2024-09-03T09:19:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/"},"wordCount":137,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24.png","keywords":["Aeromart","Aerospazio","ICE Agenzia"],"articleSection":["Fiere e Iniziative Internazionali","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/","name":"Partecipazione Collettiva - Aeromart Toulose 2024 - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24.png","datePublished":"2024-09-03T09:19:27+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24.png","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24.png","width":777,"height":437,"caption":"Logo aeromart Toulouse 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/09\/03\/partecipazione-collettiva-aeromart-toulose-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Partecipazione Collettiva &#8211; Aeromart Toulose 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758","name":"Patrizia De Vincenzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","caption":"Patrizia De Vincenzi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24-600x400.png","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/09\/AeromartT24-600x437.png","author_info":{"display_name":"Patrizia De Vincenzi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/15294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=15294"}],"version-history":[{"count":6,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/15294\/revisions"}],"predecessor-version":[{"id":15308,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/15294\/revisions\/15308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/15307"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=15294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=15294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=15294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}