{"id":16809,"date":"2024-11-14T09:23:28","date_gmt":"2024-11-14T08:23:28","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=16809"},"modified":"2024-11-25T11:06:08","modified_gmt":"2024-11-25T10:06:08","slug":"manifestazione-di-interesse-per-nse","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/","title":{"rendered":"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"256\" src=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/07\/Blocchetto-loghi-fiere-in-convenzione-2024_def2-scaled.jpg\" alt=\"\" class=\"wp-image-15018\" srcset=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/07\/Blocchetto-loghi-fiere-in-convenzione-2024_def2-scaled.jpg 2560w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/07\/Blocchetto-loghi-fiere-in-convenzione-2024_def2-300x30.jpg 300w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/07\/Blocchetto-loghi-fiere-in-convenzione-2024_def2-1024x102.jpg 1024w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/07\/Blocchetto-loghi-fiere-in-convenzione-2024_def2-768x77.jpg 768w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/07\/Blocchetto-loghi-fiere-in-convenzione-2024_def2-1536x154.jpg 1536w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/07\/Blocchetto-loghi-fiere-in-convenzione-2024_def2-2048x205.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>La <strong>Regione Lazio<\/strong>, attraverso il soggetto attuatore&nbsp;<strong>Lazio Innova<\/strong>, e la <strong>Camera di Commercio di Roma, <\/strong>per il tramite del soggetto attuatore <strong>Azienda Speciale Sviluppo e Territorio<\/strong>, nell\u2019ambito della Convenzione per la partecipazione congiunta a manifestazioni fieristiche <strong>selezionano 27 PMI<\/strong> del Lazio per la partecipazione a <strong>NSE \u2013 New Space Economy European Expoforum 2024, <\/strong>in programma presso la <strong>Fiera di Roma dal 16 al 18 dicembre 2024<\/strong>.<\/p>\n\n\n\n<p>Nell\u2019ambito della manifestazione gli Enti promotori intendono organizzare uno spazio espositivo per ospitare fino ad un massimo di <strong>27<\/strong> <strong>imprese e startup del Lazio,<\/strong> operative nel settore dell\u2019Aerospazio e dell\u2019Economia dello Spazio. <\/p>\n\n\n\n<p>La partecipazione di <strong>22 <\/strong>imprese \u00e8 sostenuta con il contributo del <strong>PR FESR Lazio 2021-2027<\/strong>, mentre quella delle restanti 5 si avvale delle risorse della Camera di Commercio di Roma.<\/p>\n\n\n\n<p>Nelle more del completamento dell\u2019iter amministrativo di approvazione dell\u2019intervento, il presente Avviso per manifestazione di interesse si intende NON VINCOLANTE per la Regione Lazio e per gli altri Enti promotori, che si riservano, in qualsiasi momento, di poter annullare, qualora le circostanze lo richiedessero, l\u2019organizzazione della collettiva regionale alla Fiera in oggetto e\/o di modificarne le caratteristiche e i servizi offerti.&nbsp;<\/p>\n\n\n\n<p>L\u2019appuntamento internazionale \u00e8 organizzato da <strong>Fiera Roma<\/strong> in collaborazione con <strong>ASI \u2013 Agenzia Spaziale Italiana<\/strong> e con il patrocinio del <strong>Ministero per le Imprese e il Made in Italy<\/strong>. <strong>NSE<\/strong> \u2013 <strong>New Space Economy European Expoforum<\/strong> si presenta come l&#8217;appuntamento annuale italiano e internazionale per promuovere e sviluppare la nuova Economia dello Spazio e ha il duplice scopo di:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>far conoscere anche al grande pubblico le potenzialit\u00e0 delle tecnologie e delle applicazioni spaziali;<\/li>\n\n\n\n<li>far incontrare enti ed aziende, del settore, grandi attori internazionali, PMI innovative, start up, investitori, centri di ricerca e mondo accademico, agenzie spaziali, istituzioni e organizzazioni internazionali.<\/li>\n<\/ol>\n\n\n\n<p><strong><em>\u201cOur Future, Our Daily Life\u201d<\/em><\/strong> \u00e8 il tema principale della VI^ Edizione di NSE che si svilupper\u00e0 in tre giornate nel corso delle quali istituzioni, esperti e professionisti si confronteranno sui temi principali connessi alla New Space Economy, per approfondire gli scenari presenti e futuri dei settori industriali coinvolti e offrire occasioni di scambio tra stakeholder industriali consolidati e realt\u00e0 emergenti, PMI innovative, investitori, venture capital, startup, universit\u00e0 e centri di ricerca, agenzie spaziali e istituzioni impegnate nel settore Spazio, a livello internazionale e nazionale.<\/p>\n\n\n\n<p>La manifestazione si articoler\u00e0 in:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>AREA MAIN STAGE,<\/strong> dove per tre giorni si alterneranno i panel di una conferenza che vedr\u00e0 la partecipazione di speaker nazionali e internazionali di grande rilievo.<\/li>\n<\/ul>\n\n\n\n<p>NSE 2024 si rivolge a un pubblico di visitatori e partecipanti composto da<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>LSI\/PMI\/Startups<\/li>\n\n\n\n<li>Accelerators \/ Incubators \/ Business Angels<\/li>\n\n\n\n<li>Academia \/ Research and Development Institutions<\/li>\n\n\n\n<li>Technological Clusters and Science Parks<\/li>\n\n\n\n<li>Investors \/ Venture Capital Funds<\/li>\n\n\n\n<li>Governments \/ Local Authorities<\/li>\n\n\n\n<li>Associations \/ Foundations<\/li>\n<\/ul>\n\n\n\n<p>Il Progetto regionale intende selezionare PMI e Startup che svolgono la propria attivit\u00e0 almeno in uno dei seguenti ambiti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Advanced manufacturing<\/li>\n\n\n\n<li>Aerospace systems associations and no profit<\/li>\n\n\n\n<li>Artificial intelligence, machine learning, internet of things<\/li>\n\n\n\n<li>Business services<\/li>\n\n\n\n<li>Climate solutions<\/li>\n\n\n\n<li>Space Communication<\/li>\n\n\n\n<li>Satellite Navigation Applications<\/li>\n\n\n\n<li>Consulting services<\/li>\n\n\n\n<li>Cybersecurity and Robotics<\/li>\n\n\n\n<li>Space Education and Training, special courses<\/li>\n\n\n\n<li>Environment government<\/li>\n\n\n\n<li>Earth observation, precision agriculture and monitoring<\/li>\n\n\n\n<li>Human systems integration<\/li>\n\n\n\n<li>EEE components (electrical, electronic, electromechanical) applicable in the Space field<\/li>\n\n\n\n<li>IT\/software engineering<\/li>\n\n\n\n<li>Engineering and fast prototyping in the Space field<\/li>\n\n\n\n<li>Research and development in the Space field<\/li>\n\n\n\n<li>Satellite systems<\/li>\n\n\n\n<li>Advanced Technologies (e.g. propulsion, materials and additive manufacturing, AOCS \u2013 attitude and orbit control system, etc.)<\/li>\n\n\n\n<li>Technologies for Optical Systems and SAR<\/li>\n\n\n\n<li>Smart city services and monitoring<\/li>\n\n\n\n<li>Space service providers<\/li>\n\n\n\n<li>Spaceports and spaceport service providers<\/li>\n<\/ul>\n\n\n\n<p><br><strong>SPAZIO ESPOSITIVO<\/strong><\/p>\n\n\n\n<p>Ciascuna azienda ammessa avr\u00e0 a disposizione uno stand di 12 mq con la seguente dotazione:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&nbsp;pannelli di fondo, parete laterale, ripostiglio, moquette ignifuga a terra<\/li>\n\n\n\n<li>1 desk graficizzato<\/li>\n\n\n\n<li>1 sgabello, 1 tavolo, 2 sedie<\/li>\n\n\n\n<li>1 cestino, appendiabiti<\/li>\n\n\n\n<li>1 pannello graficizzato mq. 2<\/li>\n\n\n\n<li>impianto elettrico con 1 multiprese<\/li>\n\n\n\n<li>pulizia stand nei tre giorni di evento<\/li>\n\n\n\n<li>quota di iscrizione, comprensiva di installazione della potenza elettrica fino a 2kw\/220<\/li>\n\n\n\n<li>assicurazione R.C.T \u2013 R.C.O. e INCENDIO (quota base)<\/li>\n\n\n\n<li>inserimento nel Catalogo Ufficiale di Manifestazione<\/li>\n\n\n\n<li>3 tessere Exhibitor<\/li>\n\n\n\n<li>2 Conference Pass<\/li>\n\n\n\n<li>1 pass auto all\u2019interno del Quartiere Fieristico.<\/li>\n<\/ul>\n\n\n\n<p>La manifestazione si doter\u00e0 di una piattaforma on-line che avr\u00e0 la funzione di coordinamento delle agende B2B con stakeholder impossibilitati a partecipare in presenza.<\/p>\n\n\n\n<p>Alla manifestazione sar\u00e0 presente la <strong>Rete Enterprise Europe Network &#8211; EEN<\/strong>, la piattaforma di brokeraggio europea gestita e coordinata dalla rete europea operativa anche attraverso gli <strong>sportelli EEN<\/strong> di <strong>Lazio Innova<\/strong> e <strong>Sviluppo e Territorio<\/strong>. <br>Maggiori informazioni saranno fornite nel prosieguo delle attivit\u00e0 alle imprese ammesse a partecipare.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Gli Enti promotori, Lazio Innova e Sviluppo e Territorio daranno opportuna diffusione sui rispettivi siti istituzionali e su tutti i canali di comunicazione utilizzati per promuovere le iniziative.<\/p>\n\n\n\n<p><br><strong>REQUISITI GENERALI DI AMMISSIBILIT\u00c0 PER LE IMPRESE INVITATE A PARTECIPARE:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sede legale e\/o operativa nella Regione Lazio;<\/li>\n\n\n\n<li>coerenza dell\u2019attivit\u00e0 dell\u2019azienda con il settore o i settori economici cui la manifestazione \u00e8 rivolta;<\/li>\n\n\n\n<li>essere MPMI, come classificate nell&#8217;Allegato I del Regolamento (UE) n. 651\/2014, in forma singola o associata in Consorzi, Societ\u00e0 Consortili o Reti di imprese con personalit\u00e0 giuridica (Reti-soggetto), definite ai sensi dei commi 4-ter e 4-quater dell&#8217;art. 3 del Decreto-legge n. 5 del 10 febbraio 2009, convertito, con modificazioni, nella Legge n. 33 del 09 Aprile 2009 e ss.mm.ii., al momento della presentazione della manifestazione di interesse;<\/li>\n\n\n\n<li>essere regolarmente iscritte nel Registro delle Imprese della C.C.I.A.A. competente per territorio ed essere in regola, al momento della presentazione della manifestazione di interesse o comunque entro i termini di chiusura di presentazione della stessa, con il pagamento del diritto annuale e con la dichiarazione dell\u2019attivit\u00e0 esercitata;<\/li>\n\n\n\n<li>esercitare, in relazione alla sede laziale, un\u2019attivit\u00e0 economica coerente con il settore;<\/li>\n\n\n\n<li>non essere beneficiarie di agevolazioni pubbliche relative alla partecipazione alla manifestazione fieristica in questione n\u00e9 aver presentato domande di agevolazione per partecipare alla medesima manifestazione;<\/li>\n\n\n\n<li>non aver superato, negli ultimi tre anni, l\u2019importo massimo di \u20ac 300.000,00 delle agevolazioni in regime \u201cde minimis\u201d ai sensi del Regolamento (UE) n. 2831 del 13 dicembre 2023 relativo all\u2019applicazione degli articoli 107 e 108 del trattato sul funzionamento dell\u2019Unione Europea agli aiuti \u201cde minimis\u201d, e, in ogni caso, di disporre di un margine sufficiente alla concessione dell\u2019aiuto indiretto relativo alla presente manifestazione come evidenziato nel seguente paragrafo \u201cAiuto de minimis\u201d;<\/li>\n\n\n\n<li>essere nel pieno e libero esercizio dei propri diritti, attive e non essere sottoposte n\u00e9 essere state sottoposte, nei cinque anni precedenti, a procedure di liquidazione volontaria, liquidazione coatta, fallimento, concordato preventivo (ad eccezione del concordato preventivo con continuit\u00e0 aziendale) ed ogni altra procedura concorsuale n\u00e9 abbiano in corso un procedimento per la dichiarazione di una delle suddette situazioni;<\/li>\n\n\n\n<li>possedere capacit\u00e0 di contrarre ovvero non essere state oggetto di sanzione interdittiva o altra sanzione che comporti il divieto di contrarre con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>non avere Amministratori e\/o Legali Rappresentanti che siano stati condannati con sentenza passata in giudicato ovvero nei cui confronti sia stato emesso decreto penale di condanna divenuto irrevocabile o sentenza di applicazione della pena su richiesta, ai sensi dell\u2019art. 444 c.p.p., per reati gravi in danno dello Stato o della Comunit\u00e0 che incidono sulla moralit\u00e0 professionale (\u00e8 comunque causa di esclusione la condanna, con sentenza passata in giudicato, per reati di partecipazione ad un&#8217;organizzazione criminale, corruzione, frode, riciclaggio);<\/li>\n\n\n\n<li>non avere Amministratori e\/o Legali Rappresentanti che si siano resi colpevoli di false dichiarazioni nei rapporti con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>essere in regola con il versamento dei contributi previdenziali e assistenziali, accertabile mediante acquisizione del DURC, <br>ovvero<\/li>\n\n\n\n<li>non essere soggetti agli obblighi in materia di regolarit\u00e0 contributiva e, quindi, non essere tenuti all\u2019iscrizione presso alcun Ente previdenziale o assistenziale.<\/li>\n<\/ul>\n\n\n\n<p>Il possesso dei requisiti \u00e8 attestato mediante dichiarazioni rese al momento della partecipazione attraverso il modulo di manifestazione di interesse.&nbsp;<\/p>\n\n\n\n<p><em>Tali dichiarazioni possono essere verificate cos\u00ec come stabilito dall\u2019art. 71 comma 1 del D.P.R. 445 del 28.12.2000, come modificato dall\u2019art. 264 del D.L. 19 maggio 2020 n. 34, con applicazione, nel caso di dichiarazioni mendaci, della decadenza dai benefici e delle sanzioni penali, rispettivamente previste dagli artt. 75 e 76 del medesimo D.P.R., come da ultimo rese pi\u00f9 severe per effetto del citato articolo 264.&nbsp;<\/em><\/p>\n\n\n\n<p><br><strong>MODALIT\u00c0 DI PRESENTAZIONE DELLA DOMANDA DI PARTECIPAZIONE<\/strong><\/p>\n\n\n\n<p><strong>ISCRIZIONI CHIUSE<\/strong><\/p>\n\n\n\n<p><br><strong>CRITERI DI AMMISSIBILIT\u00c0 GENERALI<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>correttezza dell&#8217;iter amministrativo di presentazione della manifestazione di interesse (rispetto delle modalit\u00e0 e dei tempi);<\/li>\n\n\n\n<li>completezza della domanda di partecipazione.<\/li>\n<\/ul>\n\n\n\n<p><br><strong>CRITERI DI SELEZIONE E COMUNICAZIONE DI AMMISSIONE<\/strong><\/p>\n\n\n\n<p>Fermo il possesso dei requisiti indicati, saranno oggetto di selezione le prime 27 PMI che risulteranno aver ottenuto il maggiore punteggio in ragione della valutazione svolta secondo i seguenti criteri:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Contenuto innovativo del prodotto o servizio (max 35 punti);<\/li>\n\n\n\n<li>Prodotto o servizio b2b o, se b2c, con interesse a partnership industriali e\/o finanziarie (max 30 punti);<\/li>\n\n\n\n<li>Prodotto o servizio pronto per il mercato, con interesse a sviluppo internazionale (max 35 punti).<\/li>\n<\/ol>\n\n\n\n<p><br><strong>SELEZIONE<\/strong><\/p>\n\n\n\n<p>La selezione avverr\u00e0 a cura di un <strong>Nucleo di Valutazione <\/strong>composto da:<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"1\">\n<li>un rappresentante di Regione Lazio;<\/li>\n\n\n\n<li>un rappresentante di Lazio Innova;<\/li>\n\n\n\n<li>un rappresentante del Sistema Camerale di Roma;<\/li>\n\n\n\n<li>un esperto di ambito.<\/li>\n<\/ol>\n\n\n\n<p><br><strong>COMUNICAZIONE DI AMMISSIONE&nbsp;<\/strong><\/p>\n\n\n\n<p>A seguito dello svolgimento del processo di selezione:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>tutti i soggetti che hanno sottoposto la candidatura riceveranno una comunicazione via PEC all\u2019indirizzo PEC indicato in sede di presentazione della manifestazione di interesse circa l\u2019ammissione o meno all\u2019iniziativa in oggetto;<\/li>\n\n\n\n<li>i soggetti ammessi dovranno, entro il termine indicato nella suddetta comunicazione, provvedere a comunicare via e-mail la loro adesione definitiva ovvero la loro rinuncia. Il mancato rispetto dei termini per l\u2019accettazione della proposta di partecipazione comporter\u00e0 l\u2019esclusione dell\u2019azienda. A seguito dell\u2019accettazione, l\u2019azienda sar\u00e0 tenuta a partecipare all\u2019iniziativa;<\/li>\n\n\n\n<li>si precisa che, accettando la partecipazione, l\u2019azienda si impegna a presidiare lo stand in modo esclusivo (lo stesso soggetto non potr\u00e0 presidiare pi\u00f9 di uno stand) e continuativo (per l\u2019intera durata della manifestazione);<\/li>\n\n\n\n<li>in caso di rinuncia di uno o pi\u00f9 dei soggetti ammessi, si proceder\u00e0 a selezionare gli ulteriori soggetti risultati idonei, nel rispetto della graduatoria redatta dal Nucleo di Valutazione.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><br><strong>CONDIZIONI DI ESCLUSIONE&nbsp;<\/strong><\/p>\n\n\n\n<p>Sono escluse dalla partecipazione le imprese gi\u00e0 presenti alla manifestazione con un proprio stand e le imprese morose nei confronti degli organizzatori per somme relative a precedenti manifestazioni, ovvero morose nei confronti di altri organismi in collaborazione con i quali gli organizzatori promuovono le iniziative.<\/p>\n\n\n\n<p>Le seguenti fattispecie potranno costituire causa di esclusione, ad insindacabile giudizio del Nucleo di Valutazione, alle future iniziative organizzate da Regione Lazio e Camera di Commercio di Roma nell\u2019ambito della Convenzione:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>mancata partecipazione;<\/li>\n\n\n\n<li>mancato presidio dello stand per l\u2019intero periodo della manifestazione;<\/li>\n\n\n\n<li>accorpamento di due o pi\u00f9 stand tramite arbitraria rimozione delle pareti divisorie dei medesimi da parte di una o pi\u00f9 imprese;<\/li>\n\n\n\n<li>partecipazione di due o pi\u00f9 imprese che, pur avendo diversa partita IVA e codice fiscale, si avvalgono per il presidio dello stand della medesima persona fisica.<\/li>\n<\/ul>\n\n\n\n<p><br><strong>REGIME DI AIUTO&nbsp;<\/strong><\/p>\n\n\n\n<p>Considerata la volont\u00e0 degli Enti Promotori di venire incontro alle esigenze delle imprese selezionate, la partecipazione alla manifestazione \u00e8 gratuita, fermo restando che rimangono a carico delle stesse le spese relative ad ogni ulteriore servizio extra di personalizzazione richiesto dalle imprese medesime.<\/p>\n\n\n\n<p>I costi di partecipazione sono sostenuti dagli Enti promotori e tale sostegno alle imprese si configura quale aiuto indiretto, per la partecipazione alle iniziative e manifestazioni promosse dalla Regione Lazio e sar\u00e0 concesso nel rispetto delle disposizioni di cui al Regolamento (UE) n. 2831 del 13 dicembre 2023 relativo all\u2019applicazione degli articoli 107 e 108 del trattato sul funzionamento dell\u2019Unione Europea agli aiuti \u201cde minimis\u201d.<\/p>\n\n\n\n<p>A seguito dell\u2019obbligo di consultazione preventiva e di implementazione del Registro Nazionale degli Aiuti di Stato, di cui al Regolamento MISE n. 115 del 31 maggio 2017, gli importi relativi alle agevolazioni concesse verranno conseguentemente inseriti nel suddetto Registro, fino ad un importo massimo di \u20ac 6.000,00&nbsp;(euro seimila\/00) I.V.A. inclusa, per ogni impresa ammessa. Come previsto dall\u2019art. 3 par. 7 dello stesso Regolamento, qualora la concessione di nuovi aiuti \u201cde minimis\u201d comporti il superamento dei massimali previsti, nessuna delle nuove misure di aiuto pu\u00f2 beneficiare del Regolamento. L\u2019importo massimo delle agevolazioni in regime \u201cde minimis\u201d che possono essere concesse ad un\u2019unica impresa nell\u2019arco di tre anni, senza la preventiva notifica ed autorizzazione da parte della Commissione Europea e senza che ci\u00f2 possa incidere sugli scambi tra gli Stati membri e da non falsare o minacciare di falsare la concorrenza, \u00e8 pari a \u20ac 300.000,00.&nbsp;<\/p>\n\n\n\n<p><br>In caso di superamento delle soglie predette, l\u2019agevolazione suindicata non potr\u00e0 essere concessa, neppure per la parte che non superi detti massimali.<\/p>\n\n\n\n<p>&nbsp;<br>Si fa presente che ciascuna impresa pu\u00f2 monitorare l\u2019importo delle agevolazioni in regime \u201cde minimis\u201d di cui ha beneficiato a far data dal 12 agosto 2017, sul sito del Registro Nazionale degli Aiuti di Stato nella sezione Trasparenza al Link: <a href=\"https:\/\/www.rna.gov.it\/RegistroNazionaleTrasparenza\/faces\/pages\/TrasparenzaAiuto.jspx\">https:\/\/www.rna.gov.it\/RegistroNazionaleTrasparenza\/faces\/pages\/TrasparenzaAiuto.jspx<\/a><\/p>\n\n\n\n<p><strong>PRIVACY<\/strong><\/p>\n\n\n\n<p>I dati forniti saranno trattati dagli organizzatori in osservanza di quanto disposto dal Regolamento UE 679\/2016 sulla protezione dei dati personali.<\/p>\n\n\n\n<p>Per informazioni rivolgersi a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Regione Lazio<br>Lazio Innova S.p.A. \u2013 Area Internazionalizzazione &amp; Cluster<em><br><\/em>e-mail:&nbsp;<a href=\"mailto:internazionalizzazione@lazioinnova.it\">internazionalizzazione@lazioinnova.it<\/a>&nbsp;<br>Tel. 06.60.51.60<\/li>\n\n\n\n<li>Camera di Commercio di Roma <br>Area III Promozione e Sviluppo \u2013 Servizio Filiere produttive e Fiere: <br>e-mail:<a href=\"mailto:attivita.promozionali@rm.camcom.it\">&nbsp;attivita.promozionali@rm.camcom.it<\/a>&nbsp;<br>Tel. 06.52082571 \u2013 2065<\/li>\n\n\n\n<li>Sviluppo e Territorio <br>Azienda Speciale della Camera di Commercio di Roma per lo sviluppo e la crescita di Roma e del Lazio: <br>e-mail <a href=\"mailto:sviluppo@sviluppoeterritorio.camcom.it\">sviluppo@sviluppoeterritorio.camcom.it<\/a> <br>Tel. 06.6787758 &#8211; 06.69797165<\/li>\n<\/ul>\n\n\n\n<p>Tutta la modulistica \u00e8 consultabile e scaricabile sui seguenti siti Istituzionali:<\/p>\n\n\n\n<p><a href=\"http:\/\/www.lazioinnova.it\/laziointernational\">www.lazioinnova.it\/laziointernational<\/a>&nbsp;<br><a href=\"https:\/\/www.lazioeuropa.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.lazioeuropa.it&nbsp;<\/a>  <br><a href=\"http:\/\/www.rm.camcom.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.rm.camcom.it<\/a>     <br><a href=\"https:\/\/sviluppoeterritorio.camcom.it\" target=\"_blank\" rel=\"noreferrer noopener\">www.sviluppoeterritorio.camcom.it<\/a>   <br><br><br><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selezione di 27 PMI per la collettiva regionale a NSE &#8211; New Space Economy Expoforum &#8211; Fiera di Roma, 16 &#8211; 18 dicembre 2024 &#8211; Le iscrizioni si sono chiuse alle ore 11.00 del 25 novembre.<\/p>\n","protected":false},"author":16,"featured_media":16829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[45,63,2,269],"tags":[752,32,756,434,755,753,77,396,72,757,519,758,754],"class_list":["post-16809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-finanziamenti","category-community-degli-innovatori","category-fiere-e-iniziative-internazionali","category-network","tag-advancedtechnologies","tag-aerospazio","tag-business","tag-cciaa-roma","tag-engineering","tag-it","tag-lazio-innova","tag-pr-fesr-lazio-2021-2027","tag-regione-lazio","tag-satellitesystems","tag-satelliti","tag-smartcities","tag-software"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"Selezione di 27 PMI per la collettiva regionale a NSE - New Space Economy Expoforum - Fiera di Roma, 16 - 18 dicembre 2024 - Candidature entro il 25 novembre ore 11.00\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Selezione di 27 PMI per la collettiva regionale a NSE - New Space Economy Expoforum - Fiera di Roma, 16 - 18 dicembre 2024 - Candidature entro il 25 novembre ore 11.00\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-14T08:23:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T10:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"778\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Annalisa Luciani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Annalisa Luciani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/\"},\"author\":{\"name\":\"Annalisa Luciani\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/c5f8e5fdd81b5aa88e6ef3a7b6417f48\"},\"headline\":\"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum\",\"datePublished\":\"2024-11-14T08:23:28+00:00\",\"dateModified\":\"2024-11-25T10:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/\"},\"wordCount\":2233,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/11\\\/NSE3.png\",\"keywords\":[\"advancedtechnologies\",\"Aerospazio\",\"business\",\"CCIAA Roma\",\"engineering\",\"IT\",\"Lazio Innova\",\"PR FESR Lazio 2021-2027\",\"Regione Lazio\",\"satellitesystems\",\"satelliti\",\"smartcities\",\"software\"],\"articleSection\":[\"Bandi e Finanziamenti\",\"Community degli Innovatori\",\"Fiere e Iniziative Internazionali\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/\",\"name\":\"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/11\\\/NSE3.png\",\"datePublished\":\"2024-11-14T08:23:28+00:00\",\"dateModified\":\"2024-11-25T10:06:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/c5f8e5fdd81b5aa88e6ef3a7b6417f48\"},\"description\":\"Selezione di 27 PMI per la collettiva regionale a NSE - New Space Economy Expoforum - Fiera di Roma, 16 - 18 dicembre 2024 - Candidature entro il 25 novembre ore 11.00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/11\\\/NSE3.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2024\\\/11\\\/NSE3.png\",\"width\":778,\"height\":437,\"caption\":\"Locandina New Space Economy Europe Expoforum, Info nella pagina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2024\\\/11\\\/14\\\/manifestazione-di-interesse-per-nse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/c5f8e5fdd81b5aa88e6ef3a7b6417f48\",\"name\":\"Annalisa Luciani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc39a78ea0fbe90db9255aaf51e0092473ac165fca0a7952be5be798cb2449c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc39a78ea0fbe90db9255aaf51e0092473ac165fca0a7952be5be798cb2449c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc39a78ea0fbe90db9255aaf51e0092473ac165fca0a7952be5be798cb2449c5?s=96&d=mm&r=g\",\"caption\":\"Annalisa Luciani\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/a-luciani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum - Lazio International - Lazio Innova","description":"Selezione di 27 PMI per la collettiva regionale a NSE - New Space Economy Expoforum - Fiera di Roma, 16 - 18 dicembre 2024 - Candidature entro il 25 novembre ore 11.00","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/","og_locale":"it_IT","og_type":"article","og_title":"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum - Lazio International - Lazio Innova","og_description":"Selezione di 27 PMI per la collettiva regionale a NSE - New Space Economy Expoforum - Fiera di Roma, 16 - 18 dicembre 2024 - Candidature entro il 25 novembre ore 11.00","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2024-11-14T08:23:28+00:00","article_modified_time":"2024-11-25T10:06:08+00:00","og_image":[{"width":778,"height":437,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3.png","type":"image\/png"}],"author":"Annalisa Luciani","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Annalisa Luciani","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/"},"author":{"name":"Annalisa Luciani","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/c5f8e5fdd81b5aa88e6ef3a7b6417f48"},"headline":"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum","datePublished":"2024-11-14T08:23:28+00:00","dateModified":"2024-11-25T10:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/"},"wordCount":2233,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3.png","keywords":["advancedtechnologies","Aerospazio","business","CCIAA Roma","engineering","IT","Lazio Innova","PR FESR Lazio 2021-2027","Regione Lazio","satellitesystems","satelliti","smartcities","software"],"articleSection":["Bandi e Finanziamenti","Community degli Innovatori","Fiere e Iniziative Internazionali","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/","name":"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3.png","datePublished":"2024-11-14T08:23:28+00:00","dateModified":"2024-11-25T10:06:08+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/c5f8e5fdd81b5aa88e6ef3a7b6417f48"},"description":"Selezione di 27 PMI per la collettiva regionale a NSE - New Space Economy Expoforum - Fiera di Roma, 16 - 18 dicembre 2024 - Candidature entro il 25 novembre ore 11.00","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3.png","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3.png","width":778,"height":437,"caption":"Locandina New Space Economy Europe Expoforum, Info nella pagina"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2024\/11\/14\/manifestazione-di-interesse-per-nse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Manifestazione di interesse per NSE \u2013 New Space Economy European Expoforum"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/c5f8e5fdd81b5aa88e6ef3a7b6417f48","name":"Annalisa Luciani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bc39a78ea0fbe90db9255aaf51e0092473ac165fca0a7952be5be798cb2449c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc39a78ea0fbe90db9255aaf51e0092473ac165fca0a7952be5be798cb2449c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc39a78ea0fbe90db9255aaf51e0092473ac165fca0a7952be5be798cb2449c5?s=96&d=mm&r=g","caption":"Annalisa Luciani"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/a-luciani\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3-600x400.png","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/11\/NSE3-600x437.png","author_info":{"display_name":"Annalisa Luciani","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/a-luciani\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/16809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=16809"}],"version-history":[{"count":9,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/16809\/revisions"}],"predecessor-version":[{"id":16921,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/16809\/revisions\/16921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/16829"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=16809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=16809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=16809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}