{"id":17374,"date":"2025-01-14T16:23:58","date_gmt":"2025-01-14T15:23:58","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=17374"},"modified":"2025-08-05T16:40:11","modified_gmt":"2025-08-05T14:40:11","slug":"innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/","title":{"rendered":"Innovation Day: Le sfide dell&#8217;innovazione per il settore logistico del Lazio"},"content":{"rendered":"\n<p>La <strong>Regione Lazio<\/strong>&nbsp;e&nbsp;<strong>Lazio Innova, <\/strong>in collaborazione con<strong>&nbsp;<strong><a href=\"https:\/\/www.un-industria.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Unindustria<\/a><\/strong><\/strong>, lanciano <strong>l\u2019Innovation Day Logistica<\/strong>. <br>La Logistica globale oggi infatti \u00e8 al centro di una trasformazione senza precedenti, grazie all\u2019introduzione di nuove tecnologie e al crescente percorso che le aziende devono seguire verso la sostenibilit\u00e0.<\/p>\n\n\n\n<p>L\u2019incontro rappresenta un\u2019importante occasione per analizzare le tendenze globali e regionali, discutere le esigenze della filiera e proporre soluzioni innovative, con particolare attenzione alle necessit\u00e0 del territorio laziale e porre le basi per proficui incontri b2b, che verranno organizzati per soddisfare i needs che verranno espressi nell\u2019incontro.<\/p>\n\n\n\n<p>L&#8217;iniziativa \u00e8 sostenuta con risorse del <strong>PR FESR Lazio 2021-2027<\/strong>.<\/p>\n\n\n\n<p>L&#8217;evento si svolger\u00e0 il <strong>30 gennaio<\/strong> a partire dalle <strong>9.30<\/strong> presso il <strong>Gazometro Ostiense &#8211; Opificio 41<\/strong> (Via Ostiense 72, Roma).<\/p>\n\n\n\n<p>Il programma della giornata prevede:<\/p>\n\n\n\n<p><strong>Key Note Speech<\/strong>: esperti del settore offriranno una panoramica sulle principali sfide che stanno trasformando il settore logistico, come la digitalizzazione, l\u2019automazione, la sostenibilit\u00e0 e l\u2019introduzione di nuovi modelli di business;<\/p>\n\n\n\n<p><strong>Reverse Pitch<\/strong>: imprese della filiera logistica, investitori e acceleratori presenteranno le loro esigenze e le aree di innovazione su cui intendono concentrare gli investimenti, offrendo cos\u00ec una mappa chiara delle opportunit\u00e0 di sviluppo;<\/p>\n\n\n\n<p><strong>Sessione di Networking<\/strong>: startup e imprese avranno l\u2019opportunit\u00e0 di incontrare i principali player di mercato e presentare le loro soluzioni innovative, favorendo il dialogo tra domanda e offerta di innovazione.<\/p>\n\n\n\n<p>A coronamento della giornata, verr\u00e0 lanciata una&nbsp;<strong>Open Innovation Challenge&nbsp;<\/strong>promossa con<strong>&nbsp;<a href=\"https:\/\/eshop.wuerth.it\/it\/IT\/EUR\/\" target=\"_blank\" rel=\"noreferrer noopener\">W\u00fcrth Italia<\/a><\/strong>, uno dei leader nel settore logistico e attore chiave del comparto laziale. <br>La Challenge \u00e8 volta a individuare soluzioni innovative capaci di rispondere alle sfide del settore, offrendo opportunit\u00e0 concrete di collaborazione con uno dei maggiori operatori del mercato.<\/p>\n\n\n\n<p>L\u2019Innovation Day Logistica sar\u00e0 un momento cruciale per il dialogo tra imprese, istituzioni e innovatori, con l\u2019obiettivo di accelerare la crescita e la trasformazione del comparto logistico nella Regione Lazio.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#fcfc0026\">Per rispondere ai needs che verranno esposti durante l\u2019Innovation Day, le imprese possono registrare, attraverso&nbsp;<strong><a href=\"https:\/\/b2match.com\/e\/innovation-day-logistica-2025\" target=\"_blank\" rel=\"noreferrer noopener\">questa pagina<\/a><\/strong>, il proprio profilo azienda e richiedere, successivamente alla chiusura dell\u2019evento, un incontro b2b con i Player.<br>Tutti coloro che si iscriveranno per partecipare all\u2019Innovation Day saranno tempestivamente informati su modalit\u00e0 e termini di registrazione per i b2b.<br><br>Si ricorda alle imprese che si sono iscritte o si iscrivono a b2Match di<strong> <strong>inserire <\/strong><\/strong>in piattaforma il <strong><strong>marketplace<\/strong>.<\/strong><br><br>I <strong>profili delle imprese<\/strong> che intendono partecipare agli incontri b2b sono <strong>visibili sulla piattaforma<\/strong> <a href=\"https:\/\/www.b2match.com\/\"><strong>b2match<\/strong><\/a>.<\/p>\n\n\n\n<p><br>Scarica il <strong><a href=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/Programma-Innovation-Day-Logistica-21-Gennaio-2025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Programma<\/a><\/strong><\/p>\n\n\n\n<p><br>Per maggiori informazioni e iscrizioni vai alla&nbsp;<strong><a href=\"https:\/\/www.lazioinnova.it\/innovazione-aperta\/iniziativa\/innovation-day-logistica\/\" target=\"_blank\" rel=\"noreferrer noopener\">pagina dedicata<\/a><\/strong><br><br><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>30 GENNAIO 2025 ore 9:30 \u2013 GAZOMETRO DI ROMA \u2013 VIA OSTIENSE, 72 &#8211; Opificio 41<\/p>\n","protected":false},"author":15,"featured_media":17420,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[271,269],"tags":[152,77,804,72,807,216,603],"class_list":["post-17374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomazia-economica-brokerage-e-open-innovation","category-network","tag-innovazione","tag-lazio-innova","tag-logistica","tag-regione-lazio","tag-spazio-attivo","tag-start-up-2","tag-unindustria"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Innovation Day: Le sfide dell&#039;innovazione per il settore logistico del Lazio - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovation Day: Le sfide dell&#039;innovazione per il settore logistico del Lazio - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"30 GENNAIO 2025 ore 9:30 \u2013 GAZOMETRO DI ROMA \u2013 VIA OSTIENSE, 72 - Opificio 41\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-14T15:23:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T14:40:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437.png\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Simona Saldi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simona Saldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/\"},\"author\":{\"name\":\"Simona Saldi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/7cbe2b01abf9e66e3c12dd6c1af34b4a\"},\"headline\":\"Innovation Day: Le sfide dell&#8217;innovazione per il settore logistico del Lazio\",\"datePublished\":\"2025-01-14T15:23:58+00:00\",\"dateModified\":\"2025-08-05T14:40:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/\"},\"wordCount\":439,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/01\\\/SC_InnovationDayLogistica_LI24_777x437.png\",\"keywords\":[\"innovazione\",\"Lazio Innova\",\"logistica\",\"Regione Lazio\",\"spazio attivo\",\"start up\",\"Unindustria\"],\"articleSection\":[\"Diplomazia Economica Brokerage e Open Innovation\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/\",\"name\":\"Innovation Day: Le sfide dell'innovazione per il settore logistico del Lazio - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/01\\\/SC_InnovationDayLogistica_LI24_777x437.png\",\"datePublished\":\"2025-01-14T15:23:58+00:00\",\"dateModified\":\"2025-08-05T14:40:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/7cbe2b01abf9e66e3c12dd6c1af34b4a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/01\\\/SC_InnovationDayLogistica_LI24_777x437.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/01\\\/SC_InnovationDayLogistica_LI24_777x437.png\",\"width\":777,\"height\":437,\"caption\":\"Save The date Innovation Day logistica 30 gennaio 2025. Info nella pagina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/14\\\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovation Day: Le sfide dell&#8217;innovazione per il settore logistico del Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/7cbe2b01abf9e66e3c12dd6c1af34b4a\",\"name\":\"Simona Saldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g\",\"caption\":\"Simona Saldi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/s-saldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innovation Day: Le sfide dell'innovazione per il settore logistico del Lazio - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Innovation Day: Le sfide dell'innovazione per il settore logistico del Lazio - Lazio International - Lazio Innova","og_description":"30 GENNAIO 2025 ore 9:30 \u2013 GAZOMETRO DI ROMA \u2013 VIA OSTIENSE, 72 - Opificio 41","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2025-01-14T15:23:58+00:00","article_modified_time":"2025-08-05T14:40:11+00:00","og_image":[{"width":777,"height":437,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437.png","type":"image\/png"}],"author":"Simona Saldi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Simona Saldi","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/"},"author":{"name":"Simona Saldi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/7cbe2b01abf9e66e3c12dd6c1af34b4a"},"headline":"Innovation Day: Le sfide dell&#8217;innovazione per il settore logistico del Lazio","datePublished":"2025-01-14T15:23:58+00:00","dateModified":"2025-08-05T14:40:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/"},"wordCount":439,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437.png","keywords":["innovazione","Lazio Innova","logistica","Regione Lazio","spazio attivo","start up","Unindustria"],"articleSection":["Diplomazia Economica Brokerage e Open Innovation","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/","name":"Innovation Day: Le sfide dell'innovazione per il settore logistico del Lazio - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437.png","datePublished":"2025-01-14T15:23:58+00:00","dateModified":"2025-08-05T14:40:11+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/7cbe2b01abf9e66e3c12dd6c1af34b4a"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437.png","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437.png","width":777,"height":437,"caption":"Save The date Innovation Day logistica 30 gennaio 2025. Info nella pagina"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/14\/innovation-day-le-sfide-dellinnovazione-per-il-settore-logistico-del-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Innovation Day: Le sfide dell&#8217;innovazione per il settore logistico del Lazio"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/7cbe2b01abf9e66e3c12dd6c1af34b4a","name":"Simona Saldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b48758e5a21486c9d20ea4a06226602c7757f82c020c1a6117d65f8133b71549?s=96&d=mm&r=g","caption":"Simona Saldi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/s-saldi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437-600x400.png","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/01\/SC_InnovationDayLogistica_LI24_777x437-600x437.png","author_info":{"display_name":"Simona Saldi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/s-saldi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/17374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=17374"}],"version-history":[{"count":7,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/17374\/revisions"}],"predecessor-version":[{"id":20075,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/17374\/revisions\/20075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/17420"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=17374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=17374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=17374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}