{"id":17402,"date":"2025-01-17T15:11:13","date_gmt":"2025-01-17T14:11:13","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=17402"},"modified":"2025-02-14T11:28:24","modified_gmt":"2025-02-14T10:28:24","slug":"collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/","title":{"rendered":"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco"},"content":{"rendered":"\n<p><strong>L\u2019ICE-Agenzia<\/strong>, in collaborazione con l\u2019<strong>Ambasciata d\u2019Italia in Grecia<\/strong>, l\u2019<strong>Istituto Italiano di Cultura di Atene <\/strong>e l\u2019<strong>AIE,<\/strong> organizza la partecipazione delle aziende italiane alla <strong>Fiera Internazionale del Libro di Salonicco dall\u20198 all\u201911 maggio 2025<\/strong>. L\u2019Italia sar\u00e0 il Paese Ospite d\u2019Onore.<\/p>\n\n\n\n<p>La fiera, il pi\u00f9 importante evento letterario in Grecia, offre una piattaforma di scambio culturale ed economico. <br>Alla scorsa edizione hanno partecipato 850 espositori da 25 Paesi e 85.000 visitatori.<\/p>\n\n\n\n<p><strong>L&#8217;Italia<\/strong> rappresenta, nell&#8217;edizione <strong>2025<\/strong>, il <strong>Paese Ospite d\u2019Onore<\/strong> favorendo le opportunit\u00e0 per rafforzare i legami culturali e aumentare le opportunit\u00e0 di affari per le imprese italiane. <br>Nel 2023, la Grecia \u00e8 stato l\u2019ottavo mercato europeo per l\u2019Italia in termini di scambi dei diritti.<\/p>\n\n\n\n<p>L\u2019ICE realizzer\u00e0 un <strong>Padiglione ITALIA di 250 mq<\/strong>. <br>Le aziende registrate alla Camera di Commercio con specifici codici ATECO possono partecipare pagando una <strong>quota di \u20ac750,00 + IVA<\/strong>, che include vari servizi come postazioni B2B, esposizione volumi e badge espositori. <br><strong>Le spese di viaggio e soggiorno sono a carico degli espositori.<\/strong><\/p>\n\n\n\n<p>Le aziende interessate devono <strong>iscriversi entro il 24 febbraio 2025<\/strong> tramite il modulo online disponibile sul sito dell\u2019ICE-Agenzia.<\/p>\n\n\n\n<p>Per maggiori informazioni <strong><a href=\"https:\/\/www.ice.it\/it\/area-clienti\/eventi\/dettaglio-evento\/2023\/W1\/031\">clicca qui<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dall\u20198 all\u201911 maggio 2025 partecipazione organizzata in collaborazione con Ambasciata d\u2019Italia in Grecia, Istituto Italiano di Cultura di Atene e AIE.  Iscrizioni entro il 24 febbraio<\/p>\n","protected":false},"author":11,"featured_media":1310,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[2,269],"tags":[189,71,353,516,811,810],"class_list":["post-17402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiere-e-iniziative-internazionali","category-network","tag-aie","tag-editoria","tag-fiere-internazionali","tag-ice-agenzia-2","tag-istituto-italiano-di-cultura-di-atene","tag-salonicco"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"Dall\u20198 all\u201911 maggio 2025 partecipazione organizzata in collaborazione con Ambasciata d\u2019Italia in Grecia, Istituto Italiano di Cultura di Atene e AIE. Iscrizioni entro il 31 gennaio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Dall\u20198 all\u201911 maggio 2025 partecipazione organizzata in collaborazione con Ambasciata d\u2019Italia in Grecia, Istituto Italiano di Cultura di Atene e AIE. Iscrizioni entro il 31 gennaio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-17T14:11:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-14T10:28:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patrizia De Vincenzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrizia De Vincenzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/\"},\"author\":{\"name\":\"Patrizia De Vincenzi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"headline\":\"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco\",\"datePublished\":\"2025-01-17T14:11:13+00:00\",\"dateModified\":\"2025-02-14T10:28:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/\"},\"wordCount\":197,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/libri.jpg\",\"keywords\":[\"AIE\",\"Editoria\",\"fiere internazionali\",\"ICE Agenzia\",\"Istituto Italiano di Cultura di Atene\",\"Salonicco\"],\"articleSection\":[\"Fiere e Iniziative Internazionali\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/\",\"name\":\"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/libri.jpg\",\"datePublished\":\"2025-01-17T14:11:13+00:00\",\"dateModified\":\"2025-02-14T10:28:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"description\":\"Dall\u20198 all\u201911 maggio 2025 partecipazione organizzata in collaborazione con Ambasciata d\u2019Italia in Grecia, Istituto Italiano di Cultura di Atene e AIE. Iscrizioni entro il 31 gennaio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/libri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/libri.jpg\",\"width\":400,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/01\\\/17\\\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\",\"name\":\"Patrizia De Vincenzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"caption\":\"Patrizia De Vincenzi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/p-devincenzi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco - Lazio International - Lazio Innova","description":"Dall\u20198 all\u201911 maggio 2025 partecipazione organizzata in collaborazione con Ambasciata d\u2019Italia in Grecia, Istituto Italiano di Cultura di Atene e AIE. Iscrizioni entro il 31 gennaio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/","og_locale":"it_IT","og_type":"article","og_title":"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco - Lazio International - Lazio Innova","og_description":"Dall\u20198 all\u201911 maggio 2025 partecipazione organizzata in collaborazione con Ambasciata d\u2019Italia in Grecia, Istituto Italiano di Cultura di Atene e AIE. Iscrizioni entro il 31 gennaio","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2025-01-17T14:11:13+00:00","article_modified_time":"2025-02-14T10:28:24+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg","type":"image\/jpeg"}],"author":"Patrizia De Vincenzi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Patrizia De Vincenzi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/"},"author":{"name":"Patrizia De Vincenzi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"headline":"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco","datePublished":"2025-01-17T14:11:13+00:00","dateModified":"2025-02-14T10:28:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/"},"wordCount":197,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg","keywords":["AIE","Editoria","fiere internazionali","ICE Agenzia","Istituto Italiano di Cultura di Atene","Salonicco"],"articleSection":["Fiere e Iniziative Internazionali","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/","name":"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg","datePublished":"2025-01-17T14:11:13+00:00","dateModified":"2025-02-14T10:28:24+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"description":"Dall\u20198 all\u201911 maggio 2025 partecipazione organizzata in collaborazione con Ambasciata d\u2019Italia in Grecia, Istituto Italiano di Cultura di Atene e AIE. Iscrizioni entro il 31 gennaio","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg","width":400,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/01\/17\/collettiva-ice-agenzia-alla-fiera-del-libro-di-salonicco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Collettiva ICE-Agenzia alla Fiera del Libro di Salonicco"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758","name":"Patrizia De Vincenzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","caption":"Patrizia De Vincenzi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/libri.jpg","author_info":{"display_name":"Patrizia De Vincenzi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/17402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=17402"}],"version-history":[{"count":12,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/17402\/revisions"}],"predecessor-version":[{"id":17876,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/17402\/revisions\/17876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/1310"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=17402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=17402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=17402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}