{"id":18169,"date":"2025-02-28T17:08:43","date_gmt":"2025-02-28T16:08:43","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=18169"},"modified":"2025-03-13T16:18:12","modified_gmt":"2025-03-13T15:18:12","slug":"smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/","title":{"rendered":"Smau Parigi: manifestazione di interesse per Startup e PMI innovative"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"117\" src=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/12\/Blocco-loghi-POS-fondo-Transp.png\" alt=\"\" class=\"wp-image-17041\" style=\"width:672px;height:auto\" srcset=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/12\/Blocco-loghi-POS-fondo-Transp.png 800w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/12\/Blocco-loghi-POS-fondo-Transp-300x44.png 300w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2024\/12\/Blocco-loghi-POS-fondo-Transp-768x112.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p>La&nbsp;Regione Lazio, per il tramite del soggetto attuatore&nbsp;Lazio Innova, nell\u2019ambito delle&nbsp;azioni finalizzate alla partecipazione a manifestazioni fieristiche di rilevanza nazionale e internazionale, <strong>seleziona n. 7 Startup e mPMI innovative del Lazio interessate a prendere parte a SMAU Parigi, che si svolger\u00e0 nella capitale francese dal 9 all\u201911 aprile 2025.&nbsp;<\/strong><\/p>\n\n\n\n<p>La partecipazione delle 7 imprese sar\u00e0 sostenuta con i <strong>Fondi PR FESR Lazio 2021-2027<\/strong>.<\/p>\n\n\n\n<p>La Regione Lazio intende partecipare anche alla tappa internazionale di SMAU Stoccolma (19 &#8211; 21 maggio 2025) organizzando a tal fine una collettiva di 7 imprese. Per la partecipazione a SMAU Stoccolma sar\u00e0 pubblicata una specifica Call.<\/p>\n\n\n\n<p>Nelle more dell\u2019approvazione del Programma delle Attivit\u00e0 di Internazionalizzazione 2025, il presente Avviso per manifestazione di interesse si intende&nbsp;NON VINCOLANTE&nbsp;per la Regione Lazio, che si riserva, in qualsiasi momento, di poter annullare, qualora le circostanze lo richiedessero, l\u2019organizzazione della collettiva regionale alla Fiera in oggetto e\/o di modificarne le caratteristiche e i servizi offerti.&nbsp;<\/p>\n\n\n\n<p><br><strong>PERCH\u00c9 PARTECIPARE<\/strong><\/p>\n\n\n\n<p>SMAU \u00e8 oggi una articolata piattaforma europea di incontro e matching dedicata all\u2019innovazione che si articola in un Roadshow annuale di <strong>appuntamenti territoriali<\/strong>; un evento internazionale che si svolge a <strong>Milano, tappe all\u2019estero a Parigi, Londra, Stoccolma<\/strong>. Con oltre 50.000 imprese provenienti da tutti i settori produttivi coinvolte ogni anno, SMAU \u00e8 la piattaforma di riferimento per dialogare direttamente con i protagonisti dell\u2019ecosistema dell\u2019innovazione italiano e internazionale.<\/p>\n\n\n\n<p>La partecipazione all\u2019iniziativa ha l\u2019obiettivo di sviluppare relazioni commerciali, partnership industriali e finanziarie, progetti di <em>open innovation<\/em> e attivit\u00e0 di co-innovazione e favorire processi di <em>cross-fertilization<\/em> interregionale e internazionale.<\/p>\n\n\n\n<p>I lavori di Smau Parigi, giunto alla VI^ edizione, si svolgeranno presso <strong>Station F<\/strong>, uno tra i principali incubatori internazionali di startup, il pi\u00f9 grande d\u2019Europe, che si sviluppa su 34.000 metri quadrati, e prevedono:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>1\u00b0 giorno<\/strong>: ricevimento serale presso l\u2019Ambasciata italiana a Parigi, alla presenza dei rappresentanti istituzionali delle Regioni coinvolte, delle startup selezionate da ciascuna Regione e degli investitori e <em>corporates<\/em> britannici coinvolti nell\u2019iniziativa;<\/li>\n\n\n\n<li><strong>2\u00b0 giorno<\/strong>: evento della durata di tutta la giornata presso <em>Station F<\/em>, con incontri di matching e speed pitching di presentazione delle startup al pubblico di investitori e <em>corporates<\/em> britannici interessati ad entrare in contatto con l\u2019ecosistema italiano delle startup;<\/li>\n\n\n\n<li><strong>3\u00b0 giorno<\/strong>: tour degli incubatori e acceleratori di Parigi, per stimolare la nascita di partnership tra gli stessi e l\u2019ecosistema italiano partecipante all\u2019iniziativa.<\/li>\n<\/ul>\n\n\n\n<p><br><strong>SETTORI<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Industry 4.0<\/strong> (es. IoT, Cloud Computing, AR\/VR, Smart Manufacturing, FinTech, ecc.)<\/li>\n\n\n\n<li><strong>ICT &amp; Digital<\/strong> (es. Aerospace Technology, Cybersecurity, AI, ecc.)<\/li>\n\n\n\n<li><strong>Life Sciences<\/strong> (es. Salute e Benessere, Telemedicina, Sistemi di prevenzione, ecc)<\/li>\n\n\n\n<li><strong>TechCulture e Smart Tourism<\/strong><\/li>\n\n\n\n<li><strong>Energy e Environment<\/strong> (GreenTech, Smart Energy, ecc.)<\/li>\n\n\n\n<li><strong>Smart Agriculture<\/strong> (es. AgriTech, AgriFood, ecc.)<\/li>\n\n\n\n<li><strong>Smart Communities<\/strong> (es. Smart Mobility, Education, Edilizia Sostenibile, PA Digitale, ecc.).<\/li>\n<\/ul>\n\n\n\n<p><br><strong>SERVIZI OFFERTI (<strong>attivit\u00e0 di networking e brokeraggio internazionale<\/strong>)<\/strong><\/p>\n\n\n\n<p>Le Startup e mPMI innovative selezionate per la partecipazione a SMAU Parigi, avranno a disposizione i seguenti servizi e saranno coinvolte nelle seguenti attivit\u00e0 e opportunit\u00e0 di networking che si svolgeranno prima e durante la manifestazione SMAU Parigi. L\u2019obiettivo \u00e8 quello di stimolare il loro incontro con partner industriali (grandi corporate interessate a lavorare con le Startup o ad acquisirne delle quote entrando nel loro capitale sociale) o finanziari (Business Angel, Venture Capital, Fondi di Investimento) francesi. In particolare, le mPMI selezionate beneficeranno delle seguenti opportunit\u00e0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Disponibilit\u00e0\u0300 per ciascuna startup di un proprio <strong>spazio di networking<\/strong> in cui incontrare corporate e investitori britannici. Lo spazio sar\u00e0\u0300 allestito con tavolo e sedie, totem personalizzato per il singolo soggetto, loghi di Regione Lazio e dei partner regionali.<\/li>\n\n\n\n<li>Coinvolgimento in una <strong>sessione speed pitching<\/strong> in cui presentare la propria attivit\u00e0 ad un pubblico di investitori e corporation.<\/li>\n\n\n\n<li><strong>Visibilit\u00e0\u0300<\/strong> nel sito smau.it con una pagina dedicata, riconducibile alla pagina di Regione Lazio, contenente la presentazione della propria attivit\u00e0, la descrizione dei propri servizi o prodotti e il tipo di partner e clienti che si stanno ricercando.<\/li>\n\n\n\n<li>Partecipazione ai diversi <strong>momenti di networking e incontro<\/strong> (ricevimento in Ambasciata, networking cocktail con investitori, tour guidato presso gli incubatori di Parigi, ecc.) con l\u2019ecosistema francese, al fine di favorire la nascita di nuove relazioni con investitori, corporate, incubatori, startup, ecc.<\/li>\n\n\n\n<li><strong>Servizio di assessment<\/strong> dedicato con la Direzione Smau, da organizzarsi prima dell\u2019evento in modalit\u00e0\u0300 digitale, per ricevere consigli e suggerimenti utili al fine di cogliere appieno le diverse opportunit\u00e0\u0300 che l&#8217;evento potr\u00e0\u0300 fornire, trasferire obiettivi puntuali legati alla partecipazione e apprendere spunti importanti per il proprio business.<\/li>\n\n\n\n<li>Supporto nella <strong>preparazione e organizzazione di incontri<\/strong> con operatori internazionali mediante condivisione prima dell\u2019evento delle presenze confermate al fine di identificare i soggetti in target con cui favorire un incontro durante l\u2019evento. Condivideremo con ciascuna startup un file nel quale saranno specificati tutti i protagonisti suddivisi per categoria (operatori internazionali, startup, corporate, abilitatori, investitori, istituzioni), sulla base di questo file le startup potranno segnalarci n. 6 protagonisti che vorranno incontrare durante l\u2019evento.<\/li>\n<\/ul>\n\n\n\n<p><strong><u>Le spese di viaggio e alloggio sono a carico delle imprese.<\/u><\/strong><\/p>\n\n\n\n<p><br><strong>REQUISITI GENERALI DI AMMISSIBILIT\u00c0 PER LE IMPRESE INVITATE A PARTECIPARE:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sede legale e\/o operativa nella Regione Lazio;<\/li>\n\n\n\n<li>Essere mPMI, come classificate nell\u2019Allegato I del Regolamento (UE) n. 651\/2014, in forma singola o associata in Consorzi, Societ\u00e0 Consortili o Reti di imprese con personalit\u00e0 giuridica (Reti-soggetto), definite ai sensi dei commi 4-ter e 4-quater dell\u2019art. 3 del Decreto-legge n. 5 del 10 Febbraio 2009, convertito, con modificazioni, nella Legge n. 33 del 09 Aprile 2009 e ss.mm.ii., al momento della presentazione della manifestazione di interesse;<\/li>\n\n\n\n<li>Esercitare, in relazione alla sede laziale, un\u2019attivit\u00e0 economica coerente con il settore;&nbsp;<\/li>\n\n\n\n<li>Non essere beneficiarie di agevolazioni pubbliche relative alla partecipazione alla manifestazione in questione n\u00e9 aver presentato domande di agevolazione per partecipare alla medesima manifestazione;<\/li>\n\n\n\n<li>Essere nel pieno e libero esercizio dei propri diritti, attive e non essere sottoposte n\u00e9 essere state sottoposte, nei cinque anni precedenti, a procedure di liquidazione volontaria, liquidazione coatta, fallimento, concordato preventivo (ad eccezione del concordato preventivo con continuit\u00e0 aziendale) ed ogni altra procedura concorsuale n\u00e9 avere in corso un procedimento per la dichiarazione di una delle suddette situazioni;<\/li>\n\n\n\n<li>Possedere capacit\u00e0 di contrarre ovvero non essere state oggetto di sanzione interdittiva o altra sanzione che comporti il divieto di contrarre con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>Non avere Amministratori e\/o Legali Rappresentanti che siano stati condannati con sentenza passata in giudicato ovvero nei cui confronti sia stato emesso decreto penale di condanna divenuto irrevocabile o sentenza di applicazione della pena su richiesta, ai sensi dell\u2019art. 444 c.p.p., per reati gravi in danno dello Stato o della Comunit\u00e0 che incidono sulla moralit\u00e0 professionale (\u00e8 comunque causa di esclusione la condanna, con sentenza passata in giudicato, per reati di partecipazione ad un\u2019organizzazione criminale, corruzione, frode, riciclaggio);<\/li>\n\n\n\n<li>Non avere Amministratori e\/o Legali Rappresentanti che si siano resi colpevoli di false dichiarazioni nei rapporti con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>Essere in regola con il versamento dei contributi previdenziali e assistenziali ovvero non essere soggetti agli obblighi in materia di regolarit\u00e0 contributiva e, quindi, non essere tenuti all\u2019iscrizione presso alcun Ente previdenziale o assistenziale.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Il possesso dei requisiti \u00e8 attestato mediante dichiarazioni rese al momento della partecipazione attraverso il modulo di manifestazione di interesse.&nbsp;<\/p>\n\n\n\n<p>Tali dichiarazioni possono essere verificate cos\u00ec come stabilito dall\u2019art. 71 comma 1 del D.P.R. 445 del 28.12.2000, come modificato dall\u2019art. 264 del D.L. 19 maggio 2020 n. 34, con applicazione, nel caso di dichiarazioni mendaci, della decadenza dai benefici e delle sanzioni penali, rispettivamente previste dagli artt. 75 e 76 del medesimo D.P.R., come da ultimo rese pi\u00f9 severe per effetto del citato articolo 264.&nbsp;<\/p>\n\n\n\n<p><br><strong>MODALIT\u00c0 DI PRESENTAZIONE DELLA DOMANDA DI PARTECIPAZIONE&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\" style=\"font-size:22px\"><strong>ISCRIZIONI CHIUSE <\/strong>alle <strong>ore 16.00 del 13 marzo 2025<\/strong><\/p>\n\n\n\n<p><br><strong>CRITERI DI AMMISSIBILIT\u00c0 GENERALI&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>correttezza dell&#8217;iter amministrativo di presentazione della manifestazione di interesse (rispetto delle modalit\u00e0 e dei tempi);&nbsp;<\/li>\n\n\n\n<li>completezza della domanda di partecipazione.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><br><strong>CRITERI DI SELEZIONE<\/strong><\/p>\n\n\n\n<p><strong>Le Startup e mPMI innovative devono, inoltre, essere in possesso dei seguenti requisiti:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Contenuto innovativo del prodotto o servizio presentato;<\/li>\n\n\n\n<li>Prodotto o servizio b2b o, se b2c, con interesse a partnership industriali e\/o finanziarie;<\/li>\n\n\n\n<li>Prodotto o servizio gi\u00e0 industrializzato e pronto per il mercato, con interesse a sviluppo internazionale;<\/li>\n\n\n\n<li>Linee tecnologiche di sviluppo coerenti con uno o pi\u00f9 dei seguenti ambiti: Industry 4.0, ICT &amp; Digital, Life Sciences, TechCulture e Smart Tourism, Energy e Environment, Smart Agriculture, Smart Communities;<\/li>\n\n\n\n<li>Disponibilit\u00e0 di referenze (clienti o PoC gi\u00e0 realizzati) o, in alternativa, avere nella compagine sociale un\u2019impresa gi\u00e0 consolidata o essere stati oggetto di un investimento.<\/li>\n<\/ul>\n\n\n\n<p><br>Fermo il possesso dei requisiti indicati, saranno oggetto di selezione le prime 7 mPMI che risulteranno aver ottenuto il&nbsp;<strong>maggiore punteggio<\/strong>&nbsp;in ragione della valutazione svolta&nbsp;<strong>secondo i seguenti criteri&nbsp;<\/strong>(tra parentesi indicato il punteggio massimo di ciascun criterio):&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Contenuto innovativo del prodotto o servizio (<strong>max 30 punti<\/strong>);<\/li>\n\n\n\n<li>Prodotto o servizio b2b o, se b2c, con interesse a partnership industriali e\/o finanziarie (<strong>max 20 punti<\/strong>);<\/li>\n\n\n\n<li>Disponibilit\u00e0 di referenze (clienti o PoC gi\u00e0 realizzati) o, in alternativa, avere nella compagine sociale un\u2019impresa gi\u00e0 consolidata o in alternativa essere stati oggetto di un investimento (<strong>max 30 punti<\/strong>);<\/li>\n\n\n\n<li>Prodotto o servizio gi\u00e0 industrializzato e pronto per il mercato, con interesse a sviluppo internazionale; linee tecnologiche di sviluppo coerenti con uno o pi\u00f9 dei seguenti ambiti: Industry 4.0, ICT &amp; Digital, Life Sciences, TechCulture e Smart Tourism, Energy e Environment, Smart Agriculture, Smart Communities (<strong>max 20 punti<\/strong>)<\/li>\n<\/ol>\n\n\n\n<p><br><strong>NUCLEO DI VALUTAZIONE<\/strong><\/p>\n\n\n\n<p>La selezione avverr\u00e0 a cura di un Nucleo di Valutazione composto da:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un rappresentante di Regione Lazio;<\/li>\n\n\n\n<li>un rappresentante di Lazio Innova \u2013&nbsp;<em>Direzione Internazionalizzazione e Cluster;<\/em><\/li>\n\n\n\n<li>un rappresentante di SMAU.<\/li>\n<\/ul>\n\n\n\n<p>Fermo il possesso dei requisiti indicati, saranno oggetto di selezione <strong>solo le prime 7 mPMI<\/strong> innovative che risulteranno aver ottenuto il maggiore punteggio in ragione della valutazione svolta secondo i criteri indicati nella presente manifestazione di interesse.&nbsp;<\/p>\n\n\n\n<p>In caso di parit\u00e0 di punteggio, si dar\u00e0 priorit\u00e0 in base all\u2019ordine cronologico di arrivo delle domande. Sar\u00e0 comunque predisposta una graduatoria delle domande ammesse alla quale si attinger\u00e0 qualora si dovessero registrare delle rinunce.&nbsp;<\/p>\n\n\n\n<p><strong>SELEZIONE E COMUNICAZIONE DI AMMISSIONE<\/strong><\/p>\n\n\n\n<p>A seguito dello svolgimento del processo di selezione, tutti i soggetti che hanno sottoposto la candidatura:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>riceveranno una comunicazione all\u2019indirizzo Pec indicato in sede di presentazione della manifestazione di interesse circa l\u2019ammissione o meno all\u2019iniziativa in oggetto;<\/li>\n\n\n\n<li>i soggetti ammessi dovranno, entro il termine indicato nella suddetta comunicazione, provvedere a comunicare <strong>alla Pec <\/strong><a href=\"mailto:internazionalizzazione@pec.lazioinnova.it\"><strong>internazionalizzazione@pec.lazioinnova.it<\/strong><\/a> la loro adesione definitiva ovvero la loro rinuncia; il mancato rispetto dei termini per l\u2019accettazione della proposta di partecipazione comporter\u00e0 l\u2019esclusione dell\u2019azienda. A seguito dell\u2019accettazione, l\u2019azienda sar\u00e0 tenuta a partecipare alla manifestazione in oggetto;<\/li>\n\n\n\n<li>in caso di rinuncia di uno o pi\u00f9 dei soggetti ammessi, si proceder\u00e0 a selezionare gli ulteriori soggetti risultati idonei, nel rispetto della graduatoria redatta dal Nucleo di Valutazione.<\/li>\n<\/ol>\n\n\n\n<p>Si segnala, infine, che la suddetta manifestazione di interesse dell\u2019impresa non vincola gli Enti promotori che si riservano, in qualsiasi momento, di poter annullare, qualora le circostanze lo richiedessero, l\u2019organizzazione dell\u2019iniziativa regionale alla Fiera in oggetto.<\/p>\n\n\n\n<p><br><strong>CONDIZIONI DI ESCLUSIONE<\/strong><\/p>\n\n\n\n<p>Sono escluse dalla partecipazione le imprese presenti alla manifestazione con un proprio stand e le imprese morose nei confronti degli organizzatori per somme relative a precedenti manifestazioni, ovvero morose nei confronti di altri organismi in collaborazione con i quali gli organizzatori promuovono le iniziative.<\/p>\n\n\n\n<p>La mancata partecipazione, o mancato presidio dello stand, potr\u00e0 essere causa di esclusione, ad insindacabile giudizio del Nucleo di Valutazione, alle future iniziative organizzate da Regione Lazio.<\/p>\n\n\n\n<p><br><strong>REGIME DI AIUTO&nbsp;<\/strong><\/p>\n\n\n\n<p>Considerata la volont\u00e0 degli Enti Promotori di venire incontro alle esigenze delle imprese selezionate, la partecipazione alla manifestazione \u00e8 gratuita, fermo restando che rimangono a carico delle stesse le spese relative ad ogni ulteriore servizio extra di personalizzazione richiesto dalle imprese medesime.<\/p>\n\n\n\n<p>I costi di partecipazione sono sostenuti dagli Enti promotori e tale sostegno alle imprese si configura quale aiuto indiretto, per la partecipazione alle iniziative e manifestazioni promosse dalla Regione, e sar\u00e0 concesso nel rispetto delle disposizioni di cui al Regolamento (UE) n. 2831 del 13 dicembre 2023 relativo all\u2019applicazione degli articoli 107 e 108 del trattato sul funzionamento dell\u2019Unione Europea agli aiuti \u201cde minimis\u201d.<\/p>\n\n\n\n<p>A seguito dell\u2019obbligo di consultazione preventiva e di implementazione del Registro Nazionale degli Aiuti di Stato, di cui al Regolamento MISE n. 115 del 31 maggio 2017, gli importi relativi alle agevolazioni concesse verranno conseguentemente inseriti nel suddetto Registro, fino ad un importo massimo \u20ac 6.000,00&nbsp;(euro seimila\/00) I.V.A. inclusa, per ogni impresa ammessa. Come previsto dall\u2019art. 3 par. 7 dello stesso Regolamento, qualora la concessione di nuovi aiuti \u201cde minimis\u201d comporti il superamento dei massimali previsti, nessuna delle nuove misure di aiuto pu\u00f2 beneficiare del Regolamento. L\u2019importo massimo delle agevolazioni in regime \u201cde minimis\u201d che possono essere concesse ad un\u2019unica impresa nell\u2019arco di tre anni, senza la preventiva notifica ed autorizzazione da parte della Commissione Europea e senza che ci\u00f2 possa incidere sugli scambi tra gli Stati membri e da non falsare o minacciare di falsare la concorrenza, \u00e8 pari a \u20ac 300.000,00.&nbsp;<\/p>\n\n\n\n<p>In caso di superamento delle soglie predette, l\u2019agevolazione suindicata non potr\u00e0 essere concessa, neppure per la parte che non superi detti massimali.<\/p>\n\n\n\n<p>Si fa presente che ciascuna impresa pu\u00f2 monitorare l\u2019importo delle agevolazioni in regime \u201cde minimis\u201d di cui ha beneficiato a far data dal 12 agosto 2017, sul sito del Registro Nazionale degli Aiuti di Stato nella sezione Trasparenza al seguente Link: https:\/\/www.rna.gov.it\/RegistroNazionaleTrasparenza\/faces\/pages\/TrasparenzaAiuto.jspx<\/p>\n\n\n\n<p><br><strong>PRIVACY&nbsp;<\/strong><\/p>\n\n\n\n<p>I dati forniti saranno trattati dagli organizzatori in osservanza di quanto disposto dal Regolamento UE 679\/2016 sulla protezione dei dati personali.&nbsp;<\/p>\n\n\n\n<p>Per informazioni rivolgersi a:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Regione Lazio<br>Lazio Innova S.p.A. \u2013 Direzione Internazionalizzazione &amp; Cluster <br>e-mail:\u202finternazionalizzazione@lazioinnova.it\u202f- Tel. 06.60.51.60&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Tutta la modulistica \u00e8 consultabile e scaricabile sui siti: <br><a href=\"http:\/\/www.lazioinnova.it\/laziointernational\">www.lazioinnova.it\/laziointernational<\/a> <br><a href=\"http:\/\/www.lazioeuropa.it\">www.lazioeuropa.it<\/a><br><br><br><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Lazio promuove una collettiva di 7 startup e mPMI innovative. Candidature entro le ore 16.00 del 13 marzo<\/p>\n","protected":false},"author":12,"featured_media":9284,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[45,63,2],"tags":[26,47,42,152,77,19,72,62,106],"class_list":["post-18169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-finanziamenti","category-community-degli-innovatori","category-fiere-e-iniziative-internazionali","tag-agro-industria","tag-bioscienze","tag-ict","tag-innovazione","tag-lazio-innova","tag-multisettore","tag-regione-lazio","tag-smart-cities-tech","tag-smau"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Smau Parigi: manifestazione di interesse per Startup e PMI innovative - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"La Regione Lazio promuove una collettiva di 7 startup e mPMI innovative. Candidature entro le ore 16.00 del 13 marzo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smau Parigi: manifestazione di interesse per Startup e PMI innovative - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"La Regione Lazio promuove una collettiva di 7 startup e mPMI innovative. Candidature entro le ore 16.00 del 13 marzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T16:08:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T15:18:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Donatella Piccione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Donatella Piccione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/\"},\"author\":{\"name\":\"Donatella Piccione\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/564e7ecfadf603a28e3631d0406f3f4d\"},\"headline\":\"Smau Parigi: manifestazione di interesse per Startup e PMI innovative\",\"datePublished\":\"2025-02-28T16:08:43+00:00\",\"dateModified\":\"2025-03-13T15:18:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/\"},\"wordCount\":2288,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/02\\\/smau-slider.jpg\",\"keywords\":[\"Agro-industria\",\"Bioscienze\",\"ICT\",\"innovazione\",\"Lazio Innova\",\"Multisettore\",\"Regione Lazio\",\"Smart Cities &amp; Tech\",\"SMAU\"],\"articleSection\":[\"Bandi e Finanziamenti\",\"Community degli Innovatori\",\"Fiere e Iniziative Internazionali\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/\",\"name\":\"Smau Parigi: manifestazione di interesse per Startup e PMI innovative - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/02\\\/smau-slider.jpg\",\"datePublished\":\"2025-02-28T16:08:43+00:00\",\"dateModified\":\"2025-03-13T15:18:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/564e7ecfadf603a28e3631d0406f3f4d\"},\"description\":\"La Regione Lazio promuove una collettiva di 7 startup e mPMI innovative. Candidature entro le ore 16.00 del 13 marzo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/02\\\/smau-slider.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2023\\\/02\\\/smau-slider.jpg\",\"width\":777,\"height\":438,\"caption\":\"Logo SMAU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/02\\\/28\\\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smau Parigi: manifestazione di interesse per Startup e PMI innovative\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/564e7ecfadf603a28e3631d0406f3f4d\",\"name\":\"Donatella Piccione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f76b687cd05de56d9e2d0d9664dd1e5f4ed63c3408d6921e6b6d8a8b4cd2ff9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f76b687cd05de56d9e2d0d9664dd1e5f4ed63c3408d6921e6b6d8a8b4cd2ff9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f76b687cd05de56d9e2d0d9664dd1e5f4ed63c3408d6921e6b6d8a8b4cd2ff9?s=96&d=mm&r=g\",\"caption\":\"Donatella Piccione\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/d-piccione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smau Parigi: manifestazione di interesse per Startup e PMI innovative - Lazio International - Lazio Innova","description":"La Regione Lazio promuove una collettiva di 7 startup e mPMI innovative. Candidature entro le ore 16.00 del 13 marzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/","og_locale":"it_IT","og_type":"article","og_title":"Smau Parigi: manifestazione di interesse per Startup e PMI innovative - Lazio International - Lazio Innova","og_description":"La Regione Lazio promuove una collettiva di 7 startup e mPMI innovative. Candidature entro le ore 16.00 del 13 marzo","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2025-02-28T16:08:43+00:00","article_modified_time":"2025-03-13T15:18:12+00:00","og_image":[{"width":777,"height":438,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider.jpg","type":"image\/jpeg"}],"author":"Donatella Piccione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Donatella Piccione","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/"},"author":{"name":"Donatella Piccione","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/564e7ecfadf603a28e3631d0406f3f4d"},"headline":"Smau Parigi: manifestazione di interesse per Startup e PMI innovative","datePublished":"2025-02-28T16:08:43+00:00","dateModified":"2025-03-13T15:18:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/"},"wordCount":2288,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider.jpg","keywords":["Agro-industria","Bioscienze","ICT","innovazione","Lazio Innova","Multisettore","Regione Lazio","Smart Cities &amp; Tech","SMAU"],"articleSection":["Bandi e Finanziamenti","Community degli Innovatori","Fiere e Iniziative Internazionali"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/","name":"Smau Parigi: manifestazione di interesse per Startup e PMI innovative - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider.jpg","datePublished":"2025-02-28T16:08:43+00:00","dateModified":"2025-03-13T15:18:12+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/564e7ecfadf603a28e3631d0406f3f4d"},"description":"La Regione Lazio promuove una collettiva di 7 startup e mPMI innovative. Candidature entro le ore 16.00 del 13 marzo","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider.jpg","width":777,"height":438,"caption":"Logo SMAU"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/02\/28\/smau-parigi-manifestazione-di-interesse-per-startup-e-pmi-innovative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Smau Parigi: manifestazione di interesse per Startup e PMI innovative"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/564e7ecfadf603a28e3631d0406f3f4d","name":"Donatella Piccione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0f76b687cd05de56d9e2d0d9664dd1e5f4ed63c3408d6921e6b6d8a8b4cd2ff9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f76b687cd05de56d9e2d0d9664dd1e5f4ed63c3408d6921e6b6d8a8b4cd2ff9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f76b687cd05de56d9e2d0d9664dd1e5f4ed63c3408d6921e6b6d8a8b4cd2ff9?s=96&d=mm&r=g","caption":"Donatella Piccione"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/d-piccione\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider-600x400.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2023\/02\/smau-slider-600x438.jpg","author_info":{"display_name":"Donatella Piccione","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/d-piccione\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/18169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=18169"}],"version-history":[{"count":12,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/18169\/revisions"}],"predecessor-version":[{"id":18348,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/18169\/revisions\/18348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/9284"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=18169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=18169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=18169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}