{"id":20291,"date":"2025-09-22T10:26:21","date_gmt":"2025-09-22T08:26:21","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=20291"},"modified":"2025-09-22T10:54:22","modified_gmt":"2025-09-22T08:54:22","slug":"blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/","title":{"rendered":"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio"},"content":{"rendered":"\n<p>La Regione Lazio attraverso Lazio Innova, organizza\u00a0<strong>Blue Innovation Lab<\/strong>, due giornate di incontro, formazione e co-progettazione con i\u00a0<strong>24 Comuni costieri del Lazio<\/strong>, a\u00a0<strong>Santa Severa il 15 e 16 ottobre 2025<\/strong>.<br>Un laboratorio di idee e contaminazione, dove pubblico e privato si incontrano per costruire insieme il futuro della\u00a0<strong>Blue Economy nel Lazio<\/strong>.<\/p>\n\n\n\n<p>La partecipazione all\u2019evento \u00e8 aperta a&nbsp;<strong>imprese, startup e centri di ricerca<\/strong>&nbsp;della Blue Economy del Lazio e offre l\u2019opportunit\u00e0 di:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Presentare ed <strong>esporre gratuitamente i propri prodotti<\/strong> negli spazi esterni del Castello di Santa Severa;<\/li>\n\n\n\n<li>Divulgare a Comuni, istituzioni e stakeholder i propri <strong>progetti di ricerca e innovazione<\/strong>;<\/li>\n\n\n\n<li>Lavorare fianco a fianco con le amministrazioni locali attraverso metodologie di <strong>Design Thinking<\/strong> e gruppi di lavoro collaborativi;<\/li>\n\n\n\n<li>Generare <strong>idee innovative<\/strong> che contribuiranno alla definizione delle <strong>politiche regionali della Blue Economy 2026<\/strong>;<\/li>\n\n\n\n<li>Accedere a occasioni concrete di networking e candidarsi a diventare protagonisti dei <strong>nuovi bandi regionali<\/strong>.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center\"><strong>Programma in breve<\/strong><\/p>\n\n\n\n<p><strong>Mercoled\u00ec 15 ottobre dalle ore 15:00<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Regione Lazio: \u201cStrategie e Opportunit\u00e0 per lo Sviluppo del Litorale e della Blue Economy\u201d;<\/li>\n\n\n\n<li>Presentazione dei Progetti delle Imprese che hanno vinto il Bando di Riposizionamento Competitivo;<\/li>\n\n\n\n<li>Opportunit\u00e0 per Imprese e Comuni costieri (S3);<\/li>\n\n\n\n<li>Networking.<\/li>\n<\/ul>\n\n\n\n<p><strong>Gioved\u00ec 16 ottobre dalle ore 09:00 alle ore 16:00<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Imprese e Centri di Ricerca presentano ai Comuni Progetti Innovativi (spazio espositivo e Q&amp;A);<\/li>\n\n\n\n<li>Tavoli di Lavoro tematici con metodologie di Design Thinking per co-progettare soluzioni;<\/li>\n\n\n\n<li>Premiazione dei Comuni innovativi e conferimento del<em> Blue Ambassador Award<\/em>.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p style=\"font-size:22px\"><br><strong>Per partecipare, \u00e8 necessaria la registrazione online <a href=\"https:\/\/www.lazioinnova.it\/laziointernational\/partecipazione-a-blue-innovation-lab\/\" target=\"_blank\" rel=\"noreferrer noopener\">QUI<\/a><\/strong><br><br><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Castello di Santa Severa, 15-16 ottobre 2025. Imprese, startup e centri di ricerca incontrano Comuni, istituzioni e stakeholder<\/p>\n","protected":false},"author":2,"featured_media":20495,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[63,27,269],"tags":[227,775,76,77,72,306,625],"class_list":["post-20291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-community-degli-innovatori","category-formazione-ed-empowerment","category-network","tag-blue-economy","tag-comuni-costieri","tag-imprese","tag-lazio-innova","tag-regione-lazio","tag-ricerca","tag-stratup"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"Castello di Santa Severa, 9-10 ottobre 2025. Imprese, startup e centri di ricerca incontrano Comuni, istituzioni e stakeholder\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Castello di Santa Severa, 9-10 ottobre 2025. Imprese, startup e centri di ricerca incontrano Comuni, istituzioni e stakeholder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T08:26:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T08:54:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simona Carloppi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simona Carloppi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/\"},\"author\":{\"name\":\"Simona Carloppi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/c42136fe1dbbf753456b892800a5e2f2\"},\"headline\":\"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio\",\"datePublished\":\"2025-09-22T08:26:21+00:00\",\"dateModified\":\"2025-09-22T08:54:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/\"},\"wordCount\":254,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/09\\\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg\",\"keywords\":[\"Blue economy\",\"Comuni costieri\",\"Imprese\",\"Lazio Innova\",\"Regione Lazio\",\"Ricerca\",\"stratup\"],\"articleSection\":[\"Community degli Innovatori\",\"Formazione ed Empowerment\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/\",\"name\":\"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/09\\\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg\",\"datePublished\":\"2025-09-22T08:26:21+00:00\",\"dateModified\":\"2025-09-22T08:54:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/c42136fe1dbbf753456b892800a5e2f2\"},\"description\":\"Castello di Santa Severa, 9-10 ottobre 2025. Imprese, startup e centri di ricerca incontrano Comuni, istituzioni e stakeholder\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/09\\\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2025\\\/09\\\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"15 ottobre 2025 - ore 15. 16 ottobre 2025 ore 9.00 - Castello di Santa Severa (Via Aurelia km 52) Info nella pagina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2025\\\/09\\\/22\\\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/c42136fe1dbbf753456b892800a5e2f2\",\"name\":\"Simona Carloppi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fbfa76e102775a28693918d88280aebaf3d2a7454fa21827a18c982fcbdbe35?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fbfa76e102775a28693918d88280aebaf3d2a7454fa21827a18c982fcbdbe35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fbfa76e102775a28693918d88280aebaf3d2a7454fa21827a18c982fcbdbe35?s=96&d=mm&r=g\",\"caption\":\"Simona Carloppi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/s-carloppi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio - Lazio International - Lazio Innova","description":"Castello di Santa Severa, 9-10 ottobre 2025. Imprese, startup e centri di ricerca incontrano Comuni, istituzioni e stakeholder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio - Lazio International - Lazio Innova","og_description":"Castello di Santa Severa, 9-10 ottobre 2025. Imprese, startup e centri di ricerca incontrano Comuni, istituzioni e stakeholder","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2025-09-22T08:26:21+00:00","article_modified_time":"2025-09-22T08:54:22+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg","type":"image\/jpeg"}],"author":"Simona Carloppi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Simona Carloppi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/"},"author":{"name":"Simona Carloppi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/c42136fe1dbbf753456b892800a5e2f2"},"headline":"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio","datePublished":"2025-09-22T08:26:21+00:00","dateModified":"2025-09-22T08:54:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/"},"wordCount":254,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg","keywords":["Blue economy","Comuni costieri","Imprese","Lazio Innova","Regione Lazio","Ricerca","stratup"],"articleSection":["Community degli Innovatori","Formazione ed Empowerment","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/","name":"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg","datePublished":"2025-09-22T08:26:21+00:00","dateModified":"2025-09-22T08:54:22+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/c42136fe1dbbf753456b892800a5e2f2"},"description":"Castello di Santa Severa, 9-10 ottobre 2025. Imprese, startup e centri di ricerca incontrano Comuni, istituzioni e stakeholder","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF.jpg","width":1920,"height":1080,"caption":"15 ottobre 2025 - ore 15. 16 ottobre 2025 ore 9.00 - Castello di Santa Severa (Via Aurelia km 52) Info nella pagina"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2025\/09\/22\/blue-innovation-lab-co-progettare-linnovazione-per-i-comuni-costieri-del-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Blue Innovation Lab: Co-progettare l\u2019Innovazione per i Comuni costieri del Lazio"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/c42136fe1dbbf753456b892800a5e2f2","name":"Simona Carloppi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5fbfa76e102775a28693918d88280aebaf3d2a7454fa21827a18c982fcbdbe35?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fbfa76e102775a28693918d88280aebaf3d2a7454fa21827a18c982fcbdbe35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fbfa76e102775a28693918d88280aebaf3d2a7454fa21827a18c982fcbdbe35?s=96&d=mm&r=g","caption":"Simona Carloppi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/s-carloppi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF-600x400.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/09\/Banner-Blue-Economy-Lab-15-16-ottobre-2025-DEF-600x600.jpg","author_info":{"display_name":"Simona Carloppi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/s-carloppi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/20291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=20291"}],"version-history":[{"count":3,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/20291\/revisions"}],"predecessor-version":[{"id":20499,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/20291\/revisions\/20499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/20495"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=20291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=20291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=20291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}