{"id":22227,"date":"2026-04-02T16:54:27","date_gmt":"2026-04-02T14:54:27","guid":{"rendered":"https:\/\/www.lazioinnova.it\/laziointernational\/?p=22227"},"modified":"2026-05-06T14:11:57","modified_gmt":"2026-05-06T12:11:57","slug":"manifestazione-di-interesse-per-casaidea-2026","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/","title":{"rendered":"Manifestazione di interesse per Casaidea 2026"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2133\" height=\"256\" src=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/02\/loghi-fiere-in-convenzione_SOLO-CCIAA.png\" alt=\"Loghi Coesione 21-27, Unione europea, Repubblica Italiana, Regione Lazio, Lazio Innova, CCIAA Roma\" class=\"wp-image-17786\" srcset=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/02\/loghi-fiere-in-convenzione_SOLO-CCIAA.png 2133w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/02\/loghi-fiere-in-convenzione_SOLO-CCIAA-300x36.png 300w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/02\/loghi-fiere-in-convenzione_SOLO-CCIAA-1024x123.png 1024w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/02\/loghi-fiere-in-convenzione_SOLO-CCIAA-768x92.png 768w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/02\/loghi-fiere-in-convenzione_SOLO-CCIAA-1536x184.png 1536w, https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2025\/02\/loghi-fiere-in-convenzione_SOLO-CCIAA-2048x246.png 2048w\" sizes=\"auto, (max-width: 2133px) 100vw, 2133px\" \/><\/figure>\n\n\n\n<p>La <strong>Regione Lazio <\/strong>per il tramite del soggetto attuatore <strong>Lazio Innova <\/strong>e la<strong> Camera di Commercio di Roma, <\/strong>con il supporto dell\u2019<strong>Azienda Speciale Sviluppo e Territorio<\/strong>, nelle more della firma della Convenzione per la partecipazione congiunta a manifestazioni fieristiche &#8211; anno 2026, allo scopo di sostenere il tessuto economico regionale, promuovono la partecipazione a \u201c<strong>Casaidea<\/strong>\u201d che si svolger\u00e0<strong> dal 9 al 17 maggio 2026 presso<\/strong> la <strong>Fiera di Roma<\/strong>, dove \u00e8 intenzione degli Enti promotori organizzare una collettiva di <strong>n. 68 imprese<\/strong> del Lazio interessate a prendere parte alla manifestazione.<br>&nbsp;<br>La partecipazione di n. <strong>25 imprese<\/strong> delle n. 68 selezionate \u00e8 sostenuta dalla Regione Lazio con risorse del <strong>PR FESR 2021-2027<\/strong>,mentre quella delle restanti&nbsp;<strong>n. 43 imprese<\/strong>&nbsp;si avvale delle&nbsp;risorse<strong> della Camera di Commercio di Roma.<\/strong><br><strong>&nbsp;<\/strong><br>Il presente Avviso per manifestazione di interesse si intende&nbsp;NON VINCOLANTE&nbsp;per la Regione Lazio e per gli altri Enti promotori, che si riservano, in qualsiasi momento, di poter annullare, qualora le circostanze lo richiedessero, l\u2019organizzazione della collettiva regionale alla Fiera in oggetto e\/o di modificarne le caratteristiche e i servizi offerti.&nbsp;<br>Gli Enti promotori daranno opportuna diffusione sui rispettivi siti istituzionali e canali di comunicazione utilizzati per promuovere le iniziative.<br>&nbsp;<br><strong>CASAIDEA <\/strong>rappresenta uno degli appuntamenti di riferimento del settore Arredo e Design. Nove giorni di manifestazione in cui i visitatori potranno scoprire gli allestimenti delle migliori aziende del settore, sia nazionali che del territorio del Lazio. Spazio anche all\u2019artigianato di alta qualit\u00e0 che rappresenta maestria e tradizione del territorio, novit\u00e0 e tendenze dell\u2019abitare delle aziende, tra zona giorno, zona notte, cucina, bagno, infissi, arredo da esterni e prodotti artigianali, tutte con soluzioni all\u2019insegna dello stile e dell\u2019alta qualit\u00e0.<br><strong>&nbsp;<\/strong><br><br><strong>SPAZIO ESPOSITIVO<\/strong><br>&nbsp;<br>Ognuna delle imprese partecipanti avr\u00e0 a disposizione uno stand di 12 mq. comprensivo di:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pannellatura perimetrale;<\/li>\n\n\n\n<li>Moquette;<\/li>\n\n\n\n<li>Scritta centrale con insegna espositore (comprensiva anche dei loghi dei partner istituzionali);<\/li>\n\n\n\n<li>Impianto elettrico, 4 spot da 100 watt, 1 presa 16A per ogni 12 mq.<\/li>\n\n\n\n<li>N. 1 pass auto<\/li>\n\n\n\n<li>N. 2 tessere espositore<\/li>\n\n\n\n<li>Assicurazione<\/li>\n\n\n\n<li>Oneri per la sicurezza<\/li>\n<\/ul>\n\n\n\n<p>&nbsp;<br><strong>CATEGORIE MERCEOLOGICHE AMMESSE<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>&nbsp;<\/strong>Tessuti e rivestimento d&#8217;arredo;<\/li>\n\n\n\n<li>Carta da parati;<\/li>\n\n\n\n<li>Complementi d&#8217;arredo;<\/li>\n\n\n\n<li>Complementi per la cucina;<\/li>\n\n\n\n<li>Tendaggi;<\/li>\n\n\n\n<li>Restauro;<\/li>\n\n\n\n<li>Infissi;<\/li>\n\n\n\n<li>Impiantistica;<\/li>\n\n\n\n<li>Ristrutturazione;<\/li>\n\n\n\n<li>Climatizzazione;<\/li>\n<\/ul>\n\n\n\n<p>&nbsp;<br><strong>REQUISITI DI AMMISSIBILIT\u00c0 PER LE IMPRESE PARTECIPANTI ALLA MANIFESTAZIONE DI INTERESSE<\/strong><\/p>\n\n\n\n<p>&nbsp;L\u2019opportunit\u00e0 di prendere parte alla collettiva regionale presso la manifestazione Casaidea 2026 \u00e8 riservata alle imprese in possesso dei seguenti requisiti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sede legale e\/o operativa nel Lazio;&nbsp;<\/li>\n\n\n\n<li>coerenza dell\u2019attivit\u00e0 dell\u2019azienda con il settore o i settori economici cui la manifestazione \u00e8 rivolta;<\/li>\n\n\n\n<li>essere MPMI, come classificate nell\u2019Allegato I del Regolamento (UE) n. 651\/2014, in forma singola o associata in Consorzi, Societ\u00e0 Consortili o Reti di imprese con personalit\u00e0 giuridica (Reti-soggetto), definite ai sensi dei commi 4-ter e 4-quater dell\u2019art. 3 del Decreto-legge n. 5 del 10 febbraio 2009, convertito, con modificazioni, nella Legge n. 33 del 09 Aprile 2009 e ss.mm.ii., al momento della presentazione della manifestazione di interesse;<\/li>\n\n\n\n<li>essere regolarmente iscritte nel Registro delle Imprese della C.C.I.A.A. competente per territorio e in regola, al momento della presentazione della manifestazione di interesse o comunque entro i termini di chiusura di presentazione della stessa, con il pagamento del diritto annuale (Il controllo sulla regolarit\u00e0 del diritto annuale si estende agli ultimi cinque anni escluso il corrente) e con la dichiarazione dell\u2019attivit\u00e0 esercitata;<\/li>\n\n\n\n<li>esercitare, in relazione alla sede laziale, un\u2019attivit\u00e0 economica coerente con il settore;<\/li>\n\n\n\n<li>non essere beneficiarie di agevolazioni pubbliche relative alla partecipazione alla manifestazione fieristica in questione e non avere presentato domande di agevolazione per partecipare alla medesima manifestazione;&nbsp;<\/li>\n\n\n\n<li>non aver superato, negli ultimi tre anni, l\u2019importo massimo di \u20ac 300.000,00 delle agevolazioni in regime \u201cde minimis\u201d ai sensi del Regolamento (UE) n. 2831 del 13 dicembre 2023 relativo all\u2019applicazione degli articoli 107 e 108 del trattato sul funzionamento dell\u2019Unione Europea agli aiuti \u201cde minimis\u201d;<\/li>\n\n\n\n<li>essere nel pieno e libero esercizio dei propri diritti, attive e non essere sottoposte n\u00e9 essere state sottoposte, nei cinque anni precedenti, a procedure di liquidazione volontaria, liquidazione coatta, fallimento, concordato preventivo (ad eccezione del concordato preventivo con continuit\u00e0 aziendale) ed ogni altra procedura concorsuale n\u00e9 abbiano in corso un procedimento per la dichiarazione di una delle suddette situazioni;<\/li>\n\n\n\n<li>possedere capacit\u00e0 di contrarre ovvero non siano state oggetto di sanzione interdittiva o altra sanzione che comporti il divieto di contrarre con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>non avere Amministratori e\/o Legali Rappresentanti che siano stati condannati con sentenza passata in giudicato ovvero nei cui confronti sia stato emesso decreto penale di condanna divenuto irrevocabile o sentenza di applicazione della pena su richiesta, ai sensi dell\u2019art. 444 c.p.p., per reati gravi in danno dello Stato o della Comunit\u00e0 che incidono sulla moralit\u00e0 professionale (\u00e8 comunque causa di esclusione la condanna, con sentenza passata in giudicato, per reati di partecipazione ad un\u2019organizzazione criminale, corruzione, frode, riciclaggio);<\/li>\n\n\n\n<li>non avere Amministratori e\/o Legali Rappresentanti che si siano resi colpevoli di false dichiarazioni nei rapporti con la Pubblica Amministrazione;<\/li>\n\n\n\n<li>essere in regola con il versamento dei contributi previdenziali e assistenziali, accertabile mediante acquisizione del DURC, ovvero, &nbsp;non essere soggetti agli obblighi in materia di regolarit\u00e0 contributiva e, quindi, non essere tenuti all\u2019iscrizione presso alcun Ente previdenziale o assistenziale.<\/li>\n<\/ul>\n\n\n\n<p>&nbsp;Il possesso dei succitati requisiti \u00e8 attestato mediante dichiarazioni rese attraverso il modulo di manifestazione di interesse.&nbsp;<\/p>\n\n\n\n<p><em>&nbsp;Tali dichiarazioni possono essere verificate cos\u00ec come stabilito dall\u2019art. 71 comma 1 del D.P.R. 445 del 28.12.2000, come modificato dall\u2019art. 264 del D.L. 19 maggio 2020 n. 34, con applicazione, nel caso di dichiarazioni mendaci, della decadenza dai benefici e delle sanzioni penali, rispettivamente previste dagli artt. 75 e 76 del medesimo D.P.R., come da ultimo rese pi\u00f9 severe per effetto del citato articolo 264.&nbsp;<\/em><\/p>\n\n\n\n<p>&nbsp;<br><strong>MODALIT\u00c0 DI PRESENTAZIONE DELLA DOMANDA DI PARTECIPAZIONE&nbsp;<\/strong><\/p>\n\n\n\n<p>\u00a0Le aziende interessate a partecipare alla collettiva regionale dovranno effettuare, <strong>entro e non oltre le ore 10.00 del 16 aprile 2026<\/strong>, i seguenti adempimenti, pena la non ammissibilit\u00e0 della domanda.<\/p>\n\n\n\n<p><strong>ISCRIZIONI CHIUSE<\/strong><\/p>\n\n\n\n<p>&nbsp;<br><strong>CRITERI DI AMMISSIBILIT\u00c0 GENERALI&nbsp;<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>&nbsp;Correttezza dell\u2019iter amministrativo di presentazione della domanda di partecipazione (rispetto delle modalit\u00e0 e dei tempi);&nbsp;<\/li>\n\n\n\n<li>Completezza della domanda di partecipazione.<\/li>\n<\/ol>\n\n\n\n<p><strong>&nbsp;<\/strong><br><strong>SELEZIONE&nbsp;<\/strong><\/p>\n\n\n\n<p>&nbsp;La selezione avverr\u00e0 a cura di un <strong>Nucleo di Valutazione<\/strong> composto da:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un rappresentante di Regione Lazio;<\/li>\n\n\n\n<li>un rappresentante del Sistema Camerale di Roma;<\/li>\n\n\n\n<li>un rappresentante di Lazio Innova.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>&nbsp;<\/strong><br><strong>CRITERI DI SELEZIONE E COMUNICAZIONE DI AMMISSIONE<\/strong>&nbsp;<\/p>\n\n\n\n<p>&nbsp;Gli spazi espositivi saranno assegnati alle imprese sulla base della graduatoria elaborata attraverso l\u2019applicazione dei seguenti criteri di selezione:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>priorit\u00e0 in graduatoria alle imprese che non hanno partecipato alla precedente edizione di Casaidea attraverso la collettiva di imprese di Regione Lazio \u2013 Camera di Commercio di Roma;<\/li>\n\n\n\n<li>riserva di 17 posti per le imprese cd \u201cgiovanili\u201d, ossia imprese la cui propriet\u00e0 e controllo sono detenuti prevalentemente (oltre il 50%) da persone fino a 35 anni d\u2019et\u00e0 inclusi al momento della domanda, e, nello specifico:<br>impresa individuale, il cui titolare \u00e8 un \u201cgiovane\u201d;<br>societ\u00e0 di persone o societ\u00e0 cooperative, in cui il numero dei \u201cgiovani\u201d soci rappresenti pi\u00f9 del 50% della compagine sociale e i cui organi di amministrazione siano costituiti in misura superiore al 50% da \u201cgiovani\u201d;<br>societ\u00e0 di capitali, le cui quote di partecipazione spettino in misura superiore al 50% a \u201cgiovani\u201d e i cui organi di amministrazione siano costituiti in misura superiore al 50% da \u201cgiovani\u201d.<\/li>\n<\/ul>\n\n\n\n<p>A parit\u00e0 dei criteri precedenti, la graduatoria \u00e8 redatta secondo l\u2019ordine cronologico di invio della PEC di candidatura, preceduta in ogni caso dalla compilazione del modulo\/form di registrazione online della Manifestazione di interesse, trattandosi di \u201cprocedura a sportello\u201d.<\/p>\n\n\n\n<p>Alla graduatoria di tutte le domande ammissibili si attinger\u00e0 inoltre qualora si dovessero registrare delle rinunce tra le imprese selezionate.<\/p>\n\n\n\n<p>A seguito dello svolgimento del processo di selezione, tutti i soggetti che hanno sottoposto la candidatura:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>riceveranno una comunicazione all\u2019indirizzo PEC indicato in sede di presentazione della manifestazione di interesse circa l\u2019ammissione o meno all\u2019iniziativa in oggetto;<\/li>\n\n\n\n<li>&nbsp;i soggetti ammessi dovranno, entro il termine indicato nella suddetta comunicazione, provvedere a comunicare via PEC la loro adesione&nbsp;definitiva ovvero la loro rinuncia; il mancato rispetto dei termini per l\u2019accettazione della proposta di partecipazione comporter\u00e0 l\u2019esclusione dell\u2019azienda. A seguito dell\u2019accettazione, l\u2019azienda sar\u00e0 tenuta a partecipare alla manifestazione in oggetto; si precisa che, accettando la partecipazione, l\u2019azienda si impegna a presidiare lo stand in modo esclusivo (lo stesso soggetto non potr\u00e0 presidiare pi\u00f9 di uno stand) e continuativo (per l\u2019intera durata della manifestazione);<\/li>\n\n\n\n<li>in caso di rinuncia di uno o pi\u00f9 dei soggetti ammessi, si proceder\u00e0 a selezionare gli ulteriori soggetti risultati idonei, nel rispetto della graduatoria redatta dal Nucleo di Valutazione.<\/li>\n<\/ul>\n\n\n\n<p>Si segnala, infine, che la suddetta manifestazione di interesse dell\u2019impresa non vincola gli Enti promotori che si riservano, in qualsiasi momento, di poter annullare, qualora le circostanze lo richiedessero, l\u2019organizzazione della collettiva regionale alla Fiera in oggetto.<\/p>\n\n\n\n<p>&nbsp;<br><strong>CONDIZIONI DI ESCLUSIONE<\/strong><\/p>\n\n\n\n<p>Le imprese gi\u00e0 presenti alla manifestazione con un proprio stand;<\/p>\n\n\n\n<p>Le imprese morose nei confronti degli organizzatori per somme relative a precedenti manifestazioni, ovvero morose nei confronti di altri organismi in collaborazione con i quali gli organizzatori promuovono l\u2019iniziativa.<\/p>\n\n\n\n<p>Le seguenti fattispecie potranno costituire causa di esclusione, a insindacabile giudizio del Nucleo di Valutazione, alle future iniziative organizzate da Regione Lazio e Camera di Commercio di Roma nell\u2019ambito della Convenzione:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>mancata partecipazione;<\/li>\n\n\n\n<li>mancato presidio dello stand per una parte o per l\u2019intero periodo della manifestazione;<\/li>\n\n\n\n<li>accorpamento di due o pi\u00f9 stand tramite arbitraria rimozione delle pareti divisorie dei medesimi da parte di una o pi\u00f9 imprese;<\/li>\n\n\n\n<li>partecipazione di due o pi\u00f9 imprese che, pur avendo diversa partita IVA e codice fiscale, si avvalgono per il presidio dello stand della medesima persona fisica.<\/li>\n<\/ul>\n\n\n\n<p><br><strong>REGIME DI AIUTO&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;<\/strong>Per le imprese selezionate tramite il presente Avviso, la partecipazione alla manifestazione \u00e8 gratuita, fermo restando che rimangono a carico delle stesse le spese relative ad ogni ulteriore servizio extra di personalizzazione richiesto dalle imprese medesime.<\/p>\n\n\n\n<p>I costi di partecipazione sono sostenuti dagli Enti promotori e tale sostegno alle imprese si configura quale aiuto indiretto, per la partecipazione alle iniziative e manifestazioni promosse dalla Regione Lazio e Camera di Commercio di Roma, e sar\u00e0 concesso nel rispetto delle disposizioni di cui al Regolamento (UE) n. 2831 del 13 dicembre 2023 relativo all\u2019applicazione degli articoli 107 e 108 del trattato sul funzionamento dell\u2019Unione Europea agli aiuti \u201cde minimis\u201d.<\/p>\n\n\n\n<p>A seguito dell\u2019obbligo di consultazione preventiva e di implementazione del Registro Nazionale degli Aiuti di Stato, di cui al Regolamento MISE n. 115 del 31 maggio 2017, gli importi relativi alle agevolazioni concesse verranno conseguentemente inseriti nel suddetto Registro, fino ad un importo di&nbsp;massimo <strong>\u20ac 2.173,92 IVA inclusa<\/strong>, per ogni impresa ammessa. Come previsto dall\u2019art. 3 par. 7 dello stesso Regolamento, qualora la concessione di nuovi aiuti \u201cde minimis\u201d comporti il superamento dei massimali previsti, nessuna delle nuove misure di aiuto pu\u00f2 beneficiare del Regolamento. L\u2019importo massimo delle agevolazioni in regime \u201cde minimis\u201d che possono essere concesse ad un\u2019unica impresa nell\u2019arco di tre anni, senza la preventiva notifica ed autorizzazione da parte della Commissione Europea e senza che ci\u00f2 possa incidere sugli scambi tra gli Stati membri e da non falsare o minacciare di falsare la concorrenza, \u00e8 pari a \u20ac 300.000,00.&nbsp;<\/p>\n\n\n\n<p>In caso di superamento delle soglie predette, l\u2019agevolazione suindicata non potr\u00e0 essere concessa, neppure per la parte che non superi detti massimali.<\/p>\n\n\n\n<p>&nbsp;Si fa presente che ciascuna impresa pu\u00f2 monitorare l\u2019importo delle agevolazioni in regime \u201cde minimis\u201d di cui ha beneficiato a far data dal 12 agosto 2017, sul sito del Registro Nazionale degli Aiuti di Stato nella sezione Trasparenza al seguente Link: <a href=\"http:\/\/www.rna.gov.it\/RegistroNazionaleTrasparenza\/faces\/pages\/TrasparenzaAiuto.jspx\">https:\/\/www.rna.gov.it\/RegistroNazionaleTrasparenza\/faces\/pages\/TrasparenzaAiuto.jspx<\/a><\/p>\n\n\n\n<p>&nbsp;<br><strong>PRIVACY<\/strong><\/p>\n\n\n\n<p>I dati forniti saranno trattati dagli organizzatori in osservanza di quanto disposto dal Regolamento UE 679\/2016 sulla protezione dei dati personali.<\/p>\n\n\n\n<p>Per informazioni rivolgersi a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Regione Lazio <br>Lazio Innova S.p.A.<br>Area Internazionalizzazione &amp; Cluster<br>e-mail:&nbsp;<a href=\"mailto:internazionalizzazione@lazioinnova.it\">internazionalizzazione@lazioinnova.it<\/a>&nbsp;\u2013 Tel. 06.60.51.60<br><\/li>\n\n\n\n<li>Camera di Commercio di Roma:<br>Area III Promozione e Sviluppo <br>Servizio Filiere produttive e Fiere: <br>e- mail:<a href=\"mailto:attivita.promozionali@rm.camcom.it\">&nbsp;attivita.promozionali@rm.camcom.it<\/a>&nbsp;\u2013 Tel. 06.52082571 \u2013 2065<br><\/li>\n\n\n\n<li>Sviluppo e Territorio <br>Azienda Speciale della Camera di Commercio di Roma per lo sviluppo e la crescita di Roma e del Lazio: <br>e-mail <a href=\"mailto:Sviluppo@sviluppoeterritorio.camcom.it\">Sviluppo@sviluppoeterritorio.camcom.it<\/a> Tel. 066787758 &#8211; 06 69797165<\/li>\n<\/ul>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>Tutta la modulistica \u00e8 consultabile e scaricabile sui seguenti siti Istituzionali:<\/p>\n\n\n\n<p><a href=\"http:\/\/www.lazioinnova.it\/laziointernational\">www.lazioinnova.it\/laziointernational<\/a>&nbsp;<br><\/p>\n\n\n\n<p><a href=\"https:\/\/www.lazioeuropa.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.lazioeuropa.it<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.rm.camcom.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.rm.camcom.it<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/sviluppoeterritorio.camcom.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">sviluppoeterritorio.camcom.it<\/a><br><br><br><br><br><br><br><br><br><br><\/p>\n\n\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selezione di 68 imprese per la partecipazione a Casaidea (Fiera di Roma, 9-17 maggio 2026). Candidature le ore 10.00 del 16 aprile 2026<\/p>\n","protected":false},"author":11,"featured_media":22228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[45,2,269],"tags":[317,93,1046,434,193,179,396,72],"class_list":["post-22227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-finanziamenti","category-fiere-e-iniziative-internazionali","category-network","tag-arredo","tag-camera-di-commercio-di-roma","tag-casaidea","tag-cciaa-roma","tag-design","tag-fiera-di-roma","tag-pr-fesr-lazio-2021-2027","tag-regione-lazio"],"acf":{"homepage_image":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifestazione di interesse per Casaidea 2026 - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"Selezione di 68 imprese per la partecipazione a Casaidea (Fiera di Roma, 9-17 maggio 2026). Candidature le ore 10.00 del 16 aprile 2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifestazione di interesse per Casaidea 2026 - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Selezione di 68 imprese per la partecipazione a Casaidea (Fiera di Roma, 9-17 maggio 2026). Candidature le ore 10.00 del 16 aprile 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T14:54:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T12:11:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patrizia De Vincenzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrizia De Vincenzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/\"},\"author\":{\"name\":\"Patrizia De Vincenzi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"headline\":\"Manifestazione di interesse per Casaidea 2026\",\"datePublished\":\"2026-04-02T14:54:27+00:00\",\"dateModified\":\"2026-05-06T12:11:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/\"},\"wordCount\":2051,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2026\\\/04\\\/logo-casa-idea.jpg\",\"keywords\":[\"arredo\",\"Camera di Commercio di Roma\",\"Casaidea\",\"CCIAA Roma\",\"Design\",\"FIERA DI ROMA\",\"PR FESR Lazio 2021-2027\",\"Regione Lazio\"],\"articleSection\":[\"Bandi e Finanziamenti\",\"Fiere e Iniziative Internazionali\",\"Network\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/\",\"name\":\"Manifestazione di interesse per Casaidea 2026 - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2026\\\/04\\\/logo-casa-idea.jpg\",\"datePublished\":\"2026-04-02T14:54:27+00:00\",\"dateModified\":\"2026-05-06T12:11:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"description\":\"Selezione di 68 imprese per la partecipazione a Casaidea (Fiera di Roma, 9-17 maggio 2026). Candidature le ore 10.00 del 16 aprile 2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2026\\\/04\\\/logo-casa-idea.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2026\\\/04\\\/logo-casa-idea.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"CasaIdea La mostra dell'Abitare 51^ edizione 9-17 maggio Fiera Roma Ingresso Est\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2026\\\/04\\\/02\\\/manifestazione-di-interesse-per-casaidea-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifestazione di interesse per Casaidea 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\",\"name\":\"Patrizia De Vincenzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"caption\":\"Patrizia De Vincenzi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/p-devincenzi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifestazione di interesse per Casaidea 2026 - Lazio International - Lazio Innova","description":"Selezione di 68 imprese per la partecipazione a Casaidea (Fiera di Roma, 9-17 maggio 2026). Candidature le ore 10.00 del 16 aprile 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Manifestazione di interesse per Casaidea 2026 - Lazio International - Lazio Innova","og_description":"Selezione di 68 imprese per la partecipazione a Casaidea (Fiera di Roma, 9-17 maggio 2026). Candidature le ore 10.00 del 16 aprile 2026","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2026-04-02T14:54:27+00:00","article_modified_time":"2026-05-06T12:11:57+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea.jpg","type":"image\/jpeg"}],"author":"Patrizia De Vincenzi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Patrizia De Vincenzi","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/"},"author":{"name":"Patrizia De Vincenzi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"headline":"Manifestazione di interesse per Casaidea 2026","datePublished":"2026-04-02T14:54:27+00:00","dateModified":"2026-05-06T12:11:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/"},"wordCount":2051,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea.jpg","keywords":["arredo","Camera di Commercio di Roma","Casaidea","CCIAA Roma","Design","FIERA DI ROMA","PR FESR Lazio 2021-2027","Regione Lazio"],"articleSection":["Bandi e Finanziamenti","Fiere e Iniziative Internazionali","Network"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/","name":"Manifestazione di interesse per Casaidea 2026 - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea.jpg","datePublished":"2026-04-02T14:54:27+00:00","dateModified":"2026-05-06T12:11:57+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"description":"Selezione di 68 imprese per la partecipazione a Casaidea (Fiera di Roma, 9-17 maggio 2026). Candidature le ore 10.00 del 16 aprile 2026","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea.jpg","width":2560,"height":1440,"caption":"CasaIdea La mostra dell'Abitare 51^ edizione 9-17 maggio Fiera Roma Ingresso Est"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2026\/04\/02\/manifestazione-di-interesse-per-casaidea-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Manifestazione di interesse per Casaidea 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758","name":"Patrizia De Vincenzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","caption":"Patrizia De Vincenzi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea-600x400.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2026\/04\/logo-casa-idea-600x600.jpg","author_info":{"display_name":"Patrizia De Vincenzi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/22227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=22227"}],"version-history":[{"count":11,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/22227\/revisions"}],"predecessor-version":[{"id":22430,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/22227\/revisions\/22430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/22228"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=22227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=22227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=22227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}