{"id":2420,"date":"2020-04-23T00:00:00","date_gmt":"2020-04-22T22:00:00","guid":{"rendered":"http:\/\/www.laziointernational.it\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/"},"modified":"2020-04-23T00:00:00","modified_gmt":"2020-04-22T22:00:00","slug":"opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/","title":{"rendered":"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale"},"content":{"rendered":"<p>\n\tIl Governo statunitense, per il tramite dell&rsquo;Agenzia Federale USAID (United States Agency for International Development), ha recentemente messo in campo un&rsquo; importante iniziativa a beneficio del sistema sanitario italiano e delle aziende del comparto medicale.<\/p>\n<p>\n\tIl programma di assistenza finanziaria dell&rsquo;USAID, finalizzato a fronteggiare l&rsquo;emergenza epidemiologica in atto e a sviluppare la capacit&agrave; produttiva del tessuto industriale italiano, prevede stanziamenti complessivi per 50 milioni di dollari, destinati a:<\/p>\n<ol>\n<li>\n\t\t<u>Rafforzare la sicurezza sanitaria<\/u>, in particolare attraverso la fornitura al servizio sanitario nazionale di attrezzature e dispositivi medici da distribuzione in favore della popolazione (10 milioni di dollari);<\/li>\n<li>\n\t\t<u>Sostenere la societ&agrave; civile<\/u>, mediante il supporto alle istituzioni pubbliche e alle associazioni del terzo settore, impegnate nel mitigare gli effetti sociali ed economici della pandemia sulla collettivit&agrave; (30 milioni di dollari)<\/li>\n<li>\n\t\t<u>Supportare le imprese italiane<\/u> che abbiano varato o intendano varare progetti di ricerca, sviluppo e produzione di terapie, vaccini, attrezzature e forniture mediche tese a fronteggiare il virus Sars-Cov2, ivi compresi gli interventi volti a modificare le attivit&agrave; e le filiere produttive per orientarle verso la domanda di prodotti e servizi provenienti dal personale medico e dai pazienti (10 milioni di dollari).<\/li>\n<\/ol>\n<p>\n\tCon specifico riferimento alla citata finalit&agrave; 3 riservata alla imprese, l&rsquo;intervento dell&rsquo;USAID si realizzer&agrave; attraverso il programma &ldquo;INVEST&rdquo; ed &egrave; subordinato alla presentazione da parte delle imprese italiane interessate di un&rsquo;autocandidatura, nella quale dovranno essere fornite alcune informazioni sull&rsquo;attivit&agrave; svolta e sul contesto di riferimento, secondo lo schema riportato nell&rsquo;Appendice A del documento &ldquo;USAID_Invest_RFI&rdquo; (PDF ALLEGATO V. SOTTO).<\/p>\n<p>\n\tSi segnala che tali autocandidature dovranno essere trasmesse entro le ore 13:00 del giorno 27 aprile p.v. all&rsquo;indirizzo di posta elettronica <a href=\"mailto:INVEST_Procurement@dai.com\" target=\"_blank\">INVEST_Procurement@dai.com<\/a> e, in copia conoscenza, ai seguenti indirizzi: a <a href=\"mailto:katherine_tilahun@dai.com\" target=\"_blank\">katherine_tilahun@dai.com<\/a>, <a href=\"mailto:matthew_mitchell@dai.com\" target=\"_blank\">matthew_mitchell@dai.com<\/a> e <a href=\"mailto:talin_baghdadlian@dai.com\" target=\"_blank\">talin_baghdadlian@dai.com<\/a>, nonch&eacute; all&rsquo;indirizzo <a href=\"mailto:dgsp-01@esteri.it\" target=\"_blank\">dgsp-01@esteri.it<\/a><\/p>\n<p>\n\tLa mail, infine, dovr&agrave; riportare nell&rsquo;oggetto il riferimento &ldquo;Response to RFI INVEST-005&rdquo;.<\/p>\n<p>\n\t<span style=\"font-size:14px;\"><span style=\"color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; text-align: justify;\">LinkedIn: partecipa alla discussione e rimani aggiornato attraverso il gruppo LinkedIn della&nbsp;<\/span><strong style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; font-size: 16.0016px; text-align: justify;\">Community degli Innovatori della Regione Lazio&nbsp;<\/strong><span style=\"color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; text-align: justify;\">dedicata alle&nbsp;<\/span><strong style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; font-size: 16.0016px; text-align: justify;\">Scienze della Vita<\/strong><span style=\"color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; text-align: justify;\">&nbsp;<\/span><a href=\"https:\/\/www.linkedin.com\/groups\/8846745\/\" style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; text-decoration-line: none; color: rgb(18, 110, 175); font-family: Calibri, Arial, sans-serif; font-size: 16.0016px; text-align: justify;\">https:\/\/www.linkedin.com\/groups\/8846745\/&nbsp;&nbsp;<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Governo statunitense, per il tramite dell\u2019Agenzia Federale USAID (United States Agency for International Development), ha recentemente messo in campo un\u2019 importante iniziativa a beneficio del sistema sanitario italiano e delle aziende del comparto medicale.<\/p>\n","protected":false},"author":1,"featured_media":2421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[45],"tags":[54,47,42,19,62],"class_list":["post-2420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-finanziamenti","tag-bandi-aperti","tag-bioscienze","tag-ict","tag-multisettore","tag-smart-cities-tech"],"acf":{"homepage_image":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Il Governo statunitense, per il tramite dell\u2019Agenzia Federale USAID (United States Agency for International Development), ha recentemente messo in campo un\u2019 importante iniziativa a beneficio del sistema sanitario italiano e delle aziende del comparto medicale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-22T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"headline\":\"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale\",\"datePublished\":\"2020-04-22T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/\"},\"wordCount\":388,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/usaid.png\",\"keywords\":[\"Bandi aperti\",\"Bioscienze\",\"ICT\",\"Multisettore\",\"Smart Cities &amp; Tech\"],\"articleSection\":[\"Bandi e Finanziamenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/\",\"name\":\"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/usaid.png\",\"datePublished\":\"2020-04-22T22:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/usaid.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/usaid.png\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2020\\\/04\\\/23\\\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.laziointernational.it\\\/wp\"],\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/","og_locale":"it_IT","og_type":"article","og_title":"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale - Lazio International - Lazio Innova","og_description":"Il Governo statunitense, per il tramite dell\u2019Agenzia Federale USAID (United States Agency for International Development), ha recentemente messo in campo un\u2019 importante iniziativa a beneficio del sistema sanitario italiano e delle aziende del comparto medicale.","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2020-04-22T22:00:00+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/"},"author":{"name":"admin","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"headline":"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale","datePublished":"2020-04-22T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/"},"wordCount":388,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png","keywords":["Bandi aperti","Bioscienze","ICT","Multisettore","Smart Cities &amp; Tech"],"articleSection":["Bandi e Finanziamenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/","name":"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png","datePublished":"2020-04-22T22:00:00+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2020\/04\/23\/opportunita-dagli-usa-per-la-aziende-italiane-del-biomedicale-2850\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Opportunit\u00e0 dagli USA per la aziende italiane del biomedicale"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.laziointernational.it\/wp"],"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/usaid.png","author_info":{"display_name":"admin","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=2420"}],"version-history":[{"count":0,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/2421"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=2420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=2420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=2420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}