{"id":2788,"date":"2021-02-22T00:00:00","date_gmt":"2021-02-21T23:00:00","guid":{"rendered":"http:\/\/www.laziointernational.it\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/"},"modified":"2021-02-22T00:00:00","modified_gmt":"2021-02-21T23:00:00","slug":"webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/","title":{"rendered":"WEBINAR: Il Procurment della European Investment Bank &#8211; Opportunit\u00e0 per le imprese"},"content":{"rendered":"<p>\n\tL&#39;Agenzia ICE e OICE (Associazione delle organizzazioni italiane di ingegneria, architettura e consulenza tecnico-economica) invitano le imprese a&nbsp; partecipare al prossimo appuntamento dei Devolopment Webinars&nbsp;dedicato alle opportunita&#39; offerte dalla&nbsp;<strong>BANCA EUROPEA PER GLI INVESTIMENTI (BEI).&nbsp;<\/strong><\/p>\n<p>\n\tL&#39;incontro si svolger&agrave; online <strong>marted&igrave; 23 febbraio alle ore 10<\/strong>, previa registrazione al seguente link:&nbsp;<a href=\"https:\/\/docs.google.com\/forms\/d\/1bbz6biL6pQMWVydZ_VJq311dBCjQz3ulRVMqcGJF2Ac\/viewform?gxids=7628&amp;edit_requested=true\">WEBINAR : Opportunit&agrave; offerte dalla EUROPEAN INVESTMENT BANK | 23 Feb 2021 (google.com)<\/a><\/p>\n<p>\n\t<u><strong>Programma dei lavori:<\/strong><\/u><\/p>\n<p>\n\t<strong>10:00 &#8211; APERTURA LAVORI<\/strong><br \/>\n\t&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Roberto CARPANETO, Vicepresidente Affari Internazionali &#8211; OICE<\/p>\n<p>\t<strong>10:05&nbsp; &#8211; LA EIB, L&#39;ITALIA E NUOVI SCENARI&nbsp;<\/strong><br \/>\n\t&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Raffaele CORDINER, Invstment Officer, Development &amp; Impact Finance (EIB)<\/p>\n<p>\n\t&nbsp;<br \/>\n\t<strong>10:35 &#8211; IL PROCUREMENT DEI SERVIZI DELLA EIB<\/strong><br \/>\n\t&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Nicola DI PIETRO,&nbsp; Transport Specialist (EIB)<\/p>\n<p>\n\t&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Sonia DE GIORGIS, Contract Officer (EIB)<\/p>\n<p>\t<strong>11:15&nbsp; &#8211; Q&amp;A Session<\/strong><br \/>\n\t&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#39;Agenzia ICE e OICE (Associazione delle organizzazioni italiane di ingegneria, architettura e consulenza tecnico-economica) invitano le imprese a&nbsp; partecipare al prossimo appuntamento dei Devolopment Webinars&nbsp;dedicato alle opportunita&#39; offerte dalla&nbsp;BANCA EUROPEA PER GLI INVESTIMENTI (BEI).&nbsp; L&#39;incontro si svolger&agrave; online marted&igrave; 23 febbraio alle ore 10, previa registrazione al seguente link:&nbsp;WEBINAR : Opportunit&agrave; offerte dalla EUROPEAN INVESTMENT [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[27],"tags":[18,19,53,52],"class_list":["post-2788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formazione-ed-empowerment","tag-appuntamenti","tag-multisettore","tag-seminari-e-formazione","tag-unione-europea"],"acf":{"homepage_image":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WEBINAR: Il Procurment della European Investment Bank - Opportunit\u00e0 per le imprese - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WEBINAR: Il Procurment della European Investment Bank - Opportunit\u00e0 per le imprese - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"L&#039;Agenzia ICE e OICE (Associazione delle organizzazioni italiane di ingegneria, architettura e consulenza tecnico-economica) invitano le imprese a&nbsp; partecipare al prossimo appuntamento dei Devolopment Webinars&nbsp;dedicato alle opportunita&#039; offerte dalla&nbsp;BANCA EUROPEA PER GLI INVESTIMENTI (BEI).&nbsp; L&#039;incontro si svolger&agrave; online marted&igrave; 23 febbraio alle ore 10, previa registrazione al seguente link:&nbsp;WEBINAR : Opportunit&agrave; offerte dalla EUROPEAN INVESTMENT [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-21T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"headline\":\"WEBINAR: Il Procurment della European Investment Bank &#8211; Opportunit\u00e0 per le imprese\",\"datePublished\":\"2021-02-21T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/\"},\"wordCount\":170,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/eib.jpg\",\"keywords\":[\"Appuntamenti\",\"Multisettore\",\"Seminari e Formazione\",\"Unione Europea\"],\"articleSection\":[\"Formazione ed Empowerment\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/\",\"name\":\"WEBINAR: Il Procurment della European Investment Bank - Opportunit\u00e0 per le imprese - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/eib.jpg\",\"datePublished\":\"2021-02-21T23:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/eib.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/eib.jpg\",\"width\":960,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/02\\\/22\\\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WEBINAR: Il Procurment della European Investment Bank &#8211; Opportunit\u00e0 per le imprese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.laziointernational.it\\\/wp\"],\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WEBINAR: Il Procurment della European Investment Bank - Opportunit\u00e0 per le imprese - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/","og_locale":"it_IT","og_type":"article","og_title":"WEBINAR: Il Procurment della European Investment Bank - Opportunit\u00e0 per le imprese - Lazio International - Lazio Innova","og_description":"L&#39;Agenzia ICE e OICE (Associazione delle organizzazioni italiane di ingegneria, architettura e consulenza tecnico-economica) invitano le imprese a&nbsp; partecipare al prossimo appuntamento dei Devolopment Webinars&nbsp;dedicato alle opportunita&#39; offerte dalla&nbsp;BANCA EUROPEA PER GLI INVESTIMENTI (BEI).&nbsp; L&#39;incontro si svolger&agrave; online marted&igrave; 23 febbraio alle ore 10, previa registrazione al seguente link:&nbsp;WEBINAR : Opportunit&agrave; offerte dalla EUROPEAN INVESTMENT [&hellip;]","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2021-02-21T23:00:00+00:00","og_image":[{"width":960,"height":608,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/"},"author":{"name":"admin","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"headline":"WEBINAR: Il Procurment della European Investment Bank &#8211; Opportunit\u00e0 per le imprese","datePublished":"2021-02-21T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/"},"wordCount":170,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg","keywords":["Appuntamenti","Multisettore","Seminari e Formazione","Unione Europea"],"articleSection":["Formazione ed Empowerment"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/","name":"WEBINAR: Il Procurment della European Investment Bank - Opportunit\u00e0 per le imprese - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg","datePublished":"2021-02-21T23:00:00+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg","width":960,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/02\/22\/webinar-il-procurment-della-european-investment-bank-opportunita-per-le-imprese-3093\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"WEBINAR: Il Procurment della European Investment Bank &#8211; Opportunit\u00e0 per le imprese"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.laziointernational.it\/wp"],"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/eib.jpg","author_info":{"display_name":"admin","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=2788"}],"version-history":[{"count":0,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/2789"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=2788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=2788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=2788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}