{"id":2840,"date":"2021-03-22T00:00:00","date_gmt":"2021-03-21T23:00:00","guid":{"rendered":"http:\/\/www.laziointernational.it\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/"},"modified":"2021-03-22T00:00:00","modified_gmt":"2021-03-21T23:00:00","slug":"le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/","title":{"rendered":"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco"},"content":{"rendered":"<p>\n\t<span style=\"color: rgb(102, 102, 102); font-family: Assistant, Helvetica, Arial, Lucida, sans-serif; font-size: 14px;\">Il <strong>Presidente di Lazio Innova Nicola Tasco<\/strong> presenta, in un&nbsp;<strong>video<\/strong> prodotto dal&nbsp;<strong>CTNA (<\/strong><\/span><span style=\"font-size:14px;\">Cluster Tecnologico Nazionale Aerospazio)<\/span><span style=\"color: rgb(102, 102, 102); font-family: Assistant, Helvetica, Arial, Lucida, sans-serif; font-size: 14px;\">, le attivit&agrave; del <\/span><strong style=\"color: rgb(102, 102, 102); font-family: Assistant, Helvetica, Arial, Lucida, sans-serif; font-size: 14px;\">Distretto Tecnologico Aerospaziale del Lazio<\/strong><span style=\"color: rgb(102, 102, 102); font-family: Assistant, Helvetica, Arial, Lucida, sans-serif; font-size: 14px;\">, un territorio che ospita l&rsquo;Agenzia Spaziale Italiana, la sede italiana dell&rsquo;Agenzia Spaziale Europea, 8 Enti di ricerca, 4 Universit&agrave; e aziende di rilevanza globale dell&#39;industria aerospaziale. <\/span><\/p>\n<p>\n\t<span style=\"color: rgb(102, 102, 102); font-family: Assistant, Helvetica, Arial, Lucida, sans-serif; font-size: 14px;\">Il Lazio ospita tutta la filiera della cosidetta <strong>space economy <\/strong>ed &egrave; sede del&nbsp;<strong>Tecnopolo Tiburtino <\/strong>e di<strong> ESA BIC<\/strong>, incubatori della Regione Lazio in ambito aerospaziale. <\/span><\/p>\n<p>\n\t<span style=\"color: rgb(102, 102, 102); font-family: Assistant, Helvetica, Arial, Lucida, sans-serif; font-size: 14px;\"><strong>Importante per il futuro sar&agrave; l&#39;incontro tra stakeholders consolidati, l&#39;innovazione e le startup regionali,<\/strong> come si auspica possa avvenire con il recente lancio della <strong>Challange di Thales Alenia Space Italia<\/strong>, attraverso la quale l&#39;Azienda punta a trovare soluzioni innovative di intelligenza artificiale da impiegare a bordo di satelliti.<\/span><\/p>\n<p>\n\t<span style=\"font-size:14px;\"><strong>Scopri di pi&ugrave;, guarda il video su YouTube:<\/strong>&nbsp;<a href=\"https:\/\/www.ctna.it\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco\/\"><span style=\"background-color:#ffff00;\">Le attivit&agrave; del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco | CTNA<\/span><\/a><\/span><\/p>\n<p>\n\t&nbsp;<\/p>\n<p>\n\t<span style=\"font-family: Calibri, sans-serif; text-align: center; background-color: rgb(238, 238, 238); color: rgb(1, 29, 50); font-size: 16.0016px;\">Anche sulle pagine&nbsp;<\/span><strong style=\"font-family: Calibri, sans-serif; text-align: center; background-color: rgb(238, 238, 238); color: rgb(1, 29, 50); font-size: 16.0016px; transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\">LinkedIn della Comunit&agrave; degli Innovatori&nbsp;del Lazio<\/strong><span style=\"font-family: Calibri, sans-serif; text-align: center; background-color: rgb(238, 238, 238); color: rgb(1, 29, 50); font-size: 16.0016px;\">&nbsp;trovi tutte le iniziative della Regione Lazio e le opportunit&agrave; promosse da Lazio Innova a supporto di Startup e PMI innovative. Se non l&#39;hai ancora fatto, entra a far parte della Comunit&agrave; degli Innovatori dedicata agli ecosistemi produttivi regionali ad alta intensit&agrave; di R&amp;S ed innovazione tecnologica:<\/span><\/p>\n<p style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; margin: 12pt 0cm; color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; font-size: 16.0016px; background: rgb(238, 238, 238); text-align: center;\">\n\t<strong style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\"><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\">Aerospazio e Sicurezza &#8211;&nbsp;<\/span><\/strong><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\"><a href=\"https:\/\/www.linkedin.com\/groups\/8847462\/\" style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; text-decoration-line: none; color: rgb(18, 110, 175);\"><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\">https:\/\/www.linkedin.com\/groups\/8847462\/<\/span><\/a><o:p style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\"><\/o:p><\/span><\/p>\n<p style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; margin: 12pt 0cm; color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; font-size: 16.0016px; background: rgb(238, 238, 238); text-align: center;\">\n\t<strong style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\"><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\">Scienze della Vita &#8211;&nbsp;<\/span><\/strong><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\"><a href=\"https:\/\/www.linkedin.com\/groups\/8846745\/\" style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; text-decoration-line: none; color: rgb(18, 110, 175);\"><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\">https:\/\/www.linkedin.com\/groups\/8846745\/<\/span><\/a><o:p style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\"><\/o:p><\/span><\/p>\n<p style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; margin: 12pt 0cm; color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; font-size: 16.0016px; background: rgb(238, 238, 238); text-align: center;\">\n\t<strong style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\"><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\">Tecnologie della Cultura &#8211;&nbsp;<\/span><\/strong><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\"><a href=\"https:\/\/www.linkedin.com\/groups\/12308461\/\" style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; text-decoration-line: none; color: rgb(18, 110, 175);\"><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\">https:\/\/www.linkedin.com\/groups\/12308461\/<\/span><\/a><o:p style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\"><\/o:p><\/span><\/p>\n<p style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; margin: 12pt 0cm; color: rgb(1, 29, 50); font-family: Calibri, Arial, sans-serif; font-size: 16.0016px; background: rgb(238, 238, 238); text-align: center;\">\n\t<strong style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s;\"><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\">Blue Growth &#8211;&nbsp;<\/span><\/strong><span style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; font-family: Calibri, sans-serif;\"><a href=\"https:\/\/www.linkedin.com\/groups\/8948257\/\" style=\"transition: color 0.5s ease 0s, background-color 0.5s ease 0s; text-decoration-line: none; color: rgb(18, 110, 175);\">https:\/\/www.linkedin.com\/groups\/8948257\/<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente di Lazio Innova Nicola Tasco presenta, in un&nbsp;video prodotto dal&nbsp;CTNA (Cluster Tecnologico Nazionale Aerospazio), le attivit&agrave; del Distretto Tecnologico Aerospaziale del Lazio, un territorio che ospita l&rsquo;Agenzia Spaziale Italiana, la sede italiana dell&rsquo;Agenzia Spaziale Europea, 8 Enti di ricerca, 4 Universit&agrave; e aziende di rilevanza globale dell&#39;industria aerospaziale. Il Lazio ospita tutta la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[27],"tags":[32,42,19,53,62],"class_list":["post-2840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formazione-ed-empowerment","tag-aerospazio","tag-ict","tag-multisettore","tag-seminari-e-formazione","tag-smart-cities-tech"],"acf":{"homepage_image":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Il Presidente di Lazio Innova Nicola Tasco presenta, in un&nbsp;video prodotto dal&nbsp;CTNA (Cluster Tecnologico Nazionale Aerospazio), le attivit&agrave; del Distretto Tecnologico Aerospaziale del Lazio, un territorio che ospita l&rsquo;Agenzia Spaziale Italiana, la sede italiana dell&rsquo;Agenzia Spaziale Europea, 8 Enti di ricerca, 4 Universit&agrave; e aziende di rilevanza globale dell&#039;industria aerospaziale. Il Lazio ospita tutta la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-21T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"headline\":\"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco\",\"datePublished\":\"2021-03-21T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/\"},\"wordCount\":282,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/dca.png\",\"keywords\":[\"Aerospazio\",\"ICT\",\"Multisettore\",\"Seminari e Formazione\",\"Smart Cities &amp; Tech\"],\"articleSection\":[\"Formazione ed Empowerment\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/\",\"name\":\"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/dca.png\",\"datePublished\":\"2021-03-21T23:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/dca.png\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2021\\\/11\\\/dca.png\",\"width\":1024,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/03\\\/22\\\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.laziointernational.it\\\/wp\"],\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/","og_locale":"it_IT","og_type":"article","og_title":"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco - Lazio International - Lazio Innova","og_description":"Il Presidente di Lazio Innova Nicola Tasco presenta, in un&nbsp;video prodotto dal&nbsp;CTNA (Cluster Tecnologico Nazionale Aerospazio), le attivit&agrave; del Distretto Tecnologico Aerospaziale del Lazio, un territorio che ospita l&rsquo;Agenzia Spaziale Italiana, la sede italiana dell&rsquo;Agenzia Spaziale Europea, 8 Enti di ricerca, 4 Universit&agrave; e aziende di rilevanza globale dell&#39;industria aerospaziale. Il Lazio ospita tutta la [&hellip;]","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2021-03-21T23:00:00+00:00","og_image":[{"width":1024,"height":540,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/"},"author":{"name":"admin","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"headline":"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco","datePublished":"2021-03-21T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/"},"wordCount":282,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png","keywords":["Aerospazio","ICT","Multisettore","Seminari e Formazione","Smart Cities &amp; Tech"],"articleSection":["Formazione ed Empowerment"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/","name":"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png","datePublished":"2021-03-21T23:00:00+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png","width":1024,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/03\/22\/le-attivita-del-distretto-aerospaziale-del-lazio-illustrate-dal-presidente-nicola-tasco-3123\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Le attivit\u00e0 del Distretto Aerospaziale del Lazio illustrate dal Presidente Nicola Tasco"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.laziointernational.it\/wp"],"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2021\/11\/dca.png","author_info":{"display_name":"admin","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=2840"}],"version-history":[{"count":0,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/2841"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=2840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=2840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=2840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}