{"id":2991,"date":"2021-06-04T00:00:00","date_gmt":"2021-06-03T22:00:00","guid":{"rendered":"http:\/\/www.laziointernational.it\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/"},"modified":"2022-07-25T17:57:26","modified_gmt":"2022-07-25T15:57:26","slug":"hong-kong-international-medical-and-healthcare-fair-3211","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/","title":{"rendered":"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR"},"content":{"rendered":"<p align=\"center\">\n\t&nbsp;<\/p>\n<p align=\"center\">\n\t<strong>Scadenza presentazione domande 30 giugno 2021<\/strong><\/p>\n<p>\n\tSiamo lieti di informare che anche nel 2021 l&rsquo;ICE &ndash; Agenzia per la promozione all&rsquo;estero e l&rsquo;internazionalizzazione delle imprese italiane, &#8211; Ufficio di Hong Kong &#8211; nell&rsquo;ambito dell&rsquo;accordo di rappresentanza e del mandato di agenzia per l&rsquo;Italia sottoscritto con l&rsquo;ente fiera Hong Kong Trade Development Council (HKTDC), curer&agrave; la partecipazione delle aziende italiane alla <strong>12^ edizione dell&rsquo;Hong Kong International Medical and Healthcare Fair.<\/strong> <strong>La fiera si svolger&agrave; dal 13 al 16 ottobre 2021, <\/strong>presso l&#39;Hong Kong Convention and Exhibition Centre 1 Expo Drive, Wan Chai, Hong Kong, Harbour Road Entrance; la scorsa edizione 2019 (edizione 2020 e&rsquo; stata cancellata a cause della pandemia) ha occupato una superficie di circa 4.500 mq, registrando un totale di 285 espositori provenienti da tutto il mondo e visitata da circa 12.500 buyer. La manifestazione, fiera internazionale per le attrezzature mediche ed ospedaliere, ammette le seguenti principali&nbsp;&nbsp;categorie merceologiche:<\/p>\n<p align=\"center\">\n\t&nbsp;<\/p>\n<ul>\n<li>\n\t\t<em><u>Epidemic Prevention &amp; Control<\/u><\/em><\/li>\n<li>\n\t\t<em><u>Building Technology and Hospital Furniture<\/u><\/em><\/li>\n<li>\n\t\t<em><u>Hospital Equipment<\/u><\/em><\/li>\n<li>\n\t\t<em><u>Rehabilitation and Elderly Care<\/u><\/em><\/li>\n<li>\n\t\t<em><u>Medical Supplies and Disposables<\/u><\/em><\/li>\n<li>\n\t\t<em><u>Trade Services and Publications<\/u><\/em><\/li>\n<li>\n\t\t<em><u>World of Health &amp; Wellness<\/u><\/em><\/li>\n<li>\n\t\t<em><u>Laboratory Equipment &amp; Manufacturing Solutions Zone<\/u><\/em><\/li>\n<li>\n\t\t<em><u>Biotechnology<\/u><\/em><\/li>\n<\/ul>\n<p>\n\tMaggiori dettagli sulle citate categorie sono visionabili alla seguente pagina: <a href=\"http:\/\/mx-2.lazioinnova.it:32224\/?dmVyPTEuMDAxJiYyMTUxMzJlNWQ2MjYwMWU3NT02MEI5QTFCQ18yMTQxOV81MDgyXzEmJmZlYzQ2Zjk1MzRkZTcxMT0xMjMzJiZ1cmw9aHR0cHMlM0ElMkYlMkZldmVudCUyRWhrdGRjJTJFY29tJTJGZmFpciUyRmhrbWVkaWNhbGZhaXItZW4lMkZzJTJGMjU3Ny1HZW5lcmFsJTVGSW5mb3JtYXRpb24lMkZIS1REQy1Ib25nLUtvbmctSW50ZXJuYXRpb25hbC1NZWRpY2FsLWFuZC1IZWFsdGhjYXJlLUZhaXIlMkZGYWlyLURldGFpbHMlMkVodG1s\">https:\/\/event.hktdc.com\/fair\/hkmedicalfair-en\/s\/2577-General_Information\/HKTDC-Hong-Kong-International-Medical-and-Healthcare-Fair\/Fair-Details.html<\/a><\/p>\n<p>\n\tPrecisiamo che la Hong Kong International Medical and Healthcare Fair non fa parte delle iniziative promozionali in cui ICE \/ Agenzia organizza una partecipazione collettiva di imprese italiane. L&rsquo;ufficio di Hong Kong di ICE Agenzia, nell&rsquo;ambito del mandato di agenzia per l&rsquo;Italia con Ente Fiera Hong Kong Trade Development Council (HKTDC), cura i rapporti delle aziende italiane che volessero partecipare alla fiera con HKTDC, che pertanto rimane la sola controparte contrattuale delle imprese italiane partecipanti.<\/p>\n<p>\n\t<strong><u>In considerazione della attuale situazione pandemica, ad oggi &egrave; consentito l&rsquo;ingresso a Hong Kong ai soli residenti (<a href=\"http:\/\/www.viaggiaresicuri.it\/country\/HKG\">http:\/\/www.viaggiaresicuri.it\/country\/HKG<\/a>).<\/u><\/strong><\/p>\n<p>\n\t<strong><u>Salvo ulteriori provvedimenti nei prossimi mesi, allo stato attuale, le aziende italiane interessate potranno pertanto partecipare alla fiera solo tramite un proprio agente, rappresentante o referente in loco<\/u><\/strong><\/p>\n<p>\n\tIl settore delle attrezzature mediche ed ospedaliere e&rsquo; uno settori di cui viene previsto un grande sviluppo nella cosiddetta Greater Bay Area, (un&rsquo; area di 70 milioni di abitanti e che comprende le 2 citta&rsquo; a regime amministrativo speciale &#8211; Hong Kong, Macao&nbsp;&nbsp;&#8211;&nbsp;&nbsp;e 9 citta&rsquo; della provincia del Guangdong)<\/p>\n<p>\n\tLa spesa in Healthcare ad Hong Kong e&rsquo; prevista raddoppiare dai circa 20 miliardi di&nbsp;&nbsp;euro ai 40 miliardi di Euro nel 2033 (ref:&nbsp;<strong>&nbsp;&ldquo;Healthcare spending may double to $315b by 2033&rdquo;<\/strong> &#8211; articolo pubblicato su Hong Kong Business <a href=\"http:\/\/mx-2.lazioinnova.it:32224\/?dmVyPTEuMDAxJiYzZTEwMzRlOWMwMzcxMWEwNT02MEI5QTFCQ18yMTQxOV81MDgyXzEmJjJlNjU4YTUxYjQ0ZTU0Yz0xMjMzJiZ1cmw9aHR0cHMlM0ElMkYlMkZob25na29uZ2J1c2luZXNzJTJFaGslMkZoZWFsdGhjYXJlJTJGbmV3cyUyRmhlYWx0aGNhcmUtc3BlbmRpbmctbWF5LWRvdWJsZS0zMTViLTIwMzMlMjk=\">https:\/\/hongkongbusiness.hk\/healthcare\/news\/healthcare-spending-may-double-315b-2033)<\/a><\/p>\n<p>\n\tL&rsquo;ufficio di Hong Kong dell&rsquo;ICE-Agenzia offrira&rsquo; alle aziende italiane che desiderano partecipare alla Fiera servizi di informazione ed assistenza tecnico-organizzativa ed amministrativa, curando per loro conto i rapporti con l&rsquo;ente fiera HKTDC.<\/p>\n<p>\n\tIn condizioni normali il costo standard di partecipazione con uno stand pre-allestito base (standard booth, 9 mq) sarebbe di USD 4.165.<\/p>\n<p>\n\tE&rsquo; possibile prenotare anche <strong><u>l&rsquo;area nuda<\/u><\/strong>, con allestimento a carico dell&rsquo; espositore, al costo di USD413 al mq, per un minimo di 18 mq. Il costo delle diverse tipologie di stand e&rsquo; visionabile on-line alla seguente pagina:&nbsp;<a href=\"http:\/\/mx-2.lazioinnova.it:32224\/?dmVyPTEuMDAxJiYyMTUxMzJlNWQ2MjYwMWU3NT02MEI5QTFCQ18yMTQxOV81MDgyXzEmJmZlYzQ2Zjk1MzRkZTcxMT0xMjMzJiZ1cmw9aHR0cHMlM0ElMkYlMkZldmVudCUyRWhrdGRjJTJFY29tJTJGZmFpciUyRmhrbWVkaWNhbGZhaXItZW4lMkZzJTJGMjUxNS1Gb3IlNUZFeGhpYml0b3IlMkZIS1REQy1Ib25nLUtvbmctSW50ZXJuYXRpb25hbC1NZWRpY2FsLWFuZC1IZWFsdGhjYXJlLUZhaXIlMkZQYXJ0aWNpcGF0aW9uLUZlZS0lMjZhbXAlM0ItRm9ybWF0JTJFaHRtbA==\">https:\/\/event.hktdc.com\/fair\/hkmedicalfair-en\/s\/2515-For_Exhibitor\/HKTDC-Hong-Kong-International-Medical-and-Healthcare-Fair\/Participation-Fee-&amp;-Format.html<\/a><\/p>\n<p>\n\tIl &ldquo;Convention and Exhibition Industry Subsidy Scheme (C&amp;E)&rdquo;, attivato dal Governo di Hong Kong per supportare il sistema fieristico prevede, per ciascun espositore, senza alcun prerequisito, il sussidio di USD1.282 per uno stand di 9 mq, fino ad un massimo di USD 12.820 per 10 stand.<\/p>\n<p>\n\tCon questa modalita&rsquo; il costo per uno stand di 9mq e&rsquo; pari a <strong><u>USD 2.883.<\/u><\/strong><\/p>\n<p>\n\t<strong>Per le adesioni pervenute entro il 30 giugno (Sconto Early Bird), e&rsquo; prevista una quota di partecipazione ulteriormente scontata per uno stand di 9mq, pari a <\/strong><strong><u>USD 2.466,50<\/u><\/strong><strong>.<\/strong><\/p>\n<p align=\"center\">\n\t<strong><u>PROCEDURA PER L&rsquo;ADESIONE<\/u><\/strong><\/p>\n<p>\n\tLe aziende italiane che desiderano partecipare alla manifestazione dovranno compilare il modulo online HKTDC al seguente link.<\/p>\n<p>\n\t<a href=\"http:\/\/mx-2.lazioinnova.it:32224\/?dmVyPTEuMDAxJiYzZDE0MmVlYWMxNmMwMWE2NT02MEI5QTFCQ18yMTQxOV81MDgyXzEmJjFhYzRkYjc1YzVlZWYxMz0xMjMzJiZ1cmw9aHR0cHMlM0ElMkYlMkZ3d3clMkVoa3RkYyUyRWNvbSUyRmZhaXJhcHBsaWNhdGlvbiUyRmVvYSUyRmxvZ2luJTJFaHRtJTNGZmFpcklkJTNEMTg3MQ==\">https:\/\/www.hktdc.com\/fairapplication\/eoa\/login.htm?fairId=1871<\/a><\/p>\n<p>\n\t<strong><u>Una volta compilato, la copia di modulo dovra&rsquo; poi essere inoltrata all&rsquo;Ufficio ICE-Hong Kong (<a href=\"mailto:hongkong@ice.it\">hongkong@ice.it<\/a>)&nbsp;&nbsp;&nbsp;che provvedera&rsquo; ad avviare l&#39;iter d&#39;iscrizione all&#39;evento con l&#39;ente fiera entro e non oltre venerd&igrave; 30 giugno 2021.<\/u><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Scadenza presentazione domande 30 giugno 2021 Siamo lieti di informare che anche nel 2021 l&rsquo;ICE &ndash; Agenzia per la promozione all&rsquo;estero e l&rsquo;internazionalizzazione delle imprese italiane, &#8211; Ufficio di Hong Kong &#8211; nell&rsquo;ambito dell&rsquo;accordo di rappresentanza e del mandato di agenzia per l&rsquo;Italia sottoscritto con l&rsquo;ente fiera Hong Kong Trade Development Council (HKTDC), curer&agrave; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[37,2],"tags":[47],"class_list":["post-2991","post","type-post","status-publish","format-standard","hentry","category-altri-appuntamenti","category-fiere-e-iniziative-internazionali","tag-bioscienze"],"acf":{"homepage_image":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Scadenza presentazione domande 30 giugno 2021 Siamo lieti di informare che anche nel 2021 l&rsquo;ICE &ndash; Agenzia per la promozione all&rsquo;estero e l&rsquo;internazionalizzazione delle imprese italiane, &#8211; Ufficio di Hong Kong &#8211; nell&rsquo;ambito dell&rsquo;accordo di rappresentanza e del mandato di agenzia per l&rsquo;Italia sottoscritto con l&rsquo;ente fiera Hong Kong Trade Development Council (HKTDC), curer&agrave; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-03T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T15:57:26+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"headline\":\"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR\",\"datePublished\":\"2021-06-03T22:00:00+00:00\",\"dateModified\":\"2022-07-25T15:57:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/\"},\"wordCount\":743,\"keywords\":[\"Bioscienze\"],\"articleSection\":[\"Altri appuntamenti\",\"Fiere e Iniziative Internazionali\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/\",\"name\":\"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"datePublished\":\"2021-06-03T22:00:00+00:00\",\"dateModified\":\"2022-07-25T15:57:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2021\\\/06\\\/04\\\/hong-kong-international-medical-and-healthcare-fair-3211\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.laziointernational.it\\\/wp\"],\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/","og_locale":"it_IT","og_type":"article","og_title":"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR - Lazio International - Lazio Innova","og_description":"&nbsp; Scadenza presentazione domande 30 giugno 2021 Siamo lieti di informare che anche nel 2021 l&rsquo;ICE &ndash; Agenzia per la promozione all&rsquo;estero e l&rsquo;internazionalizzazione delle imprese italiane, &#8211; Ufficio di Hong Kong &#8211; nell&rsquo;ambito dell&rsquo;accordo di rappresentanza e del mandato di agenzia per l&rsquo;Italia sottoscritto con l&rsquo;ente fiera Hong Kong Trade Development Council (HKTDC), curer&agrave; [&hellip;]","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2021-06-03T22:00:00+00:00","article_modified_time":"2022-07-25T15:57:26+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/"},"author":{"name":"admin","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"headline":"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR","datePublished":"2021-06-03T22:00:00+00:00","dateModified":"2022-07-25T15:57:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/"},"wordCount":743,"keywords":["Bioscienze"],"articleSection":["Altri appuntamenti","Fiere e Iniziative Internazionali"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/","name":"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"datePublished":"2021-06-03T22:00:00+00:00","dateModified":"2022-07-25T15:57:26+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2021\/06\/04\/hong-kong-international-medical-and-healthcare-fair-3211\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"HONG KONG INTERNATIONAL MEDICAL AND HEALTHCARE FAIR"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.laziointernational.it\/wp"],"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"admin","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=2991"}],"version-history":[{"count":1,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2991\/revisions"}],"predecessor-version":[{"id":6619,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/2991\/revisions\/6619"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=2991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=2991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=2991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}