{"id":4525,"date":"2022-02-17T15:12:39","date_gmt":"2022-02-17T14:12:39","guid":{"rendered":"https:\/\/www.laziointernational.it\/?p=4525"},"modified":"2022-02-17T15:12:42","modified_gmt":"2022-02-17T14:12:42","slug":"technology-transfer-in-life-sciences-training-workshop","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/","title":{"rendered":"Technology Transfer in Life Sciences &#8211;  Training workshop"},"content":{"rendered":"\n<p>23rd and 24th February 2022 &#8211; Phygital event @ Human Technopole<br><\/p>\n\n\n\n<p>Il Centro per l&#8217;Innovazione e il Trasferimento Tecnologico nel campo delle Scienze della Vita (CITT), dipartimento interno della Fondazione Human Technopole, inaugurer\u00e0 le sue attivit\u00e0 il <strong>23 e 24 febbraio<\/strong> con un workshop formativo gratuito, <strong><em>Technology Transfer in Life Sciences &#8211; Training workshop<\/em><\/strong>, dedicato a giovani ricercatori, realizzato in collaborazione con Netval e IUSS Pavia. <\/p>\n\n\n\n<p>Il seminario intende&nbsp;offrire una introduzione al tema e una panoramica delle competenze necessarie per gestire al meglio il <strong>trasferimento della conoscenza dai laboratori al mercato. <\/strong><\/p>\n\n\n\n<p>Tale evento si terr\u00e0 presso Human Technopole (Viale Rita Levi Montalcini, 1 &#8211; Milano. Area MIND), nel rispetto delle disposizioni Covid, e sar\u00e0 prevista la possibilit\u00e0 di collegarsi in remoto. La partecipazione in presenza, purtroppo, \u00e8 gi\u00e0 chiusa, ma <strong>\u00e8 possibile seguirlo online iscrivendosi al <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=bbK5r9zdvkiEI6MophhsG_-4pzL-PttMvrSQJlA40uRUNUg2QzdPQldYNkE0VlkwRElUVktMNTMzNi4u&amp;wdLOR=cA8E0FE83-F980-4CED-BD9A-7424E98CF3E0\" target=\"_blank\" rel=\"noreferrer noopener\">seguente link,<\/a> <u>entro il 20 febbraio<\/u>:<\/strong><\/p>\n\n\n\n<p>Per maggiori informazioni, \u00e8 possibile collegarsi al link alla pagina dedicata sul <a href=\"https:\/\/humantechnopole.it\/it\/news\/trasferimento-tecnologico-nelle-scienze-della-vita-workshop\/\" target=\"_blank\" rel=\"noreferrer noopener\">sito di Human Technopole<\/a><\/p>\n\n\n\n<p><strong>PROGRAMMA<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.laziointernational.it\/wp-content\/uploads\/2022\/02\/Program_TT-training-event-HT_Netval_IUSS-Pavia.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporamento di Incorporamento di Program_TT-training-event-HT_Netval_IUSS-Pavia..\"><\/object><a href=\"https:\/\/www.laziointernational.it\/wp-content\/uploads\/2022\/02\/Program_TT-training-event-HT_Netval_IUSS-Pavia.pdf\">Program_TT-training-event-HT_Netval_IUSS-Pavia<\/a><a href=\"https:\/\/www.laziointernational.it\/wp-content\/uploads\/2022\/02\/Program_TT-training-event-HT_Netval_IUSS-Pavia.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"r3jTZWO7kd\"><a href=\"https:\/\/humantechnopole.it\/it\/news\/trasferimento-tecnologico-nelle-scienze-della-vita-workshop\/\">Trasferimento tecnologico nelle scienze della vita &#8211; Workshop<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Trasferimento tecnologico nelle scienze della vita &#8211; Workshop&#8221; &#8212; Human Technopole\" src=\"https:\/\/humantechnopole.it\/it\/news\/trasferimento-tecnologico-nelle-scienze-della-vita-workshop\/embed\/#?secret=Nhv07wRHQf#?secret=r3jTZWO7kd\" data-secret=\"r3jTZWO7kd\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Human Technopole: il seminario affronta il tema del trasferimento della conoscenza dai laboratori al mercato.<\/p>\n","protected":false},"author":14,"featured_media":4527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[27],"tags":[167,156,53,184],"class_list":["post-4525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formazione-ed-empowerment","tag-healthcare","tag-lifesciences","tag-seminari-e-formazione","tag-technology-transfer"],"acf":{"homepage_image":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Technology Transfer in Life Sciences - Training workshop - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technology Transfer in Life Sciences - Training workshop - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Human Technopole: il seminario affronta il tema del trasferimento della conoscenza dai laboratori al mercato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T14:12:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T14:12:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federica San\u00f2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federica San\u00f2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/\"},\"author\":{\"name\":\"Federica San\u00f2\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/5d1178a88b916d4e208c2f7f7880adb7\"},\"headline\":\"Technology Transfer in Life Sciences &#8211; Training workshop\",\"datePublished\":\"2022-02-17T14:12:39+00:00\",\"dateModified\":\"2022-02-17T14:12:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/\"},\"wordCount\":172,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/02\\\/ht_palazzo12-2048x1368-1.jpg\",\"keywords\":[\"healthcare\",\"lifesciences\",\"Seminari e Formazione\",\"technology transfer\"],\"articleSection\":[\"Formazione ed Empowerment\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/\",\"name\":\"Technology Transfer in Life Sciences - Training workshop - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/02\\\/ht_palazzo12-2048x1368-1.jpg\",\"datePublished\":\"2022-02-17T14:12:39+00:00\",\"dateModified\":\"2022-02-17T14:12:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/5d1178a88b916d4e208c2f7f7880adb7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/02\\\/ht_palazzo12-2048x1368-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/02\\\/ht_palazzo12-2048x1368-1.jpg\",\"width\":2048,\"height\":1368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/02\\\/17\\\/technology-transfer-in-life-sciences-training-workshop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technology Transfer in Life Sciences &#8211; Training workshop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/5d1178a88b916d4e208c2f7f7880adb7\",\"name\":\"Federica San\u00f2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g\",\"caption\":\"Federica San\u00f2\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/f-sano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technology Transfer in Life Sciences - Training workshop - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/","og_locale":"it_IT","og_type":"article","og_title":"Technology Transfer in Life Sciences - Training workshop - Lazio International - Lazio Innova","og_description":"Human Technopole: il seminario affronta il tema del trasferimento della conoscenza dai laboratori al mercato.","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2022-02-17T14:12:39+00:00","article_modified_time":"2022-02-17T14:12:42+00:00","og_image":[{"width":2048,"height":1368,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg","type":"image\/jpeg"}],"author":"Federica San\u00f2","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Federica San\u00f2","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/"},"author":{"name":"Federica San\u00f2","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/5d1178a88b916d4e208c2f7f7880adb7"},"headline":"Technology Transfer in Life Sciences &#8211; Training workshop","datePublished":"2022-02-17T14:12:39+00:00","dateModified":"2022-02-17T14:12:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/"},"wordCount":172,"commentCount":0,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg","keywords":["healthcare","lifesciences","Seminari e Formazione","technology transfer"],"articleSection":["Formazione ed Empowerment"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/","name":"Technology Transfer in Life Sciences - Training workshop - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg","datePublished":"2022-02-17T14:12:39+00:00","dateModified":"2022-02-17T14:12:42+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/5d1178a88b916d4e208c2f7f7880adb7"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg","width":2048,"height":1368},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/02\/17\/technology-transfer-in-life-sciences-training-workshop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Technology Transfer in Life Sciences &#8211; Training workshop"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/5d1178a88b916d4e208c2f7f7880adb7","name":"Federica San\u00f2","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a33bb2b755ba3bd63b47c0cd5209d8bca97bbbf7bb3afac72bdb966363f5d997?s=96&d=mm&r=g","caption":"Federica San\u00f2"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/f-sano\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/02\/ht_palazzo12-2048x1368-1.jpg","author_info":{"display_name":"Federica San\u00f2","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/f-sano\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/4525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=4525"}],"version-history":[{"count":5,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/4525\/revisions"}],"predecessor-version":[{"id":4532,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/4525\/revisions\/4532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/4527"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=4525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=4525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=4525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}