{"id":5209,"date":"2022-03-25T10:55:16","date_gmt":"2022-03-25T09:55:16","guid":{"rendered":"https:\/\/www.laziointernational.it\/?p=5209"},"modified":"2022-07-25T12:57:44","modified_gmt":"2022-07-25T10:57:44","slug":"lazio-smart-green-health-forum-tematico-expo2o20-dubai","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/","title":{"rendered":"Lazio, Smart &#038; Green Health-Forum tematico EXPO2O20 Dubai"},"content":{"rendered":"\n<p><strong>Marted\u00ec 29 marzo<\/strong>&nbsp;alle 18.00 (ora di Dubai) \u2013 16.00 (ora italiana) si svolge ad Expo 2020 Dubai, un Forum organizzato dalla&nbsp;<strong>Regione Lazio&nbsp;<\/strong>dal titolo \u201c<strong>Lazio, Smart &amp; Green Health. Dalla gestione smart della Sanit\u00e0 alla virtualizzazione delle cure. Le nuove frontiere della salute e i modelli digitali dell\u2019Industry 4.0 e dei Digital Twin<\/strong>\u201d.<\/p>\n\n\n\n<p>La crisi sanitaria provocata dal Covid-19 ha acceso i riflettori sul valore della Salute quale pivot per la crescita economica e il benessere e, nel contempo, sul ruolo della Sanit\u00e0 pubblica quale asset fondamentale per il nostro Paese. In un quadro di stime economiche globali in drastico calo, il settore della Salute e delle Scienze della Vita pi\u00f9 in generale, hanno dimostrato in questi ultimi mesi reattivit\u00e0, capacit\u00e0 di organizzazione, apertura alla collaborazione e, ancora una volta, eccellenza scientifica. Tutto questo a beneficio di una sempre maggiore qualit\u00e0 della vita e delle cure offerte ai cittadini.<\/p>\n\n\n\n<p>Il Forum, che si svolge all\u2019interno del Padiglione Italia di Expo2020 Dubai, intende presentare il<strong> Lazio<\/strong> come <strong>territorio<\/strong> in cui \u00e8 forte lo sviluppo <strong>della Smart &amp; Green Health<\/strong>, in termini di virtualizzazione delle cure, gestione delle emergenze, efficienza energetica e riduzione degli impatti ambientali, innovazione tecnologica e ottimizzazione dei processi. Inoltre, la vocazione turistica, in termini di turismo medicale e turismo del benessere, nella Regione Lazio sono in grado di offrire una prospettiva integrata di servizi sanitari e servizi turistici.<\/p>\n\n\n\n<p><strong><em>Tutte queste tematiche saranno protagoniste del fitto programma di interventi<\/em><\/strong><em>, tra i quali annoveriamo <strong>l\u2019<\/strong><\/em><strong>Ospedale pediatrico Bambino Ges\u00f9, \u00a0l\u2019Istituto \u201cSpallanzani\u201d di Roma, nonch\u00e9 l\u2019Istituto Superiore di Sanit\u00e0 (ISS). <\/strong><br><strong>Concluder\u00e0 i lavori l\u2019Assessore Sanit\u00e0 e Integrazione Socio &#8211; Sanitaria Alessio D\u2019Amato<\/strong>.<\/p>\n\n\n\n<p><strong>Diretta streaming sulle pagine facebook della&nbsp;<a href=\"https:\/\/www.facebook.com\/RegioneLazio\" target=\"_blank\" rel=\"noreferrer noopener\">Regione Lazio<\/a>&nbsp;e di Lazio Innova e su:&nbsp;<a href=\"http:\/\/expo2020.lazioinnova.it\/diretta-streaming\/\" target=\"_blank\" rel=\"noreferrer noopener\">expo2020.lazioinnova<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.laziointernational.it\/app\/uploads\/2022\/03\/Health-forum-program-29-marzo-Dubai.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">PROGRAMMA<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec 29 marzo alle 18.00 a Dubai (ore 16.00 in Italia), il Forum internazionale organizzato dalla Regione Lazio dedicato alle nuove frontiere della Salute e ai modelli digitali dell&#8217;Industry 4.0<\/p>\n","protected":false},"author":11,"featured_media":5210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[37,2],"tags":[47,131,186,65,72],"class_list":["post-5209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altri-appuntamenti","category-fiere-e-iniziative-internazionali","tag-bioscienze","tag-expo2020","tag-expo2020dubai","tag-internazionalizzazione","tag-regione-lazio"],"acf":{"homepage_image":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lazio, Smart &amp; Green Health-Forum tematico EXPO2O20 Dubai - Lazio International - Lazio Innova<\/title>\n<meta name=\"description\" content=\"Marted\u00ec 29 marzo alle 18.00 a Dubai (ore 16.00 in Italia), il Forum internazionale organizzato dalla Regione Lazio dedicato alle nuove frontiere della Salute e ai modelli digitali dell&#039;Industry 4.0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lazio, Smart &amp; Green Health-Forum tematico EXPO2O20 Dubai - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Marted\u00ec 29 marzo alle 18.00 a Dubai (ore 16.00 in Italia), il Forum internazionale organizzato dalla Regione Lazio dedicato alle nuove frontiere della Salute e ai modelli digitali dell&#039;Industry 4.0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-25T09:55:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T10:57:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patrizia De Vincenzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrizia De Vincenzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/\"},\"author\":{\"name\":\"Patrizia De Vincenzi\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"headline\":\"Lazio, Smart &#038; Green Health-Forum tematico EXPO2O20 Dubai\",\"datePublished\":\"2022-03-25T09:55:16+00:00\",\"dateModified\":\"2022-07-25T10:57:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/\"},\"wordCount\":303,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/03\\\/green-health-2048x1076-1.jpg\",\"keywords\":[\"Bioscienze\",\"Expo2020\",\"Expo2020Dubai\",\"Internazionalizzazione\",\"Regione Lazio\"],\"articleSection\":[\"Altri appuntamenti\",\"Fiere e Iniziative Internazionali\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/\",\"name\":\"Lazio, Smart & Green Health-Forum tematico EXPO2O20 Dubai - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/03\\\/green-health-2048x1076-1.jpg\",\"datePublished\":\"2022-03-25T09:55:16+00:00\",\"dateModified\":\"2022-07-25T10:57:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\"},\"description\":\"Marted\u00ec 29 marzo alle 18.00 a Dubai (ore 16.00 in Italia), il Forum internazionale organizzato dalla Regione Lazio dedicato alle nuove frontiere della Salute e ai modelli digitali dell'Industry 4.0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/03\\\/green-health-2048x1076-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/app\\\/uploads\\\/2022\\\/03\\\/green-health-2048x1076-1.jpg\",\"width\":2048,\"height\":1076},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2022\\\/03\\\/25\\\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lazio, Smart &#038; Green Health-Forum tematico EXPO2O20 Dubai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/e10234da4fb4b74202a288833515d758\",\"name\":\"Patrizia De Vincenzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g\",\"caption\":\"Patrizia De Vincenzi\"},\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/p-devincenzi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lazio, Smart & Green Health-Forum tematico EXPO2O20 Dubai - Lazio International - Lazio Innova","description":"Marted\u00ec 29 marzo alle 18.00 a Dubai (ore 16.00 in Italia), il Forum internazionale organizzato dalla Regione Lazio dedicato alle nuove frontiere della Salute e ai modelli digitali dell'Industry 4.0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/","og_locale":"it_IT","og_type":"article","og_title":"Lazio, Smart & Green Health-Forum tematico EXPO2O20 Dubai - Lazio International - Lazio Innova","og_description":"Marted\u00ec 29 marzo alle 18.00 a Dubai (ore 16.00 in Italia), il Forum internazionale organizzato dalla Regione Lazio dedicato alle nuove frontiere della Salute e ai modelli digitali dell'Industry 4.0","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2022-03-25T09:55:16+00:00","article_modified_time":"2022-07-25T10:57:44+00:00","og_image":[{"width":2048,"height":1076,"url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg","type":"image\/jpeg"}],"author":"Patrizia De Vincenzi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Patrizia De Vincenzi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/"},"author":{"name":"Patrizia De Vincenzi","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"headline":"Lazio, Smart &#038; Green Health-Forum tematico EXPO2O20 Dubai","datePublished":"2022-03-25T09:55:16+00:00","dateModified":"2022-07-25T10:57:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/"},"wordCount":303,"commentCount":0,"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg","keywords":["Bioscienze","Expo2020","Expo2020Dubai","Internazionalizzazione","Regione Lazio"],"articleSection":["Altri appuntamenti","Fiere e Iniziative Internazionali"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/","name":"Lazio, Smart & Green Health-Forum tematico EXPO2O20 Dubai - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#primaryimage"},"image":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg","datePublished":"2022-03-25T09:55:16+00:00","dateModified":"2022-07-25T10:57:44+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758"},"description":"Marted\u00ec 29 marzo alle 18.00 a Dubai (ore 16.00 in Italia), il Forum internazionale organizzato dalla Regione Lazio dedicato alle nuove frontiere della Salute e ai modelli digitali dell'Industry 4.0","breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#primaryimage","url":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg","contentUrl":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg","width":2048,"height":1076},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2022\/03\/25\/lazio-smart-green-health-forum-tematico-expo2o20-dubai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"Lazio, Smart &#038; Green Health-Forum tematico EXPO2O20 Dubai"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/e10234da4fb4b74202a288833515d758","name":"Patrizia De Vincenzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17cc95ef762982ced7f11b6aae493010130bf1fa1eebe418cd992a2be70ac875?s=96&d=mm&r=g","caption":"Patrizia De Vincenzi"},"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"}]}},"featured_image_src":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg","featured_image_src_square":"https:\/\/www.lazioinnova.it\/laziointernational\/app\/uploads\/2022\/03\/green-health-2048x1076-1.jpg","author_info":{"display_name":"Patrizia De Vincenzi","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/p-devincenzi\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/5209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=5209"}],"version-history":[{"count":3,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/5209\/revisions"}],"predecessor-version":[{"id":5268,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/5209\/revisions\/5268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media\/5210"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=5209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=5209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=5209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}