{"id":698,"date":"2013-07-05T07:24:27","date_gmt":"2013-07-05T05:24:27","guid":{"rendered":"http:\/\/www.laziointernational.it\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/"},"modified":"2013-07-05T07:24:27","modified_gmt":"2013-07-05T05:24:27","slug":"la-distribuzione-internazionale-in-cile-1453","status":"publish","type":"post","link":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/","title":{"rendered":"La distribuzione internazionale in Cile"},"content":{"rendered":"<p>Il presente scritto si propone di fornire, senza pretesa di esaustivit\u00e0, alcune informazioni utili agli operatori che intendano instaurare rapporti di distribuzione internazionale con controparti cilene.<\/p>\n<p>Considereremo i principali aspetti riguardanti la distribuzione internazionale in Cile: la forma richiesta per la conclusione del contratto, gli obblighi delle parti, lo scioglimento del contratto e i possibili metodi di risoluzione delle controversie relative al rapporto.<\/p>\n<p>Esiste un Accordo di Associazione, entrato in vigore nel 2005, volto a favorire le relazioni economiche tra gli Stati membri dell\u2019Unione Europea e il Cile. Tale Accordo contiene il <em>Free Trade Agreement<\/em>, entrato in vigore nel febbraio del 2003, il cui obiettivo \u00e8 agevolare e semplificare il commercio in un\u2019ottica di progressiva liberalizzazione. Significative in tal senso sono le <strong>agevolazioni nel settore doganale<\/strong> (art. 57 e seguenti del <em>Free Trade Agreement<\/em>) con riguardo ai prodotti industriali e agricoli. Tuttavia, nonostante l\u2019Accordo, il Cile ha introdotto restrizioni alle importazioni di alcune categorie di prodotti (ad esempio le carni).<\/p>\n<p>In Cile il contratto di distribuzione non ha una sua normativa <em>ad hoc<\/em>. Per tale motivo, i punti di riferimento principali sono i principi generali di diritto civile e commerciale cileno. Stante <strong>l\u2019assenza di una disciplina specifica in materia di distribuzione<\/strong>, le parti potranno godere di ampia autonomia nel regolare i loro rapporti.<\/p>\n<p>Con riferimento ai requisiti richiesti a coloro che intendano operare nel settore in esame, si segnala che questi ultimi non devono possedere particolari requisiti, come invece accade in altri Paesi, ove \u00e8 richiesta ad esempio l\u2019iscrizione in un apposito albo o registro. Per poter operare come distributore in Cile, non \u00e8 necessario che l\u2019operatore sia di nazionalit\u00e0 cilena.<\/p>\n<p>Ulteriore conseguenza dell\u2019assenza di una disciplina specifica in materia di distribuzione \u00e8 la mancanza del requisito della forma scritta per la validit\u00e0 del contratto. Dunque, un contratto di distribuzione in Cile assume rilevanza anche qualora il distributore operi di fatto. Tuttavia, risulta comunque opportuno suggerire alle parti di formalizzare per iscritto il loro rapporto allo scopo di riuscire a dar prova della sua effettiva esistenza, qualora dovesse venire in essere un contenzioso tra le stesse.<\/p>\n<p>Quanto alle obbligazioni di ciascuna parte, stante il fatto che il contratto di distribuzione non \u00e8 regolamentato, l\u2019individuazione delle stesse pu\u00f2 essere operata in termini generali. Cos\u00ec, <strong>l\u2019obbligazione tipica del fornitore<\/strong> \u00e8 quella di fornire i prodotti al distributore, secondo le quantit\u00e0 e le tempistiche concordate. Le parti possono altres\u00ec concordare l\u2019adempimento da parte del fornitore di specifiche obbligazioni, quali la fornitura di materiale pubblicitario, la concessione dell\u2019uso di marchi e l\u2019applicazione di sconti a certe condizioni.<\/p>\n<p>Parallelamente, <strong>l\u2019obbligazione tipica del distributore<\/strong> \u00e8 l\u2019acquisto dei prodotti contrattuali dal fornitore e la loro commercializzazione secondo quanto concordato. In tal senso, il fornitore pu\u00f2 richiedere al distributore che tale commercializzazione venga svolta secondo precise modalit\u00e0 dallo stesso stabilite, che possono riguardare, ad esempio, l\u2019esposizione dei prodotti, la loro promozione pubblicitaria o la loro presentazione al pubblico.<\/p>\n<p>Le parti possono concordemente prevedere all\u2019interno del contratto ulteriori clausole come ad esempio quelle aventi ad oggetto un <strong>obbligo di non concorrenza post-contrattuale<\/strong> da parte del distributore nei confronti del fornitore. Tuttavia, qualora si intenda operare una scelta di tal genere, \u00e8 opportuno prevedere che l\u2019obbligo in questione abbia una durata ragionevole ed eventualmente stabilire l\u2019ammontare di <strong>un\u2019indennit\u00e0 a favore del distributore<\/strong>.<\/p>\n<p>Altro specifico obbligo in capo al distributore pu\u00f2 essere quello di informazione consistente, in sostanza, nel tenere informato il fornitore circa l\u2019attivit\u00e0 svolta e le condizioni del mercato.<\/p>\n<p>Sarebbe inoltre consigliabile adottare adeguati <strong>strumenti di pagamento<\/strong> al fine di tutelare il credito (pagamento anticipato della merce o lettere di credito).<\/p>\n<p>La <strong>durata del contratto<\/strong> viene stabilita dalle parti e pu\u00f2 essere a tempo determinato o indeterminato. Qualora uno dei contraenti intenda risolvere il contratto, stante la predetta assenza di disciplina, non si hanno particolari prescrizioni per quanto riguarda il periodo di preavviso. L\u2019ovvia conseguenza \u00e8 che il giudizio circa la congruit\u00e0 del periodo di preavviso eventualmente concesso viene lasciato alla valutazione del giudicante che sar\u00e0 chiamato a decidere le controversie.<\/p>\n<p>Meglio prevedere <strong>contratto scritto con clausola che contenga un congruo periodo di preavviso<\/strong>. In assenza di contratto scritto, la parte che intende recedere dal contratto dovr\u00e0 concedere un termine di preavviso che sia adeguato in considerazione di tutti gli elementi che hanno caratterizzato il rapporto, stante il rischio di una condanna al pagamento di un\u2019indennit\u00e0 di mancato preavviso a favore della parte che subisce la risoluzione.<\/p>\n<p>Per quanto concerne, invece, la corresponsione di un\u2019<strong>indennit\u00e0 di fine rapporto<\/strong>, il giudizio di opportunit\u00e0 o meno della spettanza di quest\u2019ultima al distributore \u00e8 lasciata al giudice competente. Nei casi in cui le Corti cilene sono state chiamate a pronunciarsi in proposito in base alla legge del loro Stato, hanno elaborato precisi criteri cui fare riferimento caso per caso (ad esempio, previsioni contrattuali, periodo di preavviso concesso, attivit\u00e0 svolta dal distributore).<\/p>\n<p>Quanto alla <strong>legge applicabile<\/strong> al rapporto di distribuzione, quest\u2019ultima sar\u00e0 quella liberamente determinata dalle parti. Cos\u00ec anche per quanto riguarda il <strong>foro competente<\/strong> a risolvere le controversie che eventualmente dovessero sorgere tra le parti, queste ultime avranno facolt\u00e0 di scelta in proposito.<\/p>\n<p>Gli operatori italiani dovrebbero considerare che, in caso di ottenimento di una sentenza favorevole in Italia, potrebbero prospettarsi impedimenti con riguardo al suo riconoscimento e all\u2019esecuzione in Cile per problemi, ad esempio, di ordine procedurale. Sarebbe dunque preferibile inserire nel contratto di distribuzione una <strong>clausola che devolva la risoluzione delle controversie ad arbitri<\/strong>. Ci\u00f2 \u00e8 altamente consigliabile, non solo per la tradizionale maggiore rapidit\u00e0 e praticit\u00e0 con cui si svolge il giudizio arbitrale, ma anche perch\u00e8 <strong>il Cile ha ratificato <st1:personname productid=\"la Convenzione\" w:st=\"on\">la Convenzione<\/st1:personname> di New York del 1958<\/strong> sul riconoscimento e l\u2019esecuzione dei lodi arbitrali stranieri, con conseguente possibilit\u00e0 di rendere esecutivo in Cile il lodo emesso.<\/p>\n<p><strong>Paolo Lombardi e Elisabetta Mura<\/strong><\/p>\n<p><a href=\"http:\/\/www.newsmercati.com\">www.newsmercati.com<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presente scritto si propone di fornire, senza pretesa di esaustivit\u00e0, alcune informazioni utili agli operatori che intendano instaurare rapporti di distribuzione internazionale con controparti cilene.<br \/>\nConsidereremo i principali aspetti riguardanti la distribuzione internazionale in Cile: la forma richiesta per la conclusione del contratto, gli obblighi delle parti, lo scioglimento del contratto e i possibili metodi di risoluzione delle controversie relative al rapporto.<br \/>\nEsiste un Accordo di Associazione, entrato in vigore nel 2005, volto a favorire le relazioni economiche tra gli Stati membri dell\u2019Unione Europea e il Cile. Tale Accordo contiene il Free Trade Agreement, entrato in vigore nel febbraio del 2003, il cui obiettivo \u00e8 agevolare e semplificare il commercio in un\u2019ottica di progressiva liberalizzazione. Significative in tal senso sono le agevolazioni nel settore doganale (art. 57 e seguenti del Free Trade Agreement) con riguardo ai prodotti industriali e agricoli. Tuttavia, nonostante l\u2019Accordo, il Cile ha introdotto restrizioni alle importazioni di alcune categorie di prodotti (ad esempio le carni).<br \/>\nIn Cile il contratto di distribuzione non ha una sua normativa ad hoc. Per tale motivo, i punti di riferimento principali sono i principi generali di diritto civile e commerciale cileno. Stante l\u2019assenza di una disciplina specifica in materia di distribuzione, le parti potranno godere di ampia autonomia nel regolare i loro rapporti.<br \/>\nCon riferimento ai requisiti richiesti a coloro che intendano operare nel settore in esame, si segnala che questi ultimi non devono possedere particolari requisiti, come invece accade in altri Paesi, ove \u00e8 richiesta ad esempio l\u2019iscrizione in un apposito albo o registro. Per poter operare come distributore in Cile, non \u00e8 necessario che l\u2019operatore sia di nazionalit\u00e0 cilena.<br \/>\nUlteriore conseguenza dell\u2019assenza di una disciplina specifica in materia di distribuzione \u00e8 la mancanza del requisito della forma scritta per la validit\u00e0 del contratto. Dunque, un contratto di distribuzione in Cile assume rilevanza anche qualora il distributore operi di fatto. Tuttavia, risulta comunque opportuno suggerire alle parti di formalizzare per iscritto il loro rapporto allo scopo di riuscire a dar prova della sua effettiva esistenza, qualora dovesse venire in essere un contenzioso tra le stesse.<br \/>\nQuanto alle obbligazioni di ciascuna parte, stante il fatto che il contratto di distribuzione non \u00e8 regolamentato, l\u2019individuazione delle stesse pu\u00f2 essere operata in termini generali. Cos\u00ec, l\u2019obbligazione tipica del fornitore \u00e8 quella di fornire i prodotti al distributore, secondo le quantit\u00e0 e le tempistiche concordate. Le parti possono altres\u00ec concordare l\u2019adempimento da parte del fornitore di specifiche obbligazioni, quali la fornitura di materiale pubblicitario, la concessione dell\u2019uso di marchi e l\u2019applicazione di sconti a certe condizioni.<br \/>\nParallelamente, l\u2019obbligazione tipica del distributore \u00e8 l\u2019acquisto dei prodotti contrattuali dal fornitore e la loro commercializzazione secondo quanto concordato. In tal senso, il fornitore pu\u00f2 richiedere al distributore che tale commercializzazione venga svolta secondo precise modalit\u00e0 dallo stesso stabilite, che possono riguardare, ad esempio, l\u2019esposizione dei prodotti, la loro promozione pubblicitaria o la loro presentazione al pubblico.<br \/>\nLe parti possono concordemente prevedere all\u2019interno del contratto ulteriori clausole come ad esempio quelle aventi ad oggetto un obbligo di non concorrenza post-contrattuale da parte del distributore nei confronti del fornitore. Tuttavia, qualora si intenda operare una scelta di tal genere, \u00e8 opportuno prevedere che l\u2019obbligo in questione abbia una durata ragionevole ed eventualmente stabilire l\u2019ammontare di un\u2019indennit\u00e0 a favore del distributore.<br \/>\nAltro specifico obbligo in capo al distributore pu\u00f2 essere quello di informazione consistente, in sostanza, nel tenere informato il fornitore circa l\u2019attivit\u00e0 svolta e le condizioni del mercato.<br \/>\nSarebbe inoltre consigliabile adottare adeguati strumenti di pagamento al fine di tutelare il credito (pagamento anticipato della merce o lettere di credito).<br \/>\nLa durata del contratto viene stabilita dalle parti e pu\u00f2 essere a tempo determinato o indeterminato. Qualora uno dei contraenti intenda risolvere il contratto, stante la predetta assenza di disciplina, non si hanno particolari prescrizioni per quanto riguarda il periodo di preavviso. L\u2019ovvia conseguenza \u00e8 che il giudizio circa la congruit\u00e0 del periodo di preavviso eventualmente concesso viene lasciato alla valutazione del giudicante che sar\u00e0 chiamato a decidere le controversie.<br \/>\nMeglio prevedere contratto scritto con clausola che contenga un congruo periodo di preavviso. In assenza di contratto scritto, la parte che intende recedere dal contratto dovr\u00e0 concedere un termine di preavviso che sia adeguato in considerazione di tutti gli elementi che hanno caratterizzato il rapporto, stante il rischio di una condanna al pagamento di un\u2019indennit\u00e0 di mancato preavviso a favore della parte che subisce la risoluzione.<br \/>\nPer quanto concerne, invece, la corresponsione di un\u2019indennit\u00e0 di fine rapporto, il giudizio di opportunit\u00e0 o meno della spettanza di quest\u2019ultima al distributore \u00e8 lasciata al giudice competente. Nei casi in cui le Corti cilene sono state chiamate a pronunciarsi in proposito in base alla legge del loro Stato, hanno elaborato precisi criteri cui fare riferimento caso per caso (ad esempio, previsioni contrattuali, periodo di preavviso concesso, attivit\u00e0 svolta dal distributore).<br \/>\nQuanto alla legge applicabile al rapporto di distribuzione, quest\u2019ultima sar\u00e0 quella liberamente determinata dalle parti. Cos\u00ec anche per quanto riguarda il foro competente a risolvere le controversie che eventualmente dovessero sorgere tra le parti, queste ultime avranno facolt\u00e0 di scelta in proposito.<br \/>\nGli operatori italiani dovrebbero considerare che, in caso di ottenimento di una sentenza favorevole in Italia, potrebbero prospettarsi impedimenti con riguardo al suo riconoscimento e all\u2019esecuzione in Cile per problemi, ad esempio, di ordine procedurale. Sarebbe dunque preferibile inserire nel contratto di distribuzione una clausola che devolva la risoluzione delle controversie ad arbitri. Ci\u00f2 \u00e8 altamente consigliabile, non solo per la tradizionale maggiore rapidit\u00e0 e praticit\u00e0 con cui si svolge il giudizio arbitrale, ma anche perch\u00e8 il Cile ha ratificato la Convenzione di New York del 1958 sul riconoscimento e l\u2019esecuzione dei lodi arbitrali stranieri, con conseguente possibilit\u00e0 di rendere esecutivo in Cile il lodo emesso.<br \/>\nPaolo Lombardi e Elisabetta Mura<br \/>\nwww.newsmercati.com<br \/>\n\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-698","post","type-post","status-publish","format-standard","hentry","category-notizie"],"acf":{"homepage_image":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La distribuzione internazionale in Cile - Lazio International - Lazio Innova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La distribuzione internazionale in Cile - Lazio International - Lazio Innova\" \/>\n<meta property=\"og:description\" content=\"Il presente scritto si propone di fornire, senza pretesa di esaustivit\u00e0, alcune informazioni utili agli operatori che intendano instaurare rapporti di distribuzione internazionale con controparti cilene. Considereremo i principali aspetti riguardanti la distribuzione internazionale in Cile: la forma richiesta per la conclusione del contratto, gli obblighi delle parti, lo scioglimento del contratto e i possibili metodi di risoluzione delle controversie relative al rapporto. Esiste un Accordo di Associazione, entrato in vigore nel 2005, volto a favorire le relazioni economiche tra gli Stati membri dell\u2019Unione Europea e il Cile. Tale Accordo contiene il Free Trade Agreement, entrato in vigore nel febbraio del 2003, il cui obiettivo \u00e8 agevolare e semplificare il commercio in un\u2019ottica di progressiva liberalizzazione. Significative in tal senso sono le agevolazioni nel settore doganale (art. 57 e seguenti del Free Trade Agreement) con riguardo ai prodotti industriali e agricoli. Tuttavia, nonostante l\u2019Accordo, il Cile ha introdotto restrizioni alle importazioni di alcune categorie di prodotti (ad esempio le carni). In Cile il contratto di distribuzione non ha una sua normativa ad hoc. Per tale motivo, i punti di riferimento principali sono i principi generali di diritto civile e commerciale cileno. Stante l\u2019assenza di una disciplina specifica in materia di distribuzione, le parti potranno godere di ampia autonomia nel regolare i loro rapporti. Con riferimento ai requisiti richiesti a coloro che intendano operare nel settore in esame, si segnala che questi ultimi non devono possedere particolari requisiti, come invece accade in altri Paesi, ove \u00e8 richiesta ad esempio l\u2019iscrizione in un apposito albo o registro. Per poter operare come distributore in Cile, non \u00e8 necessario che l\u2019operatore sia di nazionalit\u00e0 cilena. Ulteriore conseguenza dell\u2019assenza di una disciplina specifica in materia di distribuzione \u00e8 la mancanza del requisito della forma scritta per la validit\u00e0 del contratto. Dunque, un contratto di distribuzione in Cile assume rilevanza anche qualora il distributore operi di fatto. Tuttavia, risulta comunque opportuno suggerire alle parti di formalizzare per iscritto il loro rapporto allo scopo di riuscire a dar prova della sua effettiva esistenza, qualora dovesse venire in essere un contenzioso tra le stesse. Quanto alle obbligazioni di ciascuna parte, stante il fatto che il contratto di distribuzione non \u00e8 regolamentato, l\u2019individuazione delle stesse pu\u00f2 essere operata in termini generali. Cos\u00ec, l\u2019obbligazione tipica del fornitore \u00e8 quella di fornire i prodotti al distributore, secondo le quantit\u00e0 e le tempistiche concordate. Le parti possono altres\u00ec concordare l\u2019adempimento da parte del fornitore di specifiche obbligazioni, quali la fornitura di materiale pubblicitario, la concessione dell\u2019uso di marchi e l\u2019applicazione di sconti a certe condizioni. Parallelamente, l\u2019obbligazione tipica del distributore \u00e8 l\u2019acquisto dei prodotti contrattuali dal fornitore e la loro commercializzazione secondo quanto concordato. In tal senso, il fornitore pu\u00f2 richiedere al distributore che tale commercializzazione venga svolta secondo precise modalit\u00e0 dallo stesso stabilite, che possono riguardare, ad esempio, l\u2019esposizione dei prodotti, la loro promozione pubblicitaria o la loro presentazione al pubblico. Le parti possono concordemente prevedere all\u2019interno del contratto ulteriori clausole come ad esempio quelle aventi ad oggetto un obbligo di non concorrenza post-contrattuale da parte del distributore nei confronti del fornitore. Tuttavia, qualora si intenda operare una scelta di tal genere, \u00e8 opportuno prevedere che l\u2019obbligo in questione abbia una durata ragionevole ed eventualmente stabilire l\u2019ammontare di un\u2019indennit\u00e0 a favore del distributore. Altro specifico obbligo in capo al distributore pu\u00f2 essere quello di informazione consistente, in sostanza, nel tenere informato il fornitore circa l\u2019attivit\u00e0 svolta e le condizioni del mercato. Sarebbe inoltre consigliabile adottare adeguati strumenti di pagamento al fine di tutelare il credito (pagamento anticipato della merce o lettere di credito). La durata del contratto viene stabilita dalle parti e pu\u00f2 essere a tempo determinato o indeterminato. Qualora uno dei contraenti intenda risolvere il contratto, stante la predetta assenza di disciplina, non si hanno particolari prescrizioni per quanto riguarda il periodo di preavviso. L\u2019ovvia conseguenza \u00e8 che il giudizio circa la congruit\u00e0 del periodo di preavviso eventualmente concesso viene lasciato alla valutazione del giudicante che sar\u00e0 chiamato a decidere le controversie. Meglio prevedere contratto scritto con clausola che contenga un congruo periodo di preavviso. In assenza di contratto scritto, la parte che intende recedere dal contratto dovr\u00e0 concedere un termine di preavviso che sia adeguato in considerazione di tutti gli elementi che hanno caratterizzato il rapporto, stante il rischio di una condanna al pagamento di un\u2019indennit\u00e0 di mancato preavviso a favore della parte che subisce la risoluzione. Per quanto concerne, invece, la corresponsione di un\u2019indennit\u00e0 di fine rapporto, il giudizio di opportunit\u00e0 o meno della spettanza di quest\u2019ultima al distributore \u00e8 lasciata al giudice competente. Nei casi in cui le Corti cilene sono state chiamate a pronunciarsi in proposito in base alla legge del loro Stato, hanno elaborato precisi criteri cui fare riferimento caso per caso (ad esempio, previsioni contrattuali, periodo di preavviso concesso, attivit\u00e0 svolta dal distributore). Quanto alla legge applicabile al rapporto di distribuzione, quest\u2019ultima sar\u00e0 quella liberamente determinata dalle parti. Cos\u00ec anche per quanto riguarda il foro competente a risolvere le controversie che eventualmente dovessero sorgere tra le parti, queste ultime avranno facolt\u00e0 di scelta in proposito. Gli operatori italiani dovrebbero considerare che, in caso di ottenimento di una sentenza favorevole in Italia, potrebbero prospettarsi impedimenti con riguardo al suo riconoscimento e all\u2019esecuzione in Cile per problemi, ad esempio, di ordine procedurale. Sarebbe dunque preferibile inserire nel contratto di distribuzione una clausola che devolva la risoluzione delle controversie ad arbitri. Ci\u00f2 \u00e8 altamente consigliabile, non solo per la tradizionale maggiore rapidit\u00e0 e praticit\u00e0 con cui si svolge il giudizio arbitrale, ma anche perch\u00e8 il Cile ha ratificato la Convenzione di New York del 1958 sul riconoscimento e l\u2019esecuzione dei lodi arbitrali stranieri, con conseguente possibilit\u00e0 di rendere esecutivo in Cile il lodo emesso. Paolo Lombardi e Elisabetta Mura www.newsmercati.com \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/\" \/>\n<meta property=\"og:site_name\" content=\"Lazio International - Lazio Innova\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-05T05:24:27+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"headline\":\"La distribuzione internazionale in Cile\",\"datePublished\":\"2013-07-05T05:24:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/\"},\"wordCount\":972,\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/\",\"name\":\"La distribuzione internazionale in Cile - Lazio International - Lazio Innova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\"},\"datePublished\":\"2013-07-05T05:24:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/2013\\\/07\\\/05\\\/la-distribuzione-internazionale-in-cile-1453\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La distribuzione internazionale in Cile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#website\",\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/\",\"name\":\"Lazio International - Lazio Innova\",\"description\":\"Lazio Innova\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/#\\\/schema\\\/person\\\/06ba1706377e84a989f9f274331c7d10\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.laziointernational.it\\\/wp\"],\"url\":\"https:\\\/\\\/www.lazioinnova.it\\\/laziointernational\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La distribuzione internazionale in Cile - Lazio International - Lazio Innova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/","og_locale":"it_IT","og_type":"article","og_title":"La distribuzione internazionale in Cile - Lazio International - Lazio Innova","og_description":"Il presente scritto si propone di fornire, senza pretesa di esaustivit\u00e0, alcune informazioni utili agli operatori che intendano instaurare rapporti di distribuzione internazionale con controparti cilene. Considereremo i principali aspetti riguardanti la distribuzione internazionale in Cile: la forma richiesta per la conclusione del contratto, gli obblighi delle parti, lo scioglimento del contratto e i possibili metodi di risoluzione delle controversie relative al rapporto. Esiste un Accordo di Associazione, entrato in vigore nel 2005, volto a favorire le relazioni economiche tra gli Stati membri dell\u2019Unione Europea e il Cile. Tale Accordo contiene il Free Trade Agreement, entrato in vigore nel febbraio del 2003, il cui obiettivo \u00e8 agevolare e semplificare il commercio in un\u2019ottica di progressiva liberalizzazione. Significative in tal senso sono le agevolazioni nel settore doganale (art. 57 e seguenti del Free Trade Agreement) con riguardo ai prodotti industriali e agricoli. Tuttavia, nonostante l\u2019Accordo, il Cile ha introdotto restrizioni alle importazioni di alcune categorie di prodotti (ad esempio le carni). In Cile il contratto di distribuzione non ha una sua normativa ad hoc. Per tale motivo, i punti di riferimento principali sono i principi generali di diritto civile e commerciale cileno. Stante l\u2019assenza di una disciplina specifica in materia di distribuzione, le parti potranno godere di ampia autonomia nel regolare i loro rapporti. Con riferimento ai requisiti richiesti a coloro che intendano operare nel settore in esame, si segnala che questi ultimi non devono possedere particolari requisiti, come invece accade in altri Paesi, ove \u00e8 richiesta ad esempio l\u2019iscrizione in un apposito albo o registro. Per poter operare come distributore in Cile, non \u00e8 necessario che l\u2019operatore sia di nazionalit\u00e0 cilena. Ulteriore conseguenza dell\u2019assenza di una disciplina specifica in materia di distribuzione \u00e8 la mancanza del requisito della forma scritta per la validit\u00e0 del contratto. Dunque, un contratto di distribuzione in Cile assume rilevanza anche qualora il distributore operi di fatto. Tuttavia, risulta comunque opportuno suggerire alle parti di formalizzare per iscritto il loro rapporto allo scopo di riuscire a dar prova della sua effettiva esistenza, qualora dovesse venire in essere un contenzioso tra le stesse. Quanto alle obbligazioni di ciascuna parte, stante il fatto che il contratto di distribuzione non \u00e8 regolamentato, l\u2019individuazione delle stesse pu\u00f2 essere operata in termini generali. Cos\u00ec, l\u2019obbligazione tipica del fornitore \u00e8 quella di fornire i prodotti al distributore, secondo le quantit\u00e0 e le tempistiche concordate. Le parti possono altres\u00ec concordare l\u2019adempimento da parte del fornitore di specifiche obbligazioni, quali la fornitura di materiale pubblicitario, la concessione dell\u2019uso di marchi e l\u2019applicazione di sconti a certe condizioni. Parallelamente, l\u2019obbligazione tipica del distributore \u00e8 l\u2019acquisto dei prodotti contrattuali dal fornitore e la loro commercializzazione secondo quanto concordato. In tal senso, il fornitore pu\u00f2 richiedere al distributore che tale commercializzazione venga svolta secondo precise modalit\u00e0 dallo stesso stabilite, che possono riguardare, ad esempio, l\u2019esposizione dei prodotti, la loro promozione pubblicitaria o la loro presentazione al pubblico. Le parti possono concordemente prevedere all\u2019interno del contratto ulteriori clausole come ad esempio quelle aventi ad oggetto un obbligo di non concorrenza post-contrattuale da parte del distributore nei confronti del fornitore. Tuttavia, qualora si intenda operare una scelta di tal genere, \u00e8 opportuno prevedere che l\u2019obbligo in questione abbia una durata ragionevole ed eventualmente stabilire l\u2019ammontare di un\u2019indennit\u00e0 a favore del distributore. Altro specifico obbligo in capo al distributore pu\u00f2 essere quello di informazione consistente, in sostanza, nel tenere informato il fornitore circa l\u2019attivit\u00e0 svolta e le condizioni del mercato. Sarebbe inoltre consigliabile adottare adeguati strumenti di pagamento al fine di tutelare il credito (pagamento anticipato della merce o lettere di credito). La durata del contratto viene stabilita dalle parti e pu\u00f2 essere a tempo determinato o indeterminato. Qualora uno dei contraenti intenda risolvere il contratto, stante la predetta assenza di disciplina, non si hanno particolari prescrizioni per quanto riguarda il periodo di preavviso. L\u2019ovvia conseguenza \u00e8 che il giudizio circa la congruit\u00e0 del periodo di preavviso eventualmente concesso viene lasciato alla valutazione del giudicante che sar\u00e0 chiamato a decidere le controversie. Meglio prevedere contratto scritto con clausola che contenga un congruo periodo di preavviso. In assenza di contratto scritto, la parte che intende recedere dal contratto dovr\u00e0 concedere un termine di preavviso che sia adeguato in considerazione di tutti gli elementi che hanno caratterizzato il rapporto, stante il rischio di una condanna al pagamento di un\u2019indennit\u00e0 di mancato preavviso a favore della parte che subisce la risoluzione. Per quanto concerne, invece, la corresponsione di un\u2019indennit\u00e0 di fine rapporto, il giudizio di opportunit\u00e0 o meno della spettanza di quest\u2019ultima al distributore \u00e8 lasciata al giudice competente. Nei casi in cui le Corti cilene sono state chiamate a pronunciarsi in proposito in base alla legge del loro Stato, hanno elaborato precisi criteri cui fare riferimento caso per caso (ad esempio, previsioni contrattuali, periodo di preavviso concesso, attivit\u00e0 svolta dal distributore). Quanto alla legge applicabile al rapporto di distribuzione, quest\u2019ultima sar\u00e0 quella liberamente determinata dalle parti. Cos\u00ec anche per quanto riguarda il foro competente a risolvere le controversie che eventualmente dovessero sorgere tra le parti, queste ultime avranno facolt\u00e0 di scelta in proposito. Gli operatori italiani dovrebbero considerare che, in caso di ottenimento di una sentenza favorevole in Italia, potrebbero prospettarsi impedimenti con riguardo al suo riconoscimento e all\u2019esecuzione in Cile per problemi, ad esempio, di ordine procedurale. Sarebbe dunque preferibile inserire nel contratto di distribuzione una clausola che devolva la risoluzione delle controversie ad arbitri. Ci\u00f2 \u00e8 altamente consigliabile, non solo per la tradizionale maggiore rapidit\u00e0 e praticit\u00e0 con cui si svolge il giudizio arbitrale, ma anche perch\u00e8 il Cile ha ratificato la Convenzione di New York del 1958 sul riconoscimento e l\u2019esecuzione dei lodi arbitrali stranieri, con conseguente possibilit\u00e0 di rendere esecutivo in Cile il lodo emesso. Paolo Lombardi e Elisabetta Mura www.newsmercati.com \u00a0","og_url":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/","og_site_name":"Lazio International - Lazio Innova","article_published_time":"2013-07-05T05:24:27+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/#article","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/"},"author":{"name":"admin","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"headline":"La distribuzione internazionale in Cile","datePublished":"2013-07-05T05:24:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/"},"wordCount":972,"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/","url":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/","name":"La distribuzione internazionale in Cile - Lazio International - Lazio Innova","isPartOf":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website"},"datePublished":"2013-07-05T05:24:27+00:00","author":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10"},"breadcrumb":{"@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/2013\/07\/05\/la-distribuzione-internazionale-in-cile-1453\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lazioinnova.it\/laziointernational\/"},{"@type":"ListItem","position":2,"name":"La distribuzione internazionale in Cile"}]},{"@type":"WebSite","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#website","url":"https:\/\/www.lazioinnova.it\/laziointernational\/","name":"Lazio International - Lazio Innova","description":"Lazio Innova","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lazioinnova.it\/laziointernational\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.lazioinnova.it\/laziointernational\/#\/schema\/person\/06ba1706377e84a989f9f274331c7d10","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b0df2f1149646fd65648faf39bbd829de45fc6d5023bcd04041d62688cfdcbe?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.laziointernational.it\/wp"],"url":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"admin","author_link":"https:\/\/www.lazioinnova.it\/laziointernational\/author\/admin\/"},"homepage_image":"","_links":{"self":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/comments?post=698"}],"version-history":[{"count":0,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/posts\/698\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/media?parent=698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/categories?post=698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lazioinnova.it\/laziointernational\/wp-json\/wp\/v2\/tags?post=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}